{"id":10187,"date":"2017-02-18T18:00:40","date_gmt":"2017-02-18T17:00:40","guid":{"rendered":"https:\/\/cinedetour.it\/?p=10187"},"modified":"2017-02-20T19:42:49","modified_gmt":"2017-02-20T18:42:49","slug":"hieronymus-bosch-unto-dal-diavolo","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2017\/02\/18\/hieronymus-bosch-unto-dal-diavolo\/","title":{"rendered":"HIERONYMUS BOSCH. Unto dal diavolo"},"content":{"rendered":"<p style=\"text-align: left;\"><span style=\"font-size: 12pt;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">Roma Cinema Detour, Via Urbana 107 Roma<br \/>\n <\/span><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">sabato&nbsp;18&nbsp;febbraio&nbsp;2017 ore 18.00<\/span><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><span style=\"font-size: 12pt;\">In collaborazione con&nbsp;Wanted Cinema distribuzione<\/span><br \/>\n <\/span><span style=\"font-size: 24pt; font-family: 'trebuchet ms', geneva, sans-serif;\"><span style=\"font-size: 36pt;\"><span style=\"font-size: 24pt;\"><span style=\"font-size: 36pt;\"><span style=\"font-size: 24pt;\">HIERONYMUS BOSCH. Unto dal diavolo<\/span><br \/>\n <\/span><\/span><\/span><\/span><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\">di Pieter van Huystee (2015, 86&#8242;, italiano)<\/span><\/p>\n<div>\n<div style=\"text-align: justify;\" title=\"Page 1\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/01\/bosch_detour.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10188\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/01\/bosch_detour.jpg\" alt=\"bosch_detour\" width=\"368\" height=\"511\"><\/a><\/p>\n<p><span style=\"font-size: 8pt; font-family: 'trebuchet ms', geneva, sans-serif;\">\u201cMaestro del mostruoso e scopritore dell\u2019 inconscio\u201d \u2013 secondo la definizione di Carl Jung- Hieronymus Bosch, vissuto tra il 1450 ed il 1616, si \u00e8 distaccato dagli altri artisti del suo tempo e i suoi capolavori hanno sempre generato domande nell\u2019osservatore.<br \/>\n Nel suo universo artistico -per noi ancora un enigma di difficile soluzione &#8211; il visionario pittore olandese ha unito una complessa simbologia ad una strabiliante creativit\u00e0 che sembrerebbe lasciare ben poco al caso: metamorfosi alchemiche, disegni allegorici, tradizione ermetica, erotismo pi\u00f9 o meno mascherato in cui uomini, donne, animali e vegetali si uniscono in un solo essere e danno vita a spaventose mutazioni senza fine.<br \/>\n \u201cHieronymus Bosch \u2013 Unto dal diavolo\u201d segue un team di esperti in giro per il mondo alla scoperta dei pi\u00f9 noti quadri dell\u2019artista.. Girato nell\u2019arco di cinque anni e diretto da Pieter van Huystee, il film ripercorre la vicenda artistica e umana di uno dei pi\u00f9 misteriosi e celebrati artisti di sempre. <br \/>\n In collaborazione con Wanted Cinema.&nbsp;<br \/>\n Il film fa parte del progetto ACROSS.VIDEO ideato e curato da Cristina Nistic\u00f2 nel 2004 per il Detour. Il progetto ha raccontato negli anni la Storia dell&#8217;Arte attraverso le proiezioni di documentari, film d&#8217;arte e d&#8217;artista, video d&#8217;arte con la collaborazione di artisti, registi e curatori di fama internazionale.<br \/>\n <strong><a href=\"https:\/\/cinedetour.it\/2017\/03\/06\/prenotazioni\/\">&gt;&gt;Prenotazioni<\/a><\/strong><\/span><\/p>\n<\/div>\n<div style=\"text-align: center;\">\n<p style=\"text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">_&nbsp;<\/span><\/p>\n<table style=\"height: 18px; width: 676px;\">\n<tbody>\n<tr style=\"height: 20px;\">\n<td style=\"width: 28.6px; height: 20px; text-align: left;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/10\/LOGOTONDO_ombra.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1217\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/10\/LOGOTONDO_ombra-150x150.png\" alt=\"LOGOTONDO_ombra\" width=\"33\" height=\"33\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/10\/LOGOTONDO_ombra-150x150.png 150w, https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/10\/LOGOTONDO_ombra.png 179w\" sizes=\"(max-width: 33px) 100vw, 33px\" \/><\/a><\/td>\n<td style=\"width: 644.4px; height: 20px; text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif; font-size: 18pt;\">DETOUR<\/span><\/td>\n<\/tr>\n<tr style=\"height: 20.8px;\">\n<td style=\"width: 673px; height: 20.8px; text-align: left;\" colspan=\"2\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif; font-size: 8pt;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Distribuzione indipendente<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: left;\"><span style=\"font-size: 8pt;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<br \/>\n <\/a><\/span><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">Detour \u00e8 affiliato all&#8217;ENAL e alla FICC (Federazione Italiana Circoli Cinema)<\/span><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 8pt;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Sostienici<\/a> \/ <em><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Support Us<br \/>\n <\/a><\/em><\/span><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">Seguici su \/ <em>Follow us on:<\/em><\/span><\/span><\/p>\n<table style=\"width: 122.4px; height: 40px;\">\n<tbody>\n<tr>\n<td style=\"width: 34px;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\"><\/a><\/td>\n<td style=\"width: 34px;\"><a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\"><\/a><\/td>\n<td style=\"width: 35.4px;\"><a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\"><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">&nbsp;<\/span><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Girato nell\u2019arco di cinque anni e diretto da Pieter van Huystee, il documentario ripercorre la vita e le opere di uno dei pi\u00f9 celebrati artisti di sempre, conosciuto in tutto il mondo per le sue raffigurazioni ricche di figure bizzarre e mostruose, allegorie dei mali che affliggono l\u2019umanit\u00e0. \u201cHieronymus Bosch \u2013 Unto dal diavolo\u201d segue un team di esperti in giro per il mondo alla scoperta dei pi\u00f9 noti quadri dell\u2019artista.<\/p>\n","protected":false},"author":2,"featured_media":10188,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376],"tags":[767,434,221],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-10 00:21:07","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/10187"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=10187"}],"version-history":[{"count":7,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/10187\/revisions"}],"predecessor-version":[{"id":10365,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/10187\/revisions\/10365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/10188"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=10187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=10187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=10187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}