{"id":10200,"date":"2017-02-17T19:30:38","date_gmt":"2017-02-17T18:30:38","guid":{"rendered":"https:\/\/cinedetour.it\/?p=10200"},"modified":"2017-02-17T19:30:07","modified_gmt":"2017-02-17T18:30:07","slug":"legemonia-digitale-a-cura-di-renato-curcio-proiezione-critical-visions","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2017\/02\/17\/legemonia-digitale-a-cura-di-renato-curcio-proiezione-critical-visions\/","title":{"rendered":"L&#8217;EGEMONIA DIGITALE. L&#8217;impatto delle nuove tecnologie nel mondo del lavoro, interviene Renato Curcio + proiezione Critical Visions 1.0"},"content":{"rendered":"<p style=\"text-align: left;\"><span style=\"font-size: 12pt; font-family: 'andale mono', monospace;\">Cinema Detour, Via Urbana 107 Roma<\/span><\/p>\n<p style=\"text-align: left;\"><strong><span style=\"font-size: 12pt; font-family: 'andale mono', monospace;\">venerd\u00ec&nbsp;17 febbraio&nbsp;<br \/>\n <\/span><\/strong><span style=\"font-size: 10pt;\"><span style=\"font-family: 'andale mono', monospace;\">ore 19.30-20.00 buffet offerto ai soci &gt;&nbsp;<\/span><span style=\"font-family: 'andale mono', monospace;\">ore&nbsp;20.00-21.15&nbsp;<\/span><span style=\"font-family: 'andale mono', monospace;\">presentazione del libro &gt;&nbsp;<\/span><\/span><span style=\"font-size: 10pt;\"><span style=\"font-family: 'andale mono', monospace;\">ore 21.30 proiezione critical visions<\/span>&nbsp;1.0<\/span><\/p>\n<p><span style=\"font-family: 'andale mono', monospace; font-size: 36pt;\">L&#8217;EGEMONIA DIGITALE<\/span><\/p>\n<p><span style=\"font-family: 'andale mono', monospace; font-size: 18pt;\"><label>L&#8217;impatto delle nuove tecnologie nel mondo del lavoro<\/label>&nbsp;<\/span><\/p>\n<div><span style=\"font-family: 'andale mono', monospace;\">Intervengono: <strong>Renato Curcio<\/strong>, curatore del libro e&nbsp;<strong>Roberto Carocci<\/strong>,<strong>&nbsp;r<\/strong>icercatore in storia contemporanea, storia del lavoro e dei movimenti sociali.&nbsp;<span style=\"color: #4b4f56;\">Coordina <strong>Sara Pollice<\/strong>.<\/span><\/span><\/div>\n<div>&nbsp;<\/div>\n<div style=\"text-align: center;\">\n<div style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/cop-egemonia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10201\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/cop-egemonia.jpg\" alt=\"cop egemonia\" width=\"321\" height=\"474\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/cop-egemonia.jpg 500w, https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/cop-egemonia-203x300.jpg 203w\" sizes=\"(max-width: 321px) 100vw, 321px\" \/><\/a><\/div>\n<div>&nbsp;<\/div>\n<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: 'andale mono', monospace; font-size: 10pt;\">\u201cL\u2019egemonia digitale\u201d restituisce il percorso di un cantiere socianalitico che, partendo dalle narrazioni d\u2019esperienza dei suoi partecipanti, si \u00e8 interessato ai modi in cui L\u2019impero Virtuale cerca di costruire la sua capacit\u00e0 egemonica sul mondo del lavoro.<\/span><\/div>\n<p><span style=\"font-family: 'andale mono', monospace; font-size: 10pt;\">Ripercorrendo la micro-fisica dei processi innescati dai dispositivi digitali che mediano l\u2019attivit\u00e0 lavorativa \u2013 smartphone, piattaforme, sistemi gestionali, registri elettronici, ecc. \u2013 il libro esplora alcune metamorfosi radicali che, mentre rovesciano il rapporto millenario tra gli umani e i loro strumenti, sconvolgono ci\u00f2 che fino a ieri abbiamo familiarmente chiamato \u201clavoro\u201d.<\/span><\/p>\n<p><span style=\"font-family: 'andale mono', monospace; font-size: 10pt;\">Alcuni territori chiave \u2013 la digitalizzazione della scuola, della professione medica, dei servizi, dei trasporti condivisi, dei grandi studi legali e delle banche &#8211; assunti come analizzatori, ci raccontano l\u2019impatto trasformativo delle nuove tecnologie e il disorientamento dei lavoratori. Ma, nello stesso tempo, fanno emergere le linee liberticide su cui questo processo procede: la cattura degli atti, la dittatura dei dati, il trionfo della quantit\u00e0 e le storie improbabili in cui esso si racconta.<\/span><\/p>\n<p><span style=\"font-family: 'andale mono', monospace; font-size: 10pt;\">Proprio riflettendo su queste tendenze che velocemente ci attraversano fino al punto di chiamarci in causa singolarmente il libro, infine, indica quattro pericolose tendenze generali \u2013 l\u2019autismo digitale, l\u2019obesit\u00e0 tecnologica, l\u2019ethos della quantit\u00e0, lo smarrimento dei limiti \u2013 e pone una domanda: non \u00e8 forse giunto il momento, dopo le ambigue interpretazioni del 900, di cominciare a distinguere il progresso sociale dal progresso tecnologico?<\/span><\/p>\n<div><span style=\"font-family: 'andale mono', monospace; font-size: 10pt;\"><strong>Edizioni&nbsp;<\/strong>Sensibili alle Foglie,&nbsp;2016.<\/span><\/div>\n<p style=\"text-align: left;\">&nbsp;<\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: 'andale mono', monospace;\">ore 21.30 proiezione<\/span><\/p>\n<div>\n<div title=\"Page 1\">\n<p style=\"text-align: left;\"><span style=\"font-size: xx-large; font-family: 'andale mono', monospace;\"><span style=\"font-size: 36pt;\">CRITICAL VISIONS 1.0<\/span><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: 'andale mono', monospace; font-size: 14pt;\"><span style=\"line-height: 20px;\">Esperienze visive di critica collettiva alla societ\u00e0 digitale scelte da Detour.<\/span><\/span><\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/egemonia_2017.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10208 alignnone\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/egemonia_2017.jpg\" alt=\"egemonia_2017\" width=\"737\" height=\"414\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/egemonia_2017.jpg 1280w, https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/egemonia_2017-300x169.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/egemonia_2017-768x432.jpg 768w, https:\/\/cinedetour.it\/wp-content\/uploads\/2017\/02\/egemonia_2017-1024x576.jpg 1024w\" sizes=\"(max-width: 737px) 100vw, 737px\" \/><\/a><\/p>\n<\/div>\n<\/div>\n<p style=\"text-align: left;\">&nbsp;&#8212;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1283\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"93\" height=\"91\"><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 8pt; font-family: arial, helvetica, sans-serif;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Produzione | Distribuzione | indipendente<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 8pt; font-family: arial, helvetica, sans-serif;\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\">Tutti i film sono proiettati in lingua originale con sottotitoli in italiano<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 8pt;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><em>Art-house membership cinema in downtown Rome since 1997.<br \/>\n <\/em><\/span><em>All movies are screened in their original languages with italian or english subtitles<\/em><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\">Cineclub Detour \u00e8 affiliato all&#8217;ENAL e alla FICC (Federazione Italiana Circoli Cinema)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;EGEMONIA DIGITALE. L&#8217;impatto delle nuove tecnologie nel mondo del lavoro. Intervengono: Renato Curcio, curatore del libro e Roberto Carocci, ricercatore in storia contemporanea, di storia del lavoro e dei movimenti sociali. Coordina Sara Pollice. A seguire proiezione CRITICAL VISIONS 1.0: esperienze visive di critica collettiva alla societ\u00e0 digitale scelte da Detour.<\/p>\n","protected":false},"author":2,"featured_media":10208,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[293,429,428,305,912,294,430,911],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 22:42:13","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/10200"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=10200"}],"version-history":[{"count":15,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/10200\/revisions"}],"predecessor-version":[{"id":10317,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/10200\/revisions\/10317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/10208"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=10200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=10200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=10200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}