{"id":15192,"date":"2019-04-27T21:00:39","date_gmt":"2019-04-27T20:00:39","guid":{"rendered":"https:\/\/cinedetour.it\/?p=15192"},"modified":"2020-07-06T13:02:17","modified_gmt":"2020-07-06T12:02:17","slug":"westwood-punk-icona-attivista-2-2","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2019\/04\/27\/westwood-punk-icona-attivista-2-2\/","title":{"rendered":"WESTWOOD: Punk, Icon, Activist"},"content":{"rendered":"<p style=\"text-align: left;\"><span style=\"font-size: 12pt; font-family: 'trebuchet ms', geneva, sans-serif;\"><span style=\"font-size: 10pt;\"><em>Cinema Detour, Via Urbana 107 Roma<\/em><\/span><br \/>\n<span style=\"font-size: 10pt;\"><em>Sabato 27 Aprile 2019 ore 21.00 \/ April 27 2019, Saturday 9.00pm<\/em><\/span><br \/>\n<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><em><span style=\"font-size: 10pt;\">In collaborazione con \/ in collaboration with Wanted Cinema, On the Road Film Festival Preview 2019<\/span><\/em><br \/>\n<span style=\"font-size: 24pt;\"><span style=\"font-size: 36pt;\"><span style=\"font-size: 24pt;\"><span style=\"font-size: 36pt;\"><span style=\"font-size: 24pt;\">WESTWOOD: PUNK, ICONA, ATTIVISTA<\/span><br \/>\n<\/span><\/span><\/span><\/span><span style=\"font-size: 10pt;\">Regia \/ Director&nbsp;Lorna Tucker.&nbsp;Con&nbsp;Vivienne Westwood&nbsp;<\/span><\/span><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><span style=\"font-size: 10pt;\">(UK 2018, 85&#8242;, v.o. inglese con sott. italiano)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2019\/03\/vestvud.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14957\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2019\/03\/vestvud-683x1024.jpg\" alt=\"\" width=\"517\" height=\"776\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2019\/03\/vestvud-683x1024.jpg 683w, https:\/\/cinedetour.it\/wp-content\/uploads\/2019\/03\/vestvud-200x300.jpg 200w, https:\/\/cinedetour.it\/wp-content\/uploads\/2019\/03\/vestvud-768x1152.jpg 768w, https:\/\/cinedetour.it\/wp-content\/uploads\/2019\/03\/vestvud.jpg 780w\" sizes=\"(max-width: 517px) 100vw, 517px\" \/><\/a><\/p>\n<div>\n<div style=\"text-align: justify;\" title=\"Page 1\">\n<p style=\"text-align: left;\"><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\">ITA (scroll for Eng).&nbsp;Vivienne Westwood, icona Punk Rock per eccellenza, \u00e8 una delle artiste pi\u00f9 influenti della storia contemporanea. Il film esplora la sua ascesa verso il successo, mostrando da vicino il suo talento, il suo attivismo e la sua significativa importanza culturale. Intrecciando il materiale d\u2019archivio e quello inedito, viene raccontata in modo intimo la storia di Vivienne, attraverso le sue stesse parole e le toccanti interviste alla sua stretta cerchia di familiari, amici e collaboratori.<\/span><\/p>\n<p><span style=\"font-family: 'trebuchet ms', geneva, sans-serif; font-size: 10pt;\">WESTWOOD: PUNK, ICONA, ATTIVISTA \u00e8 il primo film ad abbracciare l\u2019eccezionale storia di una delle icone pi\u00f9 autentiche del nostro tempo, dal momento che Vivienne ha lottato per mantenere l\u2019integrit\u00e0 del suo brand, dei suoi principi e della sua eredit\u00e0. Vivienne Westwood, di umili origini, si spost\u00f2 dall\u2019Inghilterra del nord a Londra all\u2019et\u00e0 di diciassette anni, alla met\u00e0 degli anni \u201960. La sua vita cambi\u00f2 drasticamente direzione quando incontr\u00f2 Malcolm McLaren, impresario e manager dei Sex Pistols: il loro negozio a Kings Road lanci\u00f2 il genere punk e una cultura popolare rivoluzionaria. Durante i successivi quarant\u2019anni Vivienne ha dovuto far fronte a relazioni frustranti, derisioni da parte della stampa, situazioni finanziarie difficili e nonostante questo \u00e8 riuscita a emergere come un\u2019icona culturale inglese e un fenomeno nel mondo del fashion. Oggi il brand Westwood siede a fianco di marchi quali Gucci, Dior e McQueen, ma solo Vivienne possiede e gestisce direttamente il suo impero, senza dar segno di cedimento all\u2019et\u00e0 di settantasette anni. Il film ritrae Vivienne in un periodo cruciale, quando l\u2019azienda apre i suoi flagship store nelle capitali della moda, Parigi e New York. Tuttavia, il successo globale ha un prezzo e le difficolt\u00e0 legate alla gestione dell\u2019azienda non tardano ad arrivare. Attraverso il continuo alternarsi delle riprese che testimoniano i successi, i conflitti e le insicurezze che Vivienne affronta oggi e i momenti cardine della sua vita, emergono parallelismi tra il suo attivismo del 21esimo secolo e la sua attitudine punk rock antisistema della giovinezza.<\/span><\/p>\n<p><span style=\"font-family: 'trebuchet ms', geneva, sans-serif; font-size: 10pt;\">Questo documentario trascende il modello standard di film sulla moda per trasformarsi in un ritratto intimo e stimolante di una vera icona inglese.<\/span><\/p>\n<p><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\"><span class=\"text_exposed_show\">ENG. <em>The first film to encompass the remarkable story of one of the true icons of our time, as she fights to maintain her brand&#8217;s integrity, her principles &#8211; and her legacy.<\/em><\/span><\/span><\/p>\n<p><span style=\"font-size: 8pt; font-family: 'trebuchet ms', geneva, sans-serif;\"><span style=\"text-align: left; font-size: 16px;\">_&nbsp;<\/span><br \/>\n<\/span><\/p>\n<\/div>\n<div style=\"text-align: center;\">\n<table style=\"height: 18px; width: 676px;\">\n<tbody>\n<tr style=\"height: 20px;\">\n<td style=\"width: 28.6px; height: 20px; text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/10\/LOGOTONDO_ombra.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-1217\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/10\/LOGOTONDO_ombra-150x150.png\" alt=\"LOGOTONDO_ombra\" width=\"33\" height=\"33\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/10\/LOGOTONDO_ombra-150x150.png 150w, https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/10\/LOGOTONDO_ombra.png 179w\" sizes=\"(max-width: 33px) 100vw, 33px\" \/><\/a><\/span><\/td>\n<td style=\"width: 644.4px; height: 20px; text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif; font-size: 18pt;\">DETOUR<\/span><\/td>\n<\/tr>\n<tr style=\"height: 20.8px;\">\n<td style=\"width: 673px; height: 20.8px; text-align: left;\" colspan=\"2\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif; font-size: 8pt;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Distribuzione indipendente<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif; font-size: 10pt;\">Associazione Culturale Detour \u2013 Via Urbana 107 Roma&nbsp;<a href=\"http:\/\/www.cinedetour.it\/\">www.cinedetour.it<\/a>\u2013&nbsp;<a href=\"https:\/\/cinedetour.it\/2019\/02\/01\/la-donna-elettrica\/cinedetour@tiscali.it\">cinedetour@tiscali.it<br \/>\n<\/a>Ingresso con tessera annuale 5 euro + quota partecipativa. Pre-tesseramento&nbsp;<a href=\"https:\/\/cinedetour.it\/tesseramento\/\">QUI<\/a>. Prenotazioni&nbsp;<a href=\"https:\/\/cinedetour.it\/2017\/03\/06\/prenotazioni\/\">QUI<\/a>.<a href=\"https:\/\/cinedetour.it\/2019\/02\/01\/la-donna-elettrica\/cinedetour@tiscali.it\"><br \/>\n<\/a>Detour \u00e8 affiliato all\u2019ASSO.N.A.M. e alla FICC (Federazione Italiana Circoli Cinema)<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 8pt; font-family: 'trebuchet ms', geneva, sans-serif;\"><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sostienici<\/a> \/ <em><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\" rel=\"noopener noreferrer\">Support Us<br \/>\n<\/a><\/em>Seguici su \/ <em>Follow us on:<\/em><\/span><\/p>\n<table style=\"width: 122.4px; height: 40px;\">\n<tbody>\n<tr>\n<td style=\"width: 34px;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\"><\/a><\/span><\/td>\n<td style=\"width: 34px;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\"><\/a><\/span><\/td>\n<td style=\"width: 35.4px;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\"><a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\"><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">&nbsp;<\/span><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>The first film to encompass the remarkable story of one of the true icons of our time, as she fights to maintain her brand&#8217;s integrity, her principles and her legacy.<\/p>\n","protected":false},"author":2,"featured_media":14957,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[2243],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":true,"content":false,"excerpt":true}}},"publishpress_future_action":{"enabled":false,"date":"2026-07-15 03:06:10","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/15192"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=15192"}],"version-history":[{"count":4,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/15192\/revisions"}],"predecessor-version":[{"id":17207,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/15192\/revisions\/17207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/14957"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=15192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=15192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=15192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}