{"id":18019,"date":"2024-06-22T11:49:10","date_gmt":"2024-06-22T10:49:10","guid":{"rendered":"https:\/\/cinedetour.it\/?p=18019"},"modified":"2024-06-24T18:12:52","modified_gmt":"2024-06-24T17:12:52","slug":"sostieni-il-detour-con-il-tuo-5x1000-cultura-accessibile-e-solidale-2","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2024\/06\/22\/sostieni-il-detour-con-il-tuo-5x1000-cultura-accessibile-e-solidale-2\/","title":{"rendered":"Sostieni Detour con il tuo 5&#215;1000"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: 14pt; font-family: 'trebuchet ms', geneva, sans-serif;\"><strong>Per destinare il proprio 5X1000 a DETOUR APS<br \/>\nbasta inserire il codice fiscale dell&#8217;associazione: 96331750586<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; font-family: 'trebuchet ms', geneva, sans-serif;\"><strong>Il campo da compilare sulla vostra dichiarazione dei redditi \u00e8 il primo,<br \/>\nquello relativo alle associazioni di volontariato e onlus.<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2021\/03\/5x1000_detour2024.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-20644 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2021\/03\/5x1000_detour2024-1014x1024.jpg\" alt=\"\" width=\"554\" height=\"560\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2021\/03\/5x1000_detour2024-1014x1024.jpg 1014w, https:\/\/cinedetour.it\/wp-content\/uploads\/2021\/03\/5x1000_detour2024-297x300.jpg 297w, https:\/\/cinedetour.it\/wp-content\/uploads\/2021\/03\/5x1000_detour2024-768x776.jpg 768w, https:\/\/cinedetour.it\/wp-content\/uploads\/2021\/03\/5x1000_detour2024-1520x1536.jpg 1520w, https:\/\/cinedetour.it\/wp-content\/uploads\/2021\/03\/5x1000_detour2024-2027x2048.jpg 2027w\" sizes=\"(max-width: 554px) 100vw, 554px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\"><em><span style=\"font-family: 'trebuchet ms', geneva, sans-serif;\">Fotogramma: Buster Keaton and Virginia Fox collapse in THE ELECTRIC HOUSE (1922)<\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\">Detour \u00e8 portata avanti da soci volontari motivati dalla volont\u00e0 di condividere la propria passione per il cinema e l&#8217;arte, dalla possibilit\u00e0 di aprire e democratizzare l\u2019esperienza cinematografica e creativa rendendola inclusiva, condivisa e praticabile per tutte e a tutti.&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\">Il luogo del cinema assume il significato di arte accessibile, che scende dal piedistallo dell\u2019ottica commerciale della distribuzione per avvicinarsi alle persone, e annullare ogni tipo di stereotipo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\">Parallelamente all&#8217;attivit\u00e0 prevalente di diffusione del cinema indipendente di qualit\u00e0, l\u2019associazione, si occupa di promuovere e organizzare corsi di alfabetizzazione cinematografica rivolti a studenti (progetti Piccoli Filmaker e Roaming Rome con il contributo del Comune di Roma), a cittadini socialmente svantaggiati e a persone diversamente abili (Ragazzinvisibili.doc con il contributo della Regione Lazio, Lo sguardo degli Aspie &#8211; Ragazzi con Sindrome di Asperger, rassegne di cinema commentato per non vedenti, ecc.).<\/span><\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\">Detour \u00e8 attiva nella produzione di laboratori di documentario sociale partecipativo a basso budget. Tra gli audiovisivi realizzati, Arriva la Banda!, co-prodotto dalla cooperativa sociale integrata Cotrad Onlus, girato con la collaborazione e la partecipazione di giovani diversamente abili, \u00e8 stato premiato come miglior cortometraggio 2006 nel al Rdc Awards \/ Festival Tertio Millennio ed ha ricevuto la menzione speciale al festival Nickelodeon di Spoleto. Il corto Black Out, realizzato nell\u2019ambito del laboratorio Giovani Filmaker \u00e8 stato selezionato alla Festa del Cinema di Roma nella sezione Alice nella Citt\u00e0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\">Detour ha collaborato e collabora attivamente con organizzazioni non governative, cooperative, onlus e associazioni del volontariato tra cui SAVE THE CHILDREN, AMNESTY INTERNATIONAL, RE.COMMON, ASSOCIAZIONE ASPERGER, ASSOCIAZIONE ITALIANA PERSONE DOWN, UNIONE ITALIANA CIECHI E IPOVEDENTI, Coop COTRAD Onlus, ass. CINEMAMME, ecc.<\/span><\/p>\n<p><span style=\"font-size: 10pt; font-family: 'trebuchet ms', geneva, sans-serif;\"><strong>Per ulteriori informazioni, per conoscere i nostri progetti e per proporne di vostri, scriveteci a detourcinema@gmail.com o visitate le nostre pagina social.<\/strong><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Per destinare il proprio 5X1000 al DETOUR \u00e8 sufficiente inserire il codice fiscale dell\u2019associazione: CODICE FISCALE 96331750586.  Il campo da compilare sulla vostra dichiarazione dei redditi \u00e8 il primo, quello relativo alle associazioni di volontariato e Onlus.  Detour \u00e8 stato riconosciuto ente di promozione sociale, grazie alla sua storia ventennale di diffusione della cultura cinematografica e ai numerosi progetti socio-culturali inclusivi che abbiamo attivato e sostenuto nel corso degli anni, finalizzati all\u2019abbattimento totale delle barriere culturali e architettoniche. Il luogo del cinema assume il significato di arte accessibile, di arte che scende dal piedistallo dell\u2019ottica commerciale della distribuzione per avvicinarsi alle persone, e annullare ogni tipo di stereotipo. Detour \u00e8 portato avanti da soci volontari motivati dalla volont\u00e0 di condividere la propria passione per il cinema e l&#8217;arte dalla possibilit\u00e0 di aprire e democratizzare l\u2019esperienza creativa rendendola accessibile a gruppi di cittadini socialmente svantaggiati, diversamente abili, migranti, ecc. Detour \u00e8 l\u2019unico cineclub di Roma ad aver abbattuto completamente le barriere architettoniche fin dalla sua fondazione nel 1997.<\/p>\n","protected":false},"author":2,"featured_media":20644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376,13,320,697,1],"tags":[],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 14:33:27","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/18019"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=18019"}],"version-history":[{"count":15,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/18019\/revisions"}],"predecessor-version":[{"id":18023,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/18019\/revisions\/18023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/20644"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=18019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=18019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=18019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}