{"id":1807,"date":"2014-01-13T12:37:35","date_gmt":"2014-01-13T11:37:35","guid":{"rendered":"https:\/\/cinedetour.it\/?p=1807"},"modified":"2014-11-04T10:22:31","modified_gmt":"2014-11-04T09:22:31","slug":"cinemamme-gennaio","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2014\/01\/13\/cinemamme-gennaio\/","title":{"rendered":"Cinemamme Gennaio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1808\" alt=\"CINEMAMME\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/01\/CINEMAMME.jpg\" width=\"992\" height=\"1404\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/01\/CINEMAMME.jpg 992w, https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/01\/CINEMAMME-211x300.jpg 211w, https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/01\/CINEMAMME-723x1024.jpg 723w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/><\/p>\n<p style=\"text-align: center;\">\u00a0<span style=\"text-align: center;\">***<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">Ideato per la prima volta a Roma dall&#8217;associazione di volontariato Citta&#8217; delle mamme, <strong>Cinemamme<\/strong> sbarca anche al Detour. <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">Da mercoled\u00ec 15 gennaio, con cadenza settimanale, alle ore 10:30 il Detour propone i titoli migliori del proprio programma mensile in versione &#8220;baby&#8221;: <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">luci soffuse, volume adeguato, possibilita&#8217; di accedere in sala con il passeggino, fasciatoio e scalda biberon a disposizione. <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">Cinebar e caffetteria in funzione per pre e post visione.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">L&#8217;ingresso e&#8217; riservato ai soci ARCI: i genitori devono sottoscrivere la tessera (8 \u20ac).<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">Per ogni tessera si ha diritto ad un ingresso omaggio.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">Ingresso alla proiezione 5 euro.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">Per info e prenotazioni: cinebimbi@gmail.com<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0*** Ideato per la prima volta a Roma dall&#8217;associazione di volontariato Citta&#8217; delle mamme, Cinemamme sbarca anche al Detour. Da mercoled\u00ec 15 gennaio, con cadenza settimanale, alle ore 10:30 il Detour propone i titoli migliori del proprio programma mensile in versione &#8220;baby&#8221;: luci soffuse, volume adeguato, possibilita&#8217; di accedere in sala con il passeggino, fasciatoio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1809,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[6,39,874,22,41,879,4,40],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 15:08:43","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/1807"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=1807"}],"version-history":[{"count":1,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/1807\/revisions"}],"predecessor-version":[{"id":1810,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/1807\/revisions\/1810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/1809"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=1807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=1807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=1807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}