{"id":1837,"date":"2014-01-22T13:03:35","date_gmt":"2014-01-22T12:03:35","guid":{"rendered":"https:\/\/cinedetour.it\/?p=1837"},"modified":"2014-11-04T10:22:28","modified_gmt":"2014-11-04T09:22:28","slug":"cinema-militante-colonialismo-e-censura","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2014\/01\/22\/cinema-militante-colonialismo-e-censura\/","title":{"rendered":"Cinema militante | Colonialismo e censura"},"content":{"rendered":"<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"><strong>CINECLUB DETOUR VIA URBANA 107 &#8211; GIOVED\u00ec 23 ore 21.00<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"font-size: large;\"><span style=\"font-size: x-large;\"><strong><span style=\"color: #303030;\">CINEMA MILITANTE: COLONIALISMO E CENSURA<\/span><\/strong><br \/>\n<\/span><em><br \/>\n<\/em><\/span> <span style=\"font-size: small;\">in collaborazione con Aude Fourel, videoartista e insegnante all&#8217;Universit\u00e0 di St-Etienne (Francia)<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"><strong>\u00a0ore 21.30<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span class=\"aligncenter\" style=\"font-size: xx-large;\">Octobre \u00e0 Paris<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di Jacques Panijel (Francia 1962, 70\u2019, versione francese sottotitoli in italiano)<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1561\" alt=\"octobre-a-paris\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/12\/octobre-a-paris.jpg\" width=\"350\" height=\"274\" \/><\/p>\n<p><span style=\"font-size: small;\">Qualche mese prima della fine della Guerra d\u2019Algeria, il 17 ottobre 1961, un corteo di immigrati algerini che protesta pacificamente contro il coprifuoco selettivo e discriminatorio decretato dal prefetto Maurice Papon viene attaccato dalla polizia che spara sulla folla, scatena la caccia all\u2019uomo, uccide a sangue freddo, getta cadaveri nella Senna. Nei mesi che seguono il massacro d\u2019ottobre, Jacques Panijel, mostra in un film la vita quotidiana degli Algerini: nelle bidonville di Nanterre e Gennevilliers, gli arresti, il centro di tortura di rue de la Goutte d\u2019or 28. Gira, con quelli che ne erano stati gli attori e sugli stessi luoghi, la preparazione e la partenza della manifestazione del 17 ottobre, resa con un montaggio d\u2019archivio, foto e immagini filmate; poi le testimonianze: la macchina da presa torna sul percorso di coloro che sono stati arrestati, torturati, gettati nella Senna.<\/span><\/p>\n<p>Dopo anni di copie sequestrate e proiezioni vietate dalla censura, nel maggio del \u201868 il film \u00e8 proiettato al cinema Les Trois Luxembourg, insieme a La battaglia d\u2019Algeri. Nel 1973, dopo uno sciopero della fame del regista Ren\u00e9 Vautier, il film ottiene un visto della censura, senza per\u00f2 essere distribuito. Nel 1981 alcune promesse di diffusione in televisione non hanno seguito. Le copie disperse di Octobre \u00e0 Paris non sono visibili. Continua un\u2019altra forma di censura subdola.<\/p>\n<p>Nell&#8217;ottobre 2011, in occasione del cinquantenario della strage, le edizioni Montparnasse pubblicano il primo DVD di Octobre \u00e0 Paris, ma il film non \u00e8 citato nel Dizionario del Cinema Francese.<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: small;\">a seguire\u00a0<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large;\">Afrique 50 <span style=\"font-size: medium;\">+\u00a0<strong>intervista a Ren\u00e9 Vautier sul cinema militante (10&#8242;)<\/strong><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di \u00a0Ren\u00e9 Vautier\u00a0(Francia 1956, 25\u2019, versione francaise sottotitoli in italiano)<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1573\" alt=\"afrique_50\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/12\/afrique_50.jpg\" width=\"200\" height=\"280\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\">Nel 1949, Ren\u00e9 Vautier, giovane regista di 21 anni, resistente decorato della Croce di Guerra nel 1944, appena diplomato dell\u2019IDHEC (Scuola Nazionale di Cinema di Parigi, oggi La F\u00e9mis) parte per la Costa D\u2019Avorio con l\u2019incarico di girare un documentario per conto della Lega per l\u2019Istruzione (Ligue de l&#8217;enseignement). Vautier arriva l\u00ec per raccontare \u00abquello che \u00e8 vero\u00bb e decide di non servire gli interessi della propaganda ufficiale, filmando ci\u00f2 che vede quotidianamente: la mancanza di medici e insegnanti, i crimini commessi dall\u2019esercito francese e lo sfruttamento delle popolazioni colonizzate. Le autorit\u00e0 coloniali lo accusano di filmare senza l\u2019autorizzazione dei governatori. Ricercato, ufficialmente espulso, fugge verso Bamako e filma clandestinamente, lungo un percorso di mille chilometri, tracce di oppressione e di repressione. Al termine di un viaggio di quasi un anno, grazie alla solidariet\u00e0 di africani, pescatori bretoni, giudici e doganieri, Vautier riesce a tornare in Francia e a rimpatriare le pellicole del film, che vengono consegnate alla Lega per l\u2019Istruzione e in seguito sequestrate dalla polizia. Nel corso di un interrogatorio, grazie a un sotterfugio, riesce a salvare 21 bobine positive sulle 60 girate per realizzare il montaggio di Africa 50. Africa 50 \u00e8 il primo film francese dichiaratamente anticoloniale. Censurato dal 1950 al 1990, porter\u00e0 13 accuse a Ren\u00e9 Vautier e una condanna a un anno di carcere.<\/span><\/p>\n<p><span style=\"font-size: small;\"><strong>Oggi, grazie al prezioso lavoro di ricerca e traduzione di Aude Fourel, abbiamo finalmente la possibilit\u00e0 di vedere al Detour il film \u201cproibito\u201d di Jacques Panijel e Afrique 50 di Ren\u00e9 Vautier in versione francese con sottotitoli in italiano.\u00a0<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CINECLUB DETOUR VIA URBANA 107 &#8211; GIOVED\u00ec 23 ore 21.00 CINEMA MILITANTE: COLONIALISMO E CENSURA in collaborazione con Aude Fourel, videoartista e insegnante all&#8217;Universit\u00e0 di St-Etienne (Francia) \u00a0ore 21.30 Octobre \u00e0 Paris di Jacques Panijel (Francia 1962, 70\u2019, versione francese sottotitoli in italiano) Qualche mese prima della fine della Guerra d\u2019Algeria, il 17 ottobre 1961, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1842,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[55,874,58,54,59,57,56],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 15:08:41","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/1837"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=1837"}],"version-history":[{"count":3,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/1837\/revisions"}],"predecessor-version":[{"id":1841,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/1837\/revisions\/1841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/1842"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=1837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=1837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=1837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}