{"id":20587,"date":"2024-04-30T14:14:54","date_gmt":"2024-04-30T13:14:54","guid":{"rendered":"https:\/\/cinedetour.it\/?p=20587"},"modified":"2024-06-24T18:11:35","modified_gmt":"2024-06-24T17:11:35","slug":"bank-of-targets-cinema-palestina","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2024\/04\/30\/bank-of-targets-cinema-palestina\/","title":{"rendered":"BANK OF TARGETS. CINEMA PALESTINA"},"content":{"rendered":"<p><strong>CineDetour e Circolo di San Lorenzo<\/strong><\/p>\n<p>in collaborazione con<strong> Monica Maurer e Valeria Belli<\/strong><\/p>\n<p>presentano<\/p>\n<h1><strong><span style=\"font-size: 14pt;\">16, 23, 30 Aprile 2024<br \/>\n<\/span><\/strong><strong><span style=\"font-size: 14pt;\">presso CIRCOLO DI SAN LORENZO, Via dei Latini 73<\/span><\/strong><em><strong><span style=\"font-size: 14pt;\"><br \/>\n<\/span><\/strong><\/em><\/h1>\n<p>&nbsp;<\/p>\n<h1>BANK OF TARGETS. CINEMA PALESTINA<\/h1>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/cinema-palestina.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20588\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/cinema-palestina.jpg\" alt=\"\" width=\"822\" height=\"692\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/cinema-palestina.jpg 822w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/cinema-palestina-300x253.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/cinema-palestina-768x647.jpg 768w\" sizes=\"(max-width: 822px) 100vw, 822px\" \/><\/a><\/p>\n<div>\n<p>Bank of targets, terra di obiettivi, sponda di macerie, rovina della memoria e polvere mediatica a coprire. <br \/>\nIl popolo palestinese non ha mai smesso di raccontare la sofferenza sotto l&#8217;occupazione israeliana, in ogni forma possibile. L\u2019autodeterminazione parte dal narrarsi in prima persona, senza filtri occidentali, come atto di resistenza culturale &nbsp;alla colonizzazione militare e mentale delle forze di occupazione. Nelle immagini di questi film ragazze e ragazzi, donne e uomini prendono la &nbsp;parola per raccontarci le loro storie di umiliazione, terrore, privazione.<\/p>\n<p><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs xlh3980 xvmahel x1n0sxbx x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">&gt; Serate a sostegno della campagna ACQUA PER GAZA, raccolta fondi organizzata da UN PONTE PER.<\/span><\/p>\n<hr>\n<\/div>\n<p><strong>CIRCOLO DI SAN LORENZO Via dei Latini 73\/75<br \/>\n<span style=\"font-size: 12pt;\">19.30 aperitivo<\/span><span style=\"font-size: x-large;\"> <br \/>\n<\/span><span style=\"font-size: 12pt;\">20.30 incontri e proiezioni<\/span><br \/>\n<\/strong><\/p>\n<p><em>per info solo: <\/em><\/p>\n<p><em><a href=\"mailto:detourcinema@gmail.com\">&gt; detourcinema@gmail.com<\/a><br \/>\n&gt; <a href=\"https:\/\/www.facebook.com\/events\/929029618692597\/?post_id=929046175357608&amp;view=permalink&amp;notif_id=1712820231015180&amp;notif_t=feedback_reaction_generic&amp;ref=notif\">evento fb<\/a><br \/>\n<\/em><\/p>\n<div>\n<p><strong><span style=\"font-size: x-large;\">mar 16.4<br \/>\n<\/span><\/strong><em>Monica Maurer e Valeria Belli presentano<\/em><\/p>\n<\/div>\n<div>\n<p><span style=\"font-size: 14pt;\"><strong>Palestina in fiamme <\/strong><span style=\"font-size: 12pt;\">di Monica Maurer<\/span><\/span> (1988, 30&#8242;)<\/p>\n<p><span style=\"font-size: 10pt;\">ITA Il film tenta di ricostruire &#8211; in parte con materiale d&#8217;archivio &#8211; il retroscena storico-politico dell&#8217;Intifada: una rivolta che ha le sue radici negli anni &#8217;20 del Novecento, quando a causa della colonizzazione della Palestina da parte degli ebrei sionisti, provenienti soprattutto dall&#8217;Europa, fin\u00ec la secolare convivenza pacifica tra le tre religioni monoteistiche (islamismo, ebraismo, cristianesimo). Nel 1947 l&#8217;Onu decise di dividere la Palestina &#8211; allora sotto mandato britannico &#8211; in due stati: uno ebraico e l&#8217;altro arabo. Nel 1948 con la creazione dello Stato di Israele iniziarono l&#8217;occupazione delle terre arabe e l&#8217;infinita serie di scontri e guerre<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">ENG This documentary shows the political and historical roots of the Intifada which at the end of 1987 became a mass movement against the Israeli occupation, it shows that the core issue of the Palestinian Resistance is the struggle for the land &#8211; from the zionist colonization of Palestine in the twenties to the Nabka 1948, the occupation of the Westbank and Gaza in 1967 to the illegal expansioist settlement &#8211; policy ever since.<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/PIF-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-20594\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/PIF-4-300x229.jpg\" alt=\"\" width=\"300\" height=\"229\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/PIF-4-300x229.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/PIF-4-1024x782.jpg 1024w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/PIF-4-768x586.jpg 768w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/PIF-4-1536x1173.jpg 1536w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/PIF-4-2048x1564.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Bank of Targets <\/strong><span style=\"font-size: 12pt;\">di Rushdi Sarraj <\/span><\/span>(2021, 26&#8242;)<\/p>\n<p><span style=\"font-size: 10pt;\">ITA Attraverso le testimonianze dei sopravvissuti, i resoconti dei testimoni oculari e le riprese in tempo reale i bombardamenti del maggio 2021, &#8220;Bank of Targets&#8221; descrive abilmente la natura indiscriminata degli attacchi aerei israeliani, mostra la devastazione diffusa, evidenziando esplicitamente la distruzione di infrastrutture civili essenziali, tra cui ospedali, scuole e aree residenziali. Un potente film documentario diretto dall&#8217;acclamato regista\/giornalista palestinese Rushdi Sarraj, ucciso dai bombardamenti israeliani il 22 ottobre del 2023.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">ENG The film captures the heart-wrenching scenes that become all too common in Gaza, as families are torn apart and entire neighborhoods reduced to rubble. Through testimonies of survivors, eyewitness accounts, and comprehensive footage, &#8220;Bank of Targets&#8221; skillfully depicts the indiscriminate nature of the Israeli airstrikes during May 2021. It showcases the widespread devastation, explicitly highlighting the destruction of essential civilian infrastructure, including hospitals, schools, and residential areas. A powerful documentary film directed by acclaimed Palestinian filmmaker\/journalist the late Rushdi Sarraj murdered by Israeli bombings on the 22nd of October 2023.<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/bank-of-targets-locandina-ENG.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-20591\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/bank-of-targets-locandina-ENG-216x300.png\" alt=\"\" width=\"216\" height=\"300\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/bank-of-targets-locandina-ENG-216x300.png 216w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/bank-of-targets-locandina-ENG-737x1024.png 737w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/bank-of-targets-locandina-ENG-768x1067.png 768w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/bank-of-targets-locandina-ENG-1105x1536.png 1105w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/bank-of-targets-locandina-ENG.png 1160w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/><\/a><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>The People&#8217;s Patriarch <\/strong><span style=\"font-size: 12pt;\">di Mohammed Alatar <\/span><\/span>(2020, 27&#8242;)<\/p>\n<p><span style=\"font-size: 10pt;\">ITA Michel Sabbah \u00e8 un arabo palestinese cristiano di Nazareth che Papa Giovanni Paolo II ha nominato patriarca latino di Gerusalemme nel 1987, il cui impegno rappresenta una pietra miliare nella battaglia contro l\u2019ingiustizia e l\u2019oppressione che il popolo palestinese subisce.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">ENG Michel Sabbah is a Palestinian Arab Christian from Nazareth whom Pope John Paul II appointed Latin Patriarch of Jerusalem in 1987, whose efforts represent a milestone in the battle against the injustice and oppression suffered by the Palestinian people.<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/people-patriarch.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-20595\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/people-patriarch-300x153.jpg\" alt=\"\" width=\"300\" height=\"153\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/people-patriarch-300x153.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/people-patriarch-1024x522.jpg 1024w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/people-patriarch-768x392.jpg 768w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/people-patriarch-1536x783.jpg 1536w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/people-patriarch.jpg 1867w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<\/div>\n<hr>\n<p><strong><span style=\"font-size: 18pt;\">mar 23\/4<\/span> <\/strong><br \/>\n<em>Monica Maurer e Maya Issa presentano <span class=\"Apple-converted-space\">&nbsp; &nbsp; &nbsp; &nbsp;<\/span><\/em><\/p>\n<div>\n<p><strong><span style=\"font-size: 14pt;\">Between Two Crossing<\/span><\/strong> di Yaser Murtaja (2018, 43&#8242;)<\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/between-two-crossings-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-20592\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/between-two-crossings-2-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/between-two-crossings-2-300x169.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/between-two-crossings-2-1024x576.jpg 1024w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/between-two-crossings-2-768x432.jpg 768w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/between-two-crossings-2.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"font-size: 10pt;\">ITA \u201cBetween two crossings&#8221; segue il viaggio di Nour, una studentessa di Gaza che ha vinto una borsa di studio per la Portland State University, negli Stati Uniti. Non sar\u00e0 facile per\u00f2 superare i due varchi che separano la Striscia di Gaza dal resto del mondo: il valico di Erez, controllato da Israele; e quello di Rafah, controllato dall\u2019Egitto.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">ENG &#8220;Between Two Crossings&#8221; follows the journey of Nour, a student from Gaza who has won a scholarship to Portland State University, in the United States. However, it will not be easy to cross the two check-point that separate the Gaza Strip from the rest of the world: the Erez crossing, controlled by Israel, and the Rafah crossing, controlled by Egypt.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Omaggio a Yaser Murtaja <\/strong><span style=\"font-size: 12pt;\">di Rushdi Sarraj <\/span><\/span>(2023, 6&#8242;)<\/p>\n<p><span style=\"font-size: 10pt;\">ITA Un breve ricordo del filmmaker e fondatore di Ain Media, Yaser Murtaja.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">ENG A brief tribute to filmmaker and founder of Ain Media, Yaser Murtaja.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Yom Al Ard <\/strong><\/span>di Monica Maurer (1981, 15\u2019)<\/p>\n<p>&nbsp;<a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/YomAlArd.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-20601\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/YomAlArd-300x222.jpg\" alt=\"\" width=\"300\" height=\"222\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/YomAlArd-300x222.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/YomAlArd-768x569.jpg 768w, https:\/\/cinedetour.it\/wp-content\/uploads\/2024\/04\/YomAlArd.jpg 965w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"font-size: 10pt;\">ITA Film girato nel 1981 e dedicato alla quinta Giornata della Terra, con riprese dei festeggiamenti, la sfilata e il raduno della popolazione a Sakhnin, Deir Hanna, Nazareth e Haifa. Un&#8217;occasione per riaffermare l&#8217;identit\u00e0 del popolo palestinese. \u00c8 documentato soprattutto il discorso del leader, sindaco di Nazareth per ben 5 mandati, e poeta, Tawfik Zayyad.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">ENG Filmed in 16mm between the end of March and the beginning of April 1981 on the 5th Land Day (Yom-al-Ard) in Sakhnin, Deir Hanna, Nazareth and Haifa. This short is a credit to the transversal unity of the people, their collective energy in the defense of the Palestinian identity &#8211; unimaginable today &#8211; and to their charismatic leader, the 5 times Mayor of Nazareth and Poet Tawfik Zayyad.<\/span><\/p>\n<hr>\n<p><strong><span style=\"font-size: 18pt;\">mar 30\/4<\/span> <\/strong><br \/>\n<em>Cristina Tuteri presenta<\/em><\/p>\n<p><strong><span style=\"font-size: 14pt;\">5 Broken Cameras <\/span><\/strong><span style=\"font-size: 14pt;\"><span style=\"font-size: 12pt;\">di Emad Burnat e Guy Davidi <\/span><\/span>(2011, 94&#8242;)<\/p>\n<p><span style=\"font-size: 10pt;\">ITA Un documentario sulla resistenza non violenta di un contadino palestinese alle azioni dell&#8217;esercito israeliano. Emad, che vive nel villaggio palestinese di Bil&#8217;in, acquista la sua prima videocamera quando nasce suo figlio Gibreel e la usa per creare ricordi di famiglia. Quando il governo tenta di costruire una barriera sulle terre degli abitanti del villaggio, Emad filma la resistenza e si trova coinvolto in una tempesta di arresti e incursioni notturne. Una telecamera dopo l&#8217;altra viene colpita durante scontri a fuoco o distrutta nelle colluttazioni con i militari israeliani. E con ogni telecamera si apre un nuovo capitolo della storia di Emad.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\">ENG A documentary on a Palestinian farmer&#8217;s chronicle of his non violent resistance to the actions of the Israeli army. Emad, who lives in the Palestinian village of Bil\u2019in, buys his first camera when his son Gibreel is born, and puts it to use beyond creating family memories. When the government attempts to build a barrier across villagers\u2019 lands, Emad films the resistance and is caught up in a storm of arrests and night raids. One camera after another is shot or smashed. And with each camera, a new chapter of Emad\u2019s story unfolds.<\/span><\/p>\n<hr>\n<\/div>\n<div>\n<div style=\"text-align: justify;\" title=\"Page 1\">\n<div style=\"text-align: center;\">\n<p style=\"text-align: left;\"><strong>presso CIRCOLO DI SAN LORENZO Via dei Latini 73\/75<br \/>\n<span style=\"font-size: 12pt;\">19.30 aperitivo<\/span><span style=\"font-size: x-large;\"> <br \/>\n<\/span><span style=\"font-size: 12pt;\">20.30 incontri e proiezioni<\/span><br \/>\n<\/strong><\/p>\n<p style=\"text-align: left;\"><em>per info solo: <a href=\"mailto:detourcinema@gmail.com\">detourcinema@gmail.com<\/a><\/em><\/p>\n<\/div>\n<div style=\"text-align: center;\">&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bank of targets, terra di obiettivi, sponda di macerie, rovina della memoria e polvere mediatica a coprire.<br \/>\nIl popolo palestinese non ha mai smesso di raccontare la sofferenza sotto l&#8217;occupazione israeliana, in ogni forma possibile. L\u2019autodeterminazione parte dal narrarsi in prima persona, senza filtri occidentali, come atto di resistenza culturale \u00a0alla colonizzazione militare e mentale delle forze di occupazione. Nelle immagini di questi film ragazze e ragazzi, donne e uomini prendono la \u00a0parola per raccontarci le loro storie di umiliazione, terrore, privazione.<\/p>\n","protected":false},"author":2,"featured_media":20588,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376],"tags":[],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 14:33:28","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/20587"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=20587"}],"version-history":[{"count":17,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/20587\/revisions"}],"predecessor-version":[{"id":20608,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/20587\/revisions\/20608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/20588"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=20587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=20587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=20587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}