{"id":3464,"date":"2014-10-13T23:28:06","date_gmt":"2014-10-13T22:28:06","guid":{"rendered":"https:\/\/cinedetour.it\/?p=3464"},"modified":"2014-11-12T13:26:21","modified_gmt":"2014-11-12T12:26:21","slug":"ottobre-2014","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2014\/10\/13\/ottobre-2014\/","title":{"rendered":"Ottobre 2014"},"content":{"rendered":"<p><a href=\"http:\/\/www.cinedetour.it\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"130\" height=\"127\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Cinema | Corsi e Laboratori | Esposizioni | Attivit\u00e0 per Bambini | Cine Bar\u00a0| Musica | Video d&#8217;Arte e Teatro | Produzione | Distribuzione ed editoria indipendente | Web Radio<\/span><\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\">Comunicazione riservata ai soci DETOUR-ARCI &#8211; Il programma pu\u00f2 subire variazioni<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: x-large;\">CINEMA\u00a0&gt; DETOUR &gt;\u00a0OTTOBRE 2014<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/ottobre-2014_cover_small1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3633\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/ottobre-2014_cover_small1.jpg\" alt=\"ottobre-2014_cover_small\" width=\"700\" height=\"315\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Associazione Culturale DETOUR ARCI &#8211; Via Urbana 107 Roma <\/span> <span style=\"font-size: small;\"><a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>\u00a0&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: small;\">Art-house cinema in Downtown Rome since 1997.<br \/>\nAll movies are screened in their original languages with italian or english subtitles<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Ingresso riservato ai soci ARCI Primo ingresso con tessera associativa annuale: 8\u20ac\/9\u20ac<br \/>\nIngresso alle proiezioni successive e alle attivit\u00e0: quota di adesione 5\u20ac\/6\u20ac<br \/>\n<\/span><span style=\"font-size: small;\">Cineclub Detour \u00e8 affiliato ad ARCI-UCCA e alla FICC (Federazione Italiana Circoli Cinema)<br \/>\nPer il tesseramento \u00e8 preferibile arrivare con almeno 15 minuti di anticipo prima dell&#8217;inizio dello spettacolo<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: small;\"> For ARCI members only. Annual membership including first admission: 8\u20ac\/9\u20ac<br \/>\nFollowing admissions to screenings: 5\u20ac\/6\u20ac\u00a0<\/span><span style=\"font-size: small;\">Cineclub Detour is affiliated to ARCI-UCCA and to FICC<br \/>\nPlease kindly arrive 15-20 minutes before the film starts to allow time needed for membership <\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Sostienici<\/a> \/ <em><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Support Us<\/a><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Seguici su \/ <em>Follow us on:<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\" \/><\/a> <a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\" \/><\/a> <a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\" \/><\/a><\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #993300; font-size: 14pt;\"><span class=\"Apple-style-span\">\u00a0<\/span>MERCOLED\u00ec 1 &#8211; DOMENICA 12 OTTOBRE ore 21<\/span><\/p>\n<div>\n<div title=\"Page 1\">\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"color: #515151; font-size: large;\"><span style=\"font-size: xx-large;\">SHORT TERM 12<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di\u00a0Destin Daniel Cretton<\/span><span style=\"font-size: medium;\">\u00a0(Usa 2013, 96\u2019, english version, sottotitolato in italiano)\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><em><span style=\"font-size: medium;\">prima della proiezione piccolo snack per i soci<\/span><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/short_term_12-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3425\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/short_term_12-1.jpg\" alt=\"short_term_12-1\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">&#8220;Grace e Mason lavorano in un centro per ragazzi con problemi familiari, alle prese giorno dopo giorno con tentativi di fuga e complicate situazioni da risolvere. Loro stessi per\u00f2 hanno avuto un\u2019infanzia difficile, e quando lei scopre di essere incinta, arriva il momento di prendere decisioni importanti per le proprie vite&#8221;&#8230;\u00a0<em>&#8220;Short Term 12<\/em>\u00a0\u00e8 un film assolutamente sincero, perfetto nella sua imperfezione da produzione indipendente, arricchito da due splendide interpretazioni (Brie Larson al momento ha gi\u00e0 vinto una decina di premi per il suo ruolo) che riescono a far provare una stupefacente empatia per personaggi complessi e fuori dal comune. Anche il tema dell\u2019affidamento di ragazzi problematici \u00e8 trattato senza superficialit\u00e0 e spesso superando il politicamente corretto (lo stesso regista viene da un\u2019esperienza lavorativa in un centro simile allo\u00a0<em>Short Term 12<\/em>).&#8221; (Alberto Brumana .Il Fatto Quotidiano) Pluripremiato nei festival di mezzo mondo e mai distribuito in Italia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><em>I Am Not a Hipster director Destin Daniel Cretton expands his 2008 short of the same name into a feature film depicting the struggles of a compassionate twentysomething contending with some unexpected life developments while working as a supervisor at a home for at-risk teens. Grace (Brie Larson) has dedicated her life to helping kids who have slipped through the cracks of the system. Committed to her job and in love with kindhearted co-worker Mason (John Gallagher Jr.), she&#8217;s still struggling\u00a0to make sense of her own troubled past when she learns that her life is about to change forever. Meanwhile, into the facility walks a young girl who&#8217;s been constantly shifted between group homes due to dangerous behavior. Almost immediately, Grace forges a powerful connection with her new charge. Now if Grace can just open up to Mason the way she encourages her kids to open up to her, she may find a way to make peace with the future while still providing support to the kids who depend on her the most. \u00a0(Rotten tomatoes)<\/em><\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">GIOVED\u00ec 2 &#8211;\u00a0MARTED\u00ec\u00a07 ore 21.00<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 12pt;\">OUTSIDER ARTISTS &#8211; INEDITO AL DETOUR<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"font-size: large; color: #515151;\"><span style=\"font-size: xx-large;\">IN THE REALMS OF THE UNREAL<br \/>\n<span style=\"font-size: 14pt;\">The Mystery of Henry Darger<\/span><br \/>\n<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di Jessica Ju\u00a0(Usa 2005, 83\u2019, english version, sottotitolato in italiano)\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: medium; color: #993300;\">prima delle proiezioni\u00a0snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/in_the_realms.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3482\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/in_the_realms.jpg\" alt=\"in_the_realms\" width=\"350\" height=\"511\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Chi ha conosciuto la\u00a0vicenda della fotografa Vivian Maier, non potr\u00e0 fare a meno di notare sorprendenti analogie con\u00a0la materia narrativa di <em>In the\u00a0Realms of the Unreal<\/em> (realizzato qualche hanno prima di quello sulla Maier)\u00a0in cui si racconta la storia vera di Henry Darger &#8211; solitario\u00a0custode d&#8217;ospedale\u00a0di Chicago -rivelazione postuma di\u00a0un eccentrico\u00a0genio\u00a0artistico, nascosto al mondo per una vita intera. Alla sua morte, nel 1972, il suo padrone di casa fece una scoperta sorprendente: un colossale e oscuro\u00a0manoscritto\u00a0fantasy composto di 15.143 pagine, corredato\u00a0da\u00a0pi\u00f9 di 300 illustrazioni strane e affascinanti, tra collage, disegni e dipinti ad acquarello. Piuttosto che intervistare esperti d&#8217;arte e psicologi, e in mancanza di altri materiali visivi d&#8217;archivio disponibili su Darger\u00a0(del quale\u00a0esistono solo quattro fotografie note), la regista sceglie di osservare\u00a0la sua opera\u00a0dal punto di vista di coloro che lo hanno conosciuto e di raccontare il mondo epico e allucinato\u00a0del suo romanzo\u00a0attraverso alcune\u00a0sequenze in animazione, realizzate a partire dai disegni originali del suo autore.<\/span><\/p>\n<p style=\"text-align: justify;\"><span id=\"movieSynopsisRemaining\" style=\"font-size: 10pt;\"><em>An obscure janitor during his life, Darger is known for the posthumous discovery of his elaborate 15,143-page fantasy manuscript entitled The Story of the Vivian Girls, in What is Known as the Realms of the Unreal, of the Glandeco-Angelinnian War Storm, Caused by the Child Slave Rebellion, along with several hundred watercolor paintings and other drawings illustrating the story. Because of his reclusive lifestyle (there are only four known photographs of Darger) and rather than interview art scholars and psychologists, the director chooses to look at Darger&#8217;s work from the viewpoints of those who knew him. She also incorporates animation segments into the documentary, using Darger&#8217;s original images. <\/em>\u00a0<\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><span class=\"Apple-style-span\" style=\"color: #993300;\">VENERD\u00ec 3\u00a0ore 21.00<\/span><\/span><\/p>\n<\/div>\n<p align=\"center\"><span style=\"color: #515151;\"><strong><span style=\"font-size: large;\">Susurros y \u00e9xtasis &#8211;\u00a0il cinema di VICTOR ERICE<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/victor_erice_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3403\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/victor_erice_1.jpg\" alt=\"victor_erice_1\" width=\"240\" height=\"158\" \/><\/a><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: 24pt; color: #515151;\">IL SOLE DELLA MELA COTOGNA<\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: x-large; color: #515151;\">(El sol del membrillo)<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"font-size: 12pt; color: #515151;\">di Victor Erice (Spagna, 1983, 130&#8242;, original spanish version, sottotitoli in italiano)<\/span><br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 12pt; color: #993300;\">Prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/El_sol_del_membrillo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3487\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/El_sol_del_membrillo.jpg\" alt=\"El_sol_del_membrillo\" width=\"349\" height=\"211\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Terzo lungometraggio di V\u00edctor Erice, presentato al Festival di Cannes dove ottenne il Premio Speciale della Giuria e segnalato successivamente tra i migliori film del decennio, El sol del membrillo si interroga sulla natura del processo artistico e creativo, documentando gli sforzi del celebre pittore figurativo spagnolo Antonio L\u00f3pez Garc\u00eda \u00a0di dipingere il fogliame del suo cortile, cercando di cogliere le minime sfumature\u00a0della luce che filtra attraverso le\u00a0fronde degli alberi. L&#8217;artista\u00a0spera di completare il quadro prima che i frutti cadano alla fine della stagione. Nel mentre, viene distratto da visite inattese, dall&#8217;attualit\u00e0 del dibattito sulla guerra del Golfo, e dalla presenza del regista e della cinepresa. Il film inizia in forma documentaria, accompagnandosi dal voiceover dello stesso Lopez, per poi lentamente trasformarsi in\u00a0una\u00a0messa in scena appena abbozzata.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Ipnotico, dalla natura onirica, <em>\u00a0<\/em>Il film di Erice<em>\u00a0<\/em>\u00e8 cinema di finzione, pur non adottando\u00a0le abituali strutture drammatico-narrative: trasforma in spettacolo l&#8217;intimo processo creativo di un pittore, e si limita a registrarlo con apparente neutralit\u00e0; un cinema in nessun modo estraneo alla realt\u00e0, anzi a essa saldamente ancorato \u2012 anche se per addentrarvisi e trascenderla, senza limitarsi alla sua mera apparenza \u2012 e nello stesso tempo libero e imprevedibile, lontano da convenzioni e percorsi prestabiliti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><em>A film about the artistic process in every sense of the phrase, Spanish director Victor Erice&#8217;s El Sol del Mebrillo (The Quince Tree Sun) loosely documents the efforts of artist Antonio Lopez to paint the titular foliage in his backyard. Lopez agonizes over just how to capture the light falling on the tree&#8217;s leaves; he aspires to complete the painting before the fruit falls at the end of the season. Meanwhile, the artist is distracted by unannounced visitors, the debate over the Gulf War, and <span id=\"movieSynopsisRemaining\">the filmmaker himself. Sol begins in documentary form, with voiceover narration from Lopez himself, then slowly takes on other qualities: slightly staged narrative storytelling; hypnotic, dream-like nature film; and philosophical meditation on art and mortality. <\/span><\/em><\/span><\/p>\n<hr \/>\n<\/div>\n<p align=\"center\"><span style=\"color: #993300; font-size: 14pt;\">SABATO 4 ore 19.00 ore 21.00<\/span><\/p>\n<p align=\"center\"><span style=\"color: #993300; font-size: 14pt;\">DOMENICA 5 ore 19:00 e ore\u00a021.00<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><em><span style=\"font-size: 12pt;\">OUTSIDER ARTISTS &#8211;\u00a0IN COLLABORAZIONE CON FELTRINELLI REAL CINEMA<\/span><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">ALLA RICERCA DI VIVIAN MAIER<br \/>\n<span style=\"font-size: large;\">(<em>Finding Vivian Maier<\/em>)<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di John Maloof, Charlie Siskel. (Usa 2013, 84\u2019, orig vers sottotit. in italiano)\u00a0<\/span><\/p>\n<p><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/05\/vivian-maier_detour.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2946\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/05\/vivian-maier_detour.jpg\" alt=\"vivian-maier_detour\" width=\"350\" height=\"260\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Alla ricerca di Vivian Maier Nel 2007, in procinto di scrivere un libro sulla storia del suo quartiere di Chicago, John Maloof acquista all&#8217;asta una scatola piena di negativi non ancora sviluppati, sperando di trovare del materiale utile al suo scopo. Invece, trova una delle pi\u00f9 straordinarie collezioni fotografiche del XX secolo. Andando, qualche anno dopo, alla ricerca dell&#8217;identit\u00e0 del fotografo, una donna di nome Vivian Maier scomparsa nel 2009, Maloof scopre una storia da romanzo: quella di una figura dall&#8217;immenso talento artistico, che ha preferito per tutta la vita mantenere il segreto sulla sua attivit\u00e0 fotografica, facendo la tata per i bambini delle famiglie bene di Chicago. Ma il vero tesoro trovato da John Maloof \u00e8 un altro, un mistero. Un nucleo di interrogativi resistenti a qualsiasi certezza, che rester\u00e0 per sempre legato al nome e all&#8217;opera di Vivian Maier e perpetuer\u00e0 la storia e il suo fascino negli anni a venire. Un film che sta diventato un caso della distribuzione indipendente, grazie al successo scaturito dal passaparola tra gli spettatori.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #575757; font-size: 10pt;\"><em>Who is Vivian Maier? Now considered one of the 20th century&#8217;s greatest street photographers, Vivian Maier was a mysterious nanny who secretly took over 100,000 photographs that went unseen during her lifetime. Since buying her work by chance at auction, amateur historian John Maloof has crusaded to put this prolific photographer in the history books. Maier&#8217;s strange and riveting life and art are revealed through never-before-seen photographs, films, and interviews with dozens who thought they\u00a0knew her.\u00a0<\/em><\/span><\/p>\n<div title=\"Page 1\">\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">MARTED\u00ec\u00a07 ore 21.00<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 12pt;\">OUTSIDER ARTISTS &#8211; INEDITO AL DETOUR<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"font-size: large; color: #515151;\"><span style=\"font-size: xx-large;\">IN THE REALMS OF THE UNREAL<br \/>\n<span style=\"font-size: 14pt;\">The Mystery of Henry Darger<\/span><br \/>\n<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di Jessica Ju\u00a0(Usa 2005, 83\u2019, english version, sottotitolato in italiano)\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: medium; color: #993300;\">prima delle proiezioni\u00a0snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">&lt;&lt; VEDI SCHEDA GIOVED\u00ec 3 &gt;&gt;<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/in_the_realms.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3482\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/in_the_realms.jpg\" alt=\"in_the_realms\" width=\"350\" height=\"511\" \/><\/a><\/p>\n<hr \/>\n<p style=\"text-align: center;\">\u00a0\u00a0<span style=\"font-size: large; color: #993300;\">MERCOLED\u00ec 8<\/span><span class=\"Apple-style-span\" style=\"color: #993300; font-size: large;\">\u00a0<\/span><span class=\"Apple-style-span\" style=\"color: #993300; font-size: large;\">ore 21.00<\/span><\/p>\n<div title=\"Page 1\">\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"color: #515151; font-size: large;\"><span style=\"font-size: xx-large;\">IRIRIA &#8211; Ni\u00f1a\u00a0Tierra<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di\u00a0Carmelo Camilli<\/span><span style=\"font-size: medium;\">\u00a0(Italia 2013, 72\u2019, spanish\u00a0version,\u00a0sottotitolato in italiano)\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><em><span style=\"font-size: 12pt;\">\u00a0A seguire incontro con il regista Carmelo Camilli &#8211; prima della proiezione\u00a0snack gratuito\u00a0per i soci<\/span><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/iriria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3474\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/iriria.jpg\" alt=\"iriria\" width=\"350\" height=\"510\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><em>\u201cIRIRIA \u00e8 una bambina grassa dalla cui carne il dio SIB\u00d6 decise di creare la terra, dopodich\u00e9 seminare e creare la vita\u2026\u201d<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #993300;\"><strong>TRAILER: http:\/\/www.youtube.com\/watch?v=Xrwotp36EKQ<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Comincia cosi il racconto di IRIRIA \u2013 NI\u00d1A TIERRA che, dal ritratto della comunit\u00e0 BRIBRI-CABECAR della riserva indigena di Alta Talamanca in Costa Rica, fonde cosmovisione e attualit\u00e0, giornalismo e antropologia, documentario e cinema. Le voci degli innumerevoli personaggi, dall\u2019AW\u00c1 (sciamano curatore) agli anziani saggi, dal Professore di Cultura BRIBRI della scuola di COROMA al governo locale ADITIBRI, ci raccontano di una terra viva che sente e vede grazie agli spiriti della foresta, del mare, dell\u2019uragano e degli animali. Un viaggio che attraversa difesa della terra, spiritualit\u00e0 ancestrale, comportamento umano, rottura degli equilibri e interpretazione e lettura dei disastri naturali, dal locale all\u2019universale. Dall\u2019analisi del rapporto uomo-terra, ormai non pi\u00f9 sostenibile, si delinea una visione di un futuro in cui un cambiamento, culturale ancor prima che tecnologico, sar\u00e0 imposto dalla forza di IRIRA se l\u2019uomo non sar\u00e0 capace di cambiare in tempo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\"><em><span style=\"font-size: 10pt;\">IRIRIA, NINA TIERRA, is a documentary that, through Cosmovision of the indigenous community of Bribri-Cabecar in the natural reserve of Alta Talamanca in Costa Rica, reflects on the difficult relationship between man and the earth. An analysis, from the local to the universal, of the &#8216;Cultural&#8217; root which is the basis of the environmental problems in this era the planet is facing<\/span>.<\/em><\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"color: #993300; font-size: large;\">GIOVED\u00ec 9\u00a0<\/span><span class=\"Apple-style-span\" style=\"color: #993300; font-size: large;\">ore 21.00<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #993300; font-size: 12pt;\">dal vincitore della Mostra del Cinema di Venezia 2014\u00a0<\/span><\/strong><\/p>\n<div title=\"Page 1\">\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"color: #515151; font-size: large;\"><span style=\"font-size: xx-large;\">SONGS FROM THE SECOND FLOOR<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di\u00a0Roy Andersson<\/span><span style=\"font-size: medium;\">\u00a0(Svezia 2000, 82\u2019, original\u00a0version, sottotitolato in italiano)\u00a0<\/span><\/p>\n<p align=\"center\"><span style=\"color: #993300; font-size: medium;\">prima delle proiezioni snack gratuito\u00a0per i soci<\/span><\/p>\n<p align=\"center\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/songs1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3478\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/songs1.jpg\" alt=\"songs1\" width=\"350\" height=\"209\" \/><\/a><\/p>\n<p style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 10pt;\">Un film poema ispirato al poeta Caesar Vallejo, primo di una trilogia che mescola la commedia con il fantastico e con toni grotteschi (con l&#8217;ultimo capitolo,\u00a0<em>Un piccione seduto su un ramo riflette sull\u2019esistenz<\/em>a, lo svedese Andersson vince il Leone d&#8217;Oro alla Mostra del Cinema di Venezia 2014). \u00a0Una storia sul nostro bisogno d\u2019amore, la nostra confusione, grandezza e piccolezza , ma soprattutto, la nostra vulnerabilit\u00e0.\u00a0Strani eventi in una citt\u00e0: macchine imbottigliate in un traffico infernale, un imprenditore che d\u00e0 fuoco alla sua ditta, funzionari pallidi come cenci, case che si muovono, fantasmi che tornano alla vita, e una bambina sacrificata per il bene della popolazione. Curiosissima visione, opera per certi tratti apocalittica che suggerisce attraverso la sua declinazione sarcastica della realt\u00e0 un percettibile stato di malsana inquietudine.<\/span><\/p>\n<p style=\"text-align: justify;\" align=\"center\"><span style=\"font-size: 10pt;\"><em>From the winner of the 2014 Venice Film Festival, Roy Andersson.\u00a0Songs From the Second Floor, which shared the Special Jury Prize at the 2000 Cannes Film Festival, is an indescribably surrealistic examination of the pointlessness of modern life in a nameless city full of directionless people. Throughout a series of unrelated vignettes, all marked by absurd black humor, the film&#8217;s characters stand witness to an utterly motionless traffic jam, the pathetic firing of a 30-year employee, a magic trick gone horribly wrong, and the failed business ventures of a crucifix salesman. Dialogue is largely absent from the film, and even where present, it usually only confounds what little expository quality there is in the narrative. The tone of Swedish director Roy Anderssen&#8217;s highly original and challenging project recalls such bleak visionaries as Samuel Beckett and Luis Bu\u00f1uel, and though it certainly perplexed audiences, it also left them laughing uncontrollably. (Rotten Tomatoes)<\/em><\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"color: #993300; font-size: medium;\"><span class=\"Apple-style-span\" style=\"font-size: large;\">VENERD\u00ec 10 ore 21.00 LIVE @ DETOUR<\/span><\/span><\/p>\n<\/div>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: xx-large; color: #515151;\">GRONGE Rocket to Rome\u00a0<\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: 14pt; color: #515151;\">AUTOPSIA DI UN FILM di Marcho Gronge<\/span><\/p>\n<p class=\"p1\" style=\"text-align: center;\">un live impro-radical eseguito da GRONGE-X il gruppo mutante di roma oramai\u00a0 attivo sulle scene dal 1985 e condotti sin qui nelle f ascinose mura del DETOUR uno dei cineclub pi\u00f9 attivi nella capitale dal capitano ACHABEDINI al secolo marcho gronge. La band poggia attualmente sulle spalle larghe di mau suonomono bozzao\u00a0 che miscela elettroniche e campionamenti di giacomo ancillotto\u00a0 raffinato chitarrista onnivoro e di federico leo polibatterista dislocato in almeno una\u00a0decina di realt\u00e0 oltre la realt\u00e0.<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">dissecting<\/span> <span style=\"font-size: 24pt;\">LA GRANDE\u00a0BOUFFE<\/span> \u00a0<span style=\"font-size: 12pt;\">di Marco Ferreri (1973)<\/span><\/span><\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #515151;\">grazie alla elaborazione visiva della\u00a0DETOUR FACTORY\u00a0<\/span>che, sottoposto il film ad un attento esame autoptico ne hanno estratto un corpo nuovo e lo hanno offerto in pasto gli improvvisatori radicali GRONGE-X che dopo una attenta ricucitura musicale e un lavoro di destrutturazione\u00a0testuale effettuato partendo dalla sceneggiatura originale ne restituiscono al pubblico brandelli di materia pulsante e disomogenea \u00a0fino a condurre gli spettatori li dove forse lo stesso MARCO FERRERI non era riuscito ad arrivare.<\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 12pt; color: #993300;\">Ingresso a sottoscrizione per i soci ARCI &#8211; prima della proiezione\/esibizione snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-3520 alignnone\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/gronge_detour.jpg\" alt=\"gronge_detour\" width=\"350\" height=\"580\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/gronge_detour.jpg 350w, https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/gronge_detour-181x300.jpg 181w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"font-size: 10pt;\">GRONGE: gruppo musicale\u00a0romano nato nel 1985.\u00a0Il loro genere \u00e8 definito come &#8220;technopunkcabaret&#8221;, le loro esibizioni fondono musica e teatro. Tra i primi in Italia ad inserire campionamenti, sono stati fonte di ispirazione per importanti gruppi italiani contemporanei.\u00a0<\/span><span style=\"font-size: 10pt;\">Capostipite dell\u2019autoproduzione in Italia, GRONGE esporta per la prima volta il nome di una band sconosciuta ovunque (dalla Sicilia a Berlino), utilizzando esclusivamente i propri mezzi (economicamente inesistenti), cabine telefoniche e ciclostile.\u00a0<\/span><span style=\"font-size: 10pt;\">GRONGE partorisce cos\u00ec nell\u2019arco di una decina d\u2019anni centinaia di esibizioni live producendo 6 vinili e un cd che finiva per diventare capostipite di un vero e proprio genere art-noise-punk-electro-rock che unitamente ad una vena teatral grottesca ispirava svariati gruppi che nella seconda met\u00e0 degli 80 e nei primi 90 si andavano formando in ogni remota provincia dell\u2019impero.<\/span><\/em><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/GRANDE-ABBUFFATA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3494\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/GRANDE-ABBUFFATA.jpg\" alt=\"GRANDE-ABBUFFATA\" width=\"350\" height=\"143\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><em>LA GRANDE BOUFFE: Quattro amici, un giudice (Noiret), un pilota di linea (Mastroianni), un ristoratore (Tognazzi), un produttore TV (Piccoli), si riuniscono in una villa di Neuilly, fuori Parigi, decisi a compiere un quadruplice harakiri gastronomico-erotico. Li accompagna, pingue angelo della morte, un&#8217;insaziabile e materna maestra (Ferr\u00e9ol). Scritto con Rafael Azcona, \u00e8 probabilmente il pi\u00f9 grande successo internazionale (di scandalo) nell&#8217;itinerario di Ferreri. La sua forza traumatica risiede nella calma lucidit\u00e0 dello sguardo, e nell&#8217;onest\u00e0 di un linguaggio che Ferreri conserva anche e soprattutto quando non arretra davanti a nulla.<\/em><\/p>\n<hr \/>\n<div style=\"text-align: justify;\">\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">SABATO 11 LIVE @ DETOUR<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 12pt; color: #993300;\"><em><span style=\"font-size: 12pt; color: #993300;\">Ingresso a sottoscrizione per i soci ARCI &#8211; snack gratuito dalle ore 20.00<\/span><\/em><\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt; color: #515151;\"><span style=\"font-size: 12pt; color: #993300;\">\u00a0ore 20.30<\/span> COLD FACTS<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\"><strong>Parislamour+Blasco &#8211;\u00a0<\/strong><em>folk, voices rec. &amp; poesia<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt; text-align: justify;\"> <a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/PARISLAMOUR.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3506\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/PARISLAMOUR.jpg\" alt=\"PARISLAMOUR\" width=\"350\" height=\"251\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/PARISLAMOUR.jpg 350w, https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/PARISLAMOUR-300x215.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/PARISLAMOUR-222x160.jpg 222w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/a><\/span><\/p>\n<p><span style=\"font-size: 10pt; text-align: justify;\">Animate da spirito folk e attitudine punk ecco la sonorizzazione del secondo atto della Trilogia: un diario amoroso in versi irriverenti, battute pungenti e affondi dolorosi che si accartocciano su se stessi e offrono tocchi di disarmante semplicit\u00e0. Un teatro canzone analogico-digitale, una colonna sonora costituita da scorie di brani elettronici, panorami folktronici, registrazioni domestiche su cui, come un flusso di pensieri, scorre la narrazione di racconti brevissimi, canzoncine e poesie associati ai suoni prodotti dalle chitarre o dall\u2019apparato tecnologico che recitano gli stati d\u2019animo mentre le parole giocano tra rimandi di senso e ritmo. Ballate dolenti e passionali, moltiplicazioni di suoni e tracce che offrono un ascolto e una visone multilivello di un\u2019esistenza che viaggia tra sogni e desideri infranti. Di e con Parislamour (Enea Tomei) e Blasco Morozzo.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\">\u00a0&#8212;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt; color: #515151;\"><span style=\"font-size: 12pt; color: #993300;\">\u00a0ore 21.30<\/span>\u00a0100% P.H.A.K.E. <span style=\"font-size: 10pt;\">(Folk rock blues Italia)<\/span><br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/PHAKE.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3497\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/PHAKE.jpg\" alt=\"PHAKE\" width=\"350\" height=\"244\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Un progetto acustico, dal carattere folk rock&amp;blues, che prosegue nel solco dell\u2019eredit\u00e0 dei Superfetazione. Presenta brani originali, ballate dolenti e passionali in cui vive lo spirito rock e un\u2019attitudine punk. Omaggi alla tradizione irlandese, al blues del delta e all\u2019indie folk rock nelle cover selezionate e ripercorse in forme innovative dalla band.<br \/>\nUna carica di energia live rinforzata dalla verve empatica del cantante Blasco Morozzo e dalle sferzate poetiche surreali di Enea Tomei, un concerto sperimentale di contaminazione tra musica e narrativa post contemporanea. Innesti ritmico narrativi concisi ed emozionali, pulsazioni di racconti brevissimi e squarci di panorami umani nu-folk, celeri come una coltellata in petto.<br \/>\nBlasco Morozzo Voce\/Chitarra Segio Ponzio Chitarra elettrica Andrea Naglieri Cajon Fabio Gatti Basso Andrea Benini Tromba Sara Pollice Voce, Tamburello EneaTomei Paesaggi poetici<\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">\u00a0DOMENICA 12 ore 21.00<\/span><\/p>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"color: #515151; font-size: large;\"><span style=\"font-size: xx-large;\">SHORT TERM 12<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: medium;\">di\u00a0Destin Daniel Cretton<\/span><span style=\"font-size: medium;\">\u00a0(Usa 2013, 96\u2019, english version, sottotitolato in italiano)\u00a0<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><em><span style=\"font-size: medium;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/short_term_12-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3425\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/short_term_12-1.jpg\" alt=\"short_term_12-1\" width=\"500\" height=\"375\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">&#8220;Grace e Mason lavorano in un centro per ragazzi con problemi familiari, alle prese giorno dopo giorno con tentativi di fuga e complicate situazioni da risolvere. Loro stessi per\u00f2 hanno avuto un\u2019infanzia difficile, e quando lei scopre di essere incinta, arriva il momento di prendere decisioni importanti per le proprie vite&#8221;&#8230;\u00a0<em>&#8220;Short Term 12<\/em>\u00a0\u00e8 un film assolutamente sincero, perfetto nella sua imperfezione da produzione indipendente, arricchito da due splendide interpretazioni (Brie Larson al momento ha gi\u00e0 vinto una decina di premi per il suo ruolo) che riescono a far provare una stupefacente empatia per personaggi complessi e fuori dal comune. Anche il tema dell\u2019affidamento di ragazzi problematici \u00e8 trattato senza superficialit\u00e0 e spesso superando il politicamente corretto (lo stesso regista viene da un\u2019esperienza lavorativa in un centro simile allo\u00a0<em>Short Term 12<\/em>).&#8221; (Alberto Brumana .Il Fatto Quotidiano) Pluripremiato nei festival di mezzo mondo e mai distribuito in Italia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><em>I Am Not a Hipster director Destin Daniel Cretton expands his 2008 short of the same name into a feature film depicting the struggles of a compassionate twentysomething contending with some unexpected life developments while working as a supervisor at a home for at-risk teens. Grace (Brie Larson) has dedicated her life to helping kids who have slipped through the cracks of the system. Committed to her job and in love with kindhearted co-worker Mason (John Gallagher Jr.), she&#8217;s still struggling\u00a0to make sense of her own troubled past when she learns that her life is about to change forever. Meanwhile, into the facility walks a young girl who&#8217;s been constantly shifted between group homes due to dangerous behavior. Almost immediately, Grace forges a powerful connection with her new charge. Now if Grace can just open up to Mason the way she encourages her kids to open up to her, she may find a way to make peace with the future while still providing support to the kids who depend on her the most. \u00a0(Rotten tomatoes)<\/em><\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"color: #993300; font-size: large;\">MARTED\u00ec 14 ore 20.45<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large;\">INCONTRI DI CINEMA\u00a0<span style=\"font-size: 24pt;\">#100<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">serata con <span class=\"Apple-style-span\">presentazione e\u00a0proiezione di film a cura di<\/span>\u00a0<strong><span style=\"font-size: large;\">ViSiOnI<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"><em>&#8220;E&#8217; buffo come i colori del mondo divengano veri soltanto quando uno li vede sullo schermo&#8221;\u00a0<\/em>(Alex in Arancia Meccanica, S. Kubrick, 1971)<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/12\/detour-ulmer1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1621\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/12\/detour-ulmer1.jpg\" alt=\"detour-ulmer1\" width=\"350\" height=\"263\" \/><\/a><\/p>\n<p><span style=\"font-size: 10pt;\">Questo di ottobre sar\u00e0 un\u00a0appuntamento molto speciale. Festeggeremo <strong>la visione n\u00b0 100<\/strong> e dopo il film ci fermeremo tutti al cineclub per brindare insieme e gustare qualcosa di buono.\u00a0Otto anni fa circa prendeva il via la nostra \u201cavventura\u201d e, poich\u00e9 il cineclub \u00e8 stata la sede che ci ha accolto con grande affetto e simpatia, sar\u00e0 proiettato il film \u201c<strong>Detour<\/strong>\u201d di Edgar G. Ulmer (Usa 1946). Un classico noir degli anni cinquanta e allo stesso tempo un omaggio alla nostra sede naturale delle visioni.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">Per il programma dettagliato e informazioni:\u00a0<a style=\"color: #515151;\" href=\"http:\/\/forumcinema.blog.tiscali.it\/\">http:\/\/forumcinema.blog.tiscali.it<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">Per partecipare agli incontri \u00e8 preferibile prenotarsi scrivendo a\u00a0<a style=\"color: #515151;\" href=\"mailto:visioni@gmelies.it\">visioni@gmelies.it<\/a><\/span><\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span class=\"s1\" style=\"font-size: 12pt; color: #515151;\">leggi\u00a0<a style=\"color: #515151;\" href=\"http:\/\/digilander.libero.it\/sergio.nota\/Scheda%20Presentazione.pdf\"><span class=\"s2\">Cos\u2019\u00e8 Visioni<\/span><\/a><\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">MERCOLED\u00ec 15\u00a0ore 21.00<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt; color: #515151;\">DOCUMENTARIO INEDITO DEL MESE\u00a0&#8211;\u00a0OUTSIDER ARTISTS<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"font-size: large; color: #515151;\"><span style=\"font-size: xx-large;\"><span style=\"color: #515151;\">IN THE REALMS OF THE UNREAL<\/span><br \/>\n<span style=\"font-size: 14pt;\">The Mystery of Henry Darger<\/span><br \/>\n<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di Jessica Ju\u00a0(Usa 2005, 83\u2019, english version, sottotitolato in italiano)\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: medium; color: #993300;\">prima delle proiezioni\u00a0snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/in_the_realms.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3482\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/in_the_realms.jpg\" alt=\"in_the_realms\" width=\"350\" height=\"511\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Chi ha conosciuto la\u00a0vicenda della fotografa Vivian Maier, non potr\u00e0 fare a meno di notare sorprendenti analogie con\u00a0la materia narrativa di <em>In the\u00a0Realms of the Unreal<\/em> (realizzato qualche hanno prima di quello sulla Maier)\u00a0in cui si racconta la storia vera di Henry Darger &#8211; solitario\u00a0custode d&#8217;ospedale\u00a0di Chicago -rivelazione postuma di\u00a0un eccentrico\u00a0genio\u00a0artistico, nascosto al mondo per una vita intera. Alla sua morte, nel 1972, il suo padrone di casa fece una scoperta sorprendente: un colossale e oscuro\u00a0manoscritto\u00a0fantasy composto di 15.143 pagine, corredato\u00a0da\u00a0pi\u00f9 di 300 illustrazioni strane e affascinanti, tra collage, disegni e dipinti ad acquarello. Piuttosto che intervistare esperti d&#8217;arte e psicologi, e in mancanza di altri materiali visivi d&#8217;archivio disponibili su Darger\u00a0(del quale\u00a0esistono solo quattro fotografie note), la regista sceglie di osservare\u00a0la sua opera\u00a0dal punto di vista di coloro che lo hanno conosciuto e di raccontare il mondo epico e allucinato\u00a0del suo romanzo\u00a0attraverso alcune\u00a0sequenze in animazione, realizzate a partire dai disegni originali del suo autore.<\/span><\/p>\n<p style=\"text-align: justify;\"><span id=\"movieSynopsisRemaining\" style=\"font-size: 10pt;\"><em>An obscure janitor during his life, Darger is known for the posthumous discovery of his elaborate 15,143-page fantasy manuscript entitled The Story of the Vivian Girls, in What is Known as the Realms of the Unreal, of the Glandeco-Angelinnian War Storm, Caused by the Child Slave Rebellion, along with several hundred watercolor paintings and other drawings illustrating the story. Because of his reclusive lifestyle (there are only four known photographs of Darger) and rather than interview art scholars and psychologists, the director chooses to look at Darger&#8217;s work from the viewpoints of those who knew him. She also incorporates animation segments into the documentary, using Darger&#8217;s original images. <\/em>\u00a0<\/span><\/p>\n<div>\n<div title=\"Page 1\">\n<hr \/>\n<div>\n<div title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">GIOVED\u00ec 16\u00a0ore 21<\/span><\/p>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"color: #515151; font-size: large;\"><span style=\"font-size: xx-large;\"><strong><span style=\"font-size: 18pt;\">Charles Bukowski al cinema<\/span><\/strong><br \/>\n<span style=\"font-size: 12pt;\">in collaborazione con Giuseppe Montagnese<\/span><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt; color: #515151;\">CRAZY LOVE<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: medium;\">di\u00a0Dominique Deruddere<\/span><span style=\"font-size: medium;\">\u00a0(Belgium\u00a01987, 96\u2019, english version, sottotitolato in italiano)\u00a0<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #993300;\"><em><span style=\"font-size: medium;\">prima della proiezione piccolo snack per i soci<\/span><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/crazy_love_bukowski_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3516\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/crazy_love_bukowski_2.jpg\" alt=\"crazy_love_bukowski_2\" width=\"350\" height=\"253\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Dall&#8217;opera di\u00a0\u00a0Bukowski Le sirene di Venezia, California. Ingiustamente caduta nell&#8217;oblio, ritenuta dallo stesso\u00a0Charles Bukowski l&#8217;unica trasposizione cinematografica\u00a0che avesse saputo cogliere il senso del suo\u00a0universo narrativo, \u00e8\u00a0la storia di un uomo attraverso tre momenti che costituiscono altrettante svolte sessuali: l&#8217;arrivo della pubert\u00e0, la fine dell&#8217;adolescenza, la crisi dell&#8217;et\u00e0 matura.<br \/>\nTre torride notti bukowskiane nella vita di un uomo alla ricerca dell&#8217;amore. Harry Voss, \u00e8 un dodicenne idealista. L&#8217;amore \u00e8 per lui \u00e8 un bacio appassionato tra un principe e una principessa. Suo padre \u00e8 un eroe che ha rapito sua madre e l&#8217;ha sposata sul picco di una montagna solitaria. Anche lui. pi\u00f9 tardi, far\u00e0 lo stesso&#8230; Ma Harry ha molto da imparare: che ci sono uomini affascinanti e altri\u00a0disgustosi, che l&#8217;amore pu\u00f2 essere ingiusto; che si pu\u00f2 trovare conforto nell&#8217;alcol&#8230; ma soprattutto impara che le persone\u00a0sono capaci di tutto, ma proprio di tutto per conquistare la loro giusta fetta d&#8217;amore.\u00a0\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><em>Three &#8216;Bukowskian&#8217; torrid nights in the life of a man in search of love. Harry Voss, 12, is young and naive. Love, for him, is romantic love between princes and princesses demurely kissing each other on the mouth. His father is a hero who kidnapped his mother and married her on a lonely mountain peak&#8230; Later on, he&#8217;ll do the same. But Harry has a lot to learn. He also learns that there are handsome men and ugly ones, that love can be unfair. That one can find comfort in drinking&#8230; but above all he learns that man is capable of anything &#8211; absolutely anything! &#8211; to get his fair share of love<\/em><\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">VENERD\u00ec 17 ore 21<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">OUTSIDER ARTISTS &#8211;\u00a0IN COLLABORAZIONE CON FELTRINELLI REAL CINEMA<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">ALLA RICERCA DI VIVIAN MAIER<br \/>\n<span style=\"font-size: large;\">(<em>Finding Vivian Maier<\/em>)<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di John Maloof, Charlie Siskel. (Usa 2013, 84\u2019, orig vers sottotit. in italiano)\u00a0<\/span><\/p>\n<p><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/05\/vivian-maier_detour.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2946\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/05\/vivian-maier_detour.jpg\" alt=\"vivian-maier_detour\" width=\"350\" height=\"260\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Alla ricerca di Vivian Maier Nel 2007, in procinto di scrivere un libro sulla storia del suo quartiere di Chicago, John Maloof acquista all&#8217;asta una scatola piena di negativi non ancora sviluppati, sperando di trovare del materiale utile al suo scopo. Invece, trova una delle pi\u00f9 straordinarie collezioni fotografiche del XX secolo. Andando, qualche anno dopo, alla ricerca dell&#8217;identit\u00e0 del fotografo, una donna di nome Vivian Maier scomparsa nel 2009, Maloof scopre una storia da romanzo: quella di una figura dall&#8217;immenso talento artistico, che ha preferito per tutta la vita mantenere il segreto sulla sua attivit\u00e0 fotografica, facendo la tata per i bambini delle famiglie bene di Chicago. Ma il vero tesoro trovato da John Maloof \u00e8 un altro, un mistero. Un nucleo di interrogativi resistenti a qualsiasi certezza, che rester\u00e0 per sempre legato al nome e all&#8217;opera di Vivian Maier e perpetuer\u00e0 la storia e il suo fascino negli anni a venire. Un film che sta diventato un caso della distribuzione indipendente, grazie al successo scaturito dal passaparola tra gli spettatori.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #575757; font-size: 10pt;\"><em>Who is Vivian Maier? Now considered one of the 20th century&#8217;s greatest street photographers, Vivian Maier was a mysterious nanny who secretly took over 100,000 photographs that went unseen during her lifetime. Since buying her work by chance at auction, amateur historian John Maloof has crusaded to put this prolific photographer in the history books. Maier&#8217;s strange and riveting life and art are revealed through never-before-seen photographs, films, and interviews with dozens who thought they\u00a0knew her.\u00a0<\/em><\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt; color: #993300;\">SABATO\u00a018 ore 21 &#8211; MARTED\u00ec 21 ore 21 &#8211; GIOVED\u00ec 23 ore 21<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">PRIME VISIONI &#8211; IN COLLABORAZIONE CON MAREMOSSO\u00a0E SCHERMAGLIE.IT<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">SE CHIUDO GLI OCCHI NON SONO PI\u00d9 QUI<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di Vittorio Moroni\u00a0(Italia\u00a02014, 105\u2019, versione italiana, english subtitles)<br \/>\nCon Giorgio Colangeli, Beppe Fiorello, Mark Manaloto, Hazel Morillo, Vladimir Doda<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #993300;\">\u00a0INCONTRO IN SALA CON IL REGISTA VITTORIO MORONI\u00a0e L&#8217;ATTRICE ANITA KRAVOS<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/Locandina_Sechiudo_low.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3603\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/Locandina_Sechiudo_low.jpg\" alt=\"Locandina_Sechiudo_low\" width=\"450\" height=\"630\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Sedicenne con una forte passione per l&#8217;astronomia, trasmessagli dal padre, morto in un incidente stradale, Kiko vive con la madre filippina, Marilou, e il suo nuovo compagno, Ennio, un caporale che gestisce cantieri edili, sfruttando manodopera clandestina. A scuola rischia di essere bocciato per il secondo anno consecutivo e il rapporto con il patrigno, che lo forza a lavorare come manovale, \u00e8 quantomai teso anche per via dei suoi modi violenti. Un giorno, Kiko incontra Ettore, un insegnante in pensione sulla sessantina, che gli dice di essere un vecchio amico del padre e di volerlo aiutare nello studio.\u00a0\u00c8 la storia di un&#8217;adolescenza tremante quella raccontata da Vittorio Moroni, la cronaca sincera e diretta di un&#8217;esistenza incerta, dispersa nella periferia friulana tra cantieri, scuola e una bar-stazione di benzina in cui, insieme all&#8217;anomala famiglia di Kiko, vive un gruppo di immigrati clandestini.<\/p>\n<p style=\"text-align: justify;\"><em>Kiko is a teenager whose now dead father was Italian and his mother Marilou is from the Philippines. They live with Ennio, mother&#8217;s new boyfriend, a foreman who recruits and exploits illegal migrant workers. Kiko goes to school but at the same time he is forced to work in Ennio&#8217;s building yards. He feels he lives in a wrong planet. There&#8217;s only one place where Kiko can dream: an old abandoned bus in a dump yard that he&#8217;s turned into his private refuge. One day it seems his fate could change: an elderly friend of his father&#8217;s, Ettore, comes looking for Kiko and offers to become a strange kind of tutor for him. But one day Ettore reveals to Kiko his real identity&#8230;<\/em><\/p>\n<hr \/>\n<p style=\"text-align: center;\">\u00a0<span style=\"color: #993300; font-size: large;\">DOMENICA\u00a019\u00a0ore 21.00<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">OUTSIDER ARTISTS &#8211;\u00a0IN COLLABORAZIONE CON FELTRINELLI REAL CINEMA<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">DOWNTOWN 81<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #515151;\">di Edo Bertoglio (USA, 1981, 72&#8242;, english version, sottotitolato in italiano)<\/span><br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #993300;\">a seguire il regista Edo Bertoglio incontra il pubblico in video collegamento skype<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/08\/downtown81-image.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3393\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/08\/downtown81-image.jpg\" alt=\"downtown81-image\" width=\"400\" height=\"400\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\">Nell&#8217;arco di una giornata a Manhattan, fra il 1980 e il 1981, Jean-Michel Basquiat, allora poco pi\u00f9 che un artista di strada, si aggira fra Downtown e Harlem in cerca di un posto dove dormire la sera,\u00a0Sottobraccio porta uno dei suoi quadri, quelli che poi sarebbero stati valutati decine di migliaia di dollari, ma che al momento vale solo un biglietto da venti e un assegno che Jean-Michel non pu\u00f2 incassare. Lungo la via si imbatte in tutto il sottobosco della scena artistica newyorkese di quegli anni: musicisti e spacciatori, modelle e dj, stripper e graffitari.\u00a0<\/span><br \/>\n<span style=\"font-size: small;\"><em>Downtown &#8217;81<\/em>\u00a0\u00e8 \u00a0anche una sorta di musical costellato di\u00a0<em>performance<\/em>\u00a0dal vivo nei locali dell&#8217;epoca, soprattutto il <strong>Mudd Club<\/strong> e la <strong>Peppermint Lounge<\/strong>. Girato appunto fra l&#8217;80 e l&#8217;81 dal regista italo svizzero Edo Bertoglio, era infatti rimasto al palo per mancanza di fondi e fu recuperato solo nel 2000, anno in cui partecip\u00f2 fuori concorso al <strong>Festival di Cannes<\/strong> suscitando grandi entusiasmi. Il suo valore, ancor pi\u00f9 che di testimonianza artistica, \u00e8 quello di reperto archeologico: nessuno avrebbe potuto raccontare con maggior dovizia di particolari e fedelt\u00e0 di luoghi e personaggi quel particolare periodo della New York in cui tante tendenza artistiche underground &#8211; dal rap alla new wave, dalla graffiti art alla videomusic &#8211; emergevano tutte insieme nutrendosi l&#8217;una dell&#8217;altra, e i protagonisti dell&#8217;epoca,\u00a0<em>in primis<\/em>\u00a0lo stesso Basquiat, si trovavano a un passo dalla celebrit\u00e0, ma con ancora un piede affondato nella miseria e nel rischio del fallimento.<\/span><\/p>\n<p style=\"text-align: justify;\">Recensione: <a href=\"http:\/\/www.schermaglie.it\/mondovisioni\/120\/downtown-81\">http:\/\/www.schermaglie.it\/mondovisioni\/120\/downtown-81<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\"><em>The film is a day in the life of a young artist, Jean Michel Basquiat, who needs to raise money to reclaim the apartment from which he has been evicted. He wanders the downtown streets carrying a painting he hopes to sell, encountering friends, whose lives (and performances) we peek into. He finally manages to sell his painting to a wealthy female admirer, but he&#8217;s paid by check. Low on cash, he spends the evening wandering from club to club, looking for a beautiful girl he had met earlier, so he&#8217;ll have a place to spend the night. Downtown 81 not only captures one of the most interesting and lively artists of the twentieth century as he is poised for fame, but it is a slice of life from one of the most exciting periods in American culture, with the emergence of new wave music, new painting, hip hop and graffiti.<\/em><\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt; color: #993300;\">MARTED\u00ec 21 ore 21<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">PRIME VISIONI &#8211; IN COLLABORAZIONE CON\u00a0MAREMOSSO\u00a0E SCHERMAGLIE.IT<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">SE CHIUDO GLI OCCHI NON SONO PI\u00d9 QUI<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di Vittorio Moroni\u00a0(Italia\u00a02014, 105\u2019, versione italiana, english subtitles)<br \/>\n<\/span><span style=\"font-size: 12pt;\">Con Giorgio Colangeli, Beppe Fiorello, Mark Manaloto, Hazel Morillo, Vladimir Doda<\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3572\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/Se-chiudo-gli-occhi-non-sono-pi\u00f9-qui-Giorgio-Colangeli_2.jpg\" alt=\"Se-chiudo-gli-occhi-non-sono-pi\u00f9-qui-Giorgio-Colangeli_2\" width=\"350\" height=\"155\" \/><\/p>\n<p><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p><strong><span style=\"font-size: 12pt; color: #993300;\">alla presenza del cast e di Rosa Morelli (Actors Couch del film)<\/span><\/strong><\/p>\n<p><span style=\"font-size: 12pt;\">per la scheda completa del film vedere SABATO 18<\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt; color: #993300;\">MERCOLED\u00ec 22 ore 21<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">\u00a0PRIME VISIONI &#8211; IN COLLABORAZIONE CON\u00a0ISTITUTO LUCE<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">LE COSE BELLE<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di Agostino Ferrente, Giovanni Piperno (Italia\u00a02013, 88\u2019)<\/span><\/p>\n<p><strong><span style=\"color: #993300;\"><span style=\"font-size: 12pt;\">INCONTRO IN SALA CON IL REGISTA GIOVANNI PIPERNO<\/span><\/span><\/strong><\/p>\n<p><span style=\"font-size: 12pt;\"><a href=\"http:\/\/jmp.sh\/t9zwD2r\">&gt;VAI AL TRAILER&lt;<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/le_cose_belle.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3574\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/le_cose_belle.jpg\" alt=\"le_cose_belle\" width=\"350\" height=\"500\" \/><\/a><\/p>\n<p><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Il film mostra la fatica e la bellezza di crescere al Sud attraverso le storie di quattro giovani, Adele, Enzo, Fabio e Silvana raccontati in due momenti fondamentali delle loro esistenze: la prima giovinezza nella Napoli piena di speranza del 1999 e l&#8217;inizio dell&#8217;et\u00e0 adulta in quella paralizzata di oggi. Un viaggio tra tempi diversi, musiche, storie, che restituisce un\u2019et\u00e0 e un tempo ben oltre i confini della citt\u00e0 in cui \u00e8 ambientato; quella Napoli che continua a dimostrarsi il palco delle speranze e delle lotte di un Paese intero.\u00a0Il\u00a0documentario di Agostino Ferrente e Giovanni Piperno \u00e8 stato premiato al Taormina Film Fest come\u00a0miglior documentario (Premio Cariddi)\u00a0definito dalla Giuria del Taormina Film Fest: &#8220;uno dei documentari pi\u00f9 appassionanti e toccanti degli ultimi anni&#8221;.<\/p>\n<p style=\"text-align: justify;\"><em>Naples 1999, two boys and two girls full of hope. Naples 2013, the same protagonists disenchanted in a paralyzed city.<\/em><\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt; color: #993300;\">GIOVED\u00ec 23 ore 21<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">PRIME VISIONI &#8211; IN COLLABORAZIONE CON\u00a0MAREMOSSO\u00a0E SCHERMAGLIE.IT<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">SE CHIUDO GLI OCCHI NON SONO PI\u00d9 QUI<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di Vittorio Moroni\u00a0(Italia\u00a02014, 105\u2019, versione italiana, english subtitles)<br \/>\n<\/span><span style=\"font-size: 12pt;\">Con Giorgio Colangeli, Beppe Fiorello, Mark Manaloto, Hazel Morillo, Vladimir Doda<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/se-chiudo-gli-occhi_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3575\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/se-chiudo-gli-occhi_3.jpg\" alt=\"se-chiudo-gli-occhi_3\" width=\"350\" height=\"193\" \/><\/a><\/p>\n<p><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p><span style=\"color: #993300;\"><strong><span style=\"font-size: 12pt;\">alla presenza del cast e dei responsabili tecnico-artistici della troupe<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-size: 12pt;\">per la scheda completa del film vedere SABATO 18<\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">VENERD\u00ec 24 ore 19.30<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: medium; color: #515151;\">Friends in Rome &amp; Detour present<\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: xx-large; color: #515151;\">CINE FRIENDS<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium; color: #515151;\">The best Italian movies, not only pizza, spaghetti and mandolino&#8230;<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium; color: #515151;\">All movies are shown in Italian with English subtitles \/\u00a0Serata di proiezione di cinema italiano sottotitolato in inglese.<\/span><\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" title=\"cinefriends\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/cinefriends1.jpg\" alt=\"\" width=\"250\" height=\"167\" \/><\/p>\n<p align=\"center\"><span style=\"font-size: medium;\"><span style=\"color: #993300;\"><strong>h7.30 p.m.\u00a0<\/strong><\/span>Meeting time and welcome drink A chance to socialize and network while mingling with an international crowd.<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: medium;\"><span style=\"color: #993300;\"><strong>h9.00 p.m.<\/strong>\u00a0<\/span>Screening \/ proiezione <\/span><\/p>\n<p align=\"center\"><span style=\"font-size: medium;\"> Per il programma dettagliato, info e prenotazioni \/ For further information and reservation<br \/>\nplease contact:\u00a0<a href=\"mailto:cinedetour.it\">cinedetour@tiscali.it<\/a>\u00a0\/\u00a0<a href=\"http:\/\/www.friendsinrome.com\/\">www.friendsinrome.com<\/a><\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt; color: #993300;\">SABATO\u00a025 doppio spettacolo 20.30\u00a0e\u00a0ore 22.00<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">\u00a0PRIME VISIONI &#8211; IN COLLABORAZIONE CON\u00a0ISTITUTO LUCE<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">LE COSE BELLE<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di Agostino Ferrente, Giovanni Piperno (Italia\u00a02013, 88\u2019)<\/span><\/p>\n<p><strong><a href=\"http:\/\/jmp.sh\/t9zwD2r\">&gt;VAI AL TRAILER&lt;<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/cosebelle-Adeleballa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3576\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/cosebelle-Adeleballa.jpg\" alt=\"cosebelle-Adeleballa\" width=\"350\" height=\"197\" \/><\/a><\/p>\n<p><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p><span style=\"font-size: 12pt;\">per la scheda completa del film vedere MERCOLED\u00ec 22<\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\">\u00a0<span style=\"color: #993300; font-size: large;\">DOMENICA 26 ore 16.30<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 12pt; color: #515151;\">DETOUR PRESENTA<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 24pt; color: #515151;\">CINEBIMBI<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: large; color: #515151;\">pomeriggio di proiezioni e pop corn\u00a0per i pi\u00f9 piccoli\u00a0e cinebar per i grandi<br \/>\n<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 12pt; color: #515151;\">\u00a0Per info e prenotazioni:\u00a0<a style=\"color: #515151;\" href=\"mailto:cinebimbi@gmail.com\">cinebimbi@gmail.com<\/a> <\/span><\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1795\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/01\/cinebimbi-300x194.jpg\" alt=\"cinebimbi\" width=\"300\" height=\"194\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/01\/cinebimbi-300x194.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/01\/cinebimbi.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Cinebimbi \u00e8 la fabbrica dei sogni per i pi\u00f9 piccoli. Al cinebimbi i \u00a0bambini posso condividere con i propri amici e coetanei la magia della visione cinematografica. Detour selezioner\u00e0 per loro i migliori titoli dell&#8217;animazione contemporanea e non. E per i pap\u00e0 e le mamme cinebar e caffetteria in funzione con proiezioni e musica per noi. L&#8217;ingresso e&#8217; riservato ai soci ARCI: i genitori devono sottoscrivere la tessera. Per ogni tessera si ha diritto a un ingresso omaggio.\u00a0Ingresso alla proiezione 5 euro.<\/span><\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p><span style=\"font-size: 14pt; color: #993300;\">DOMENICA\u00a026 ore\u00a019<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">\u00a0PRIME VISIONI &#8211; IN COLLABORAZIONE CON\u00a0ISTITUTO LUCE<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">LE COSE BELLE<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di Agostino Ferrente, Giovanni Piperno (Italia\u00a02013, 88\u2019)<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">per la scheda completa del film vedere MERCOLED\u00ec 22\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\"><a href=\"http:\/\/jmp.sh\/t9zwD2r\">&gt;VAI AL TRAILER&lt;<\/a><\/span><\/strong><\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #993300; font-size: large;\">DOMENICA 26 ore 21.00<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\"><em>in collaborazione con\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">EU 013 L&#8217;ULTIMA FRONTIERA<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><span style=\"color: #515151;\">di Alession Genovese, Raffaella Cosentino\u00a0(Italia, 2013, 63&#8242;, versione italiana, english subtitles)<\/span><br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 14pt; color: #993300;\">a seguire incontro con la co-autrice Raffaella Cosentino<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><a href=\"http:\/\/jmp.sh\/t9zwD2r\">&gt;VAI AL TRAILER&lt;<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/Lultima_frontiera.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3510\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/Lultima_frontiera.jpg\" alt=\"L'ultima_frontiera\" width=\"350\" height=\"495\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Ogni anno migliaia di cittadini stranieri vengono trattenuti all&#8217;interno dei Centri di Identificazione ed Espulsione (C.i.e.) italiani per non avere un regolare permesso di soggiorno. Possono restarvi rinchiusi fino ad un anno e mezzo senza aver commesso reato e senza essere stati condannati da un giudice. Per la prima volta in Italia, il Ministero dell&#8217;Interno ha autorizzato una troupe cinematografica ad entrare in queste strutture. Il muro di silenzio che circonda i C.i.e. e chi vi \u00e8 rinchiuso si \u00e8 aperto, in via del tutto eccezionale, al breve passaggio della troupe per poi richiudersi nell&#8217;indifferenza di tutti i giorni. Sono luoghi che si raccontano da soli, istituzioni totali che ci ricordano i lager e i manicomi, dove a farla da padrone \u00e8 la violenza, fisica e mentale. Gli &#8220;ospiti&#8221;, come vengono chiamati i trattenuti, sono persone private della loro identit\u00e0. \u00a0Allo scadere dei diciotto mesi vengono rilasciati con un foglio di via con il quale devono uscire dal territorio nazionale italiano entro pochi giorni. Molti di loro non vengono pi\u00f9 riconosciuti dai loro consolati, se escono dal nostro per andare in un altro paese europeo vengono fermati e rimandati in Italia dove vengono riportati in un C.i.e. per altri diciotto mesi. Una storia assurda che sembra non finire mai.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><em>For the first time, the Italian authorities allowed a film crew into the Centres for Identification and Expulsion: selection centres for refugees. Genovese shows European asylum policy as a carousel of hope and frustration, in which refugees are spun around until madness ensues.\u00a0Aliens in Italy can be held up to 18 months in a CIE, a Centro di Identificazione ed Espulsione (Identification and Deportation Centre), before they are admitted or deported. The Italian photographer\/documentary maker Alessio Genovese was the first person to get permission to take a look inside the walls. He interviews both the guards and the men and women who have to spend long months behind locked doors. None of them has committed a crime or has been sentenced. They are known as &#8216;guests&#8217; in CIE jargon. Most of them grew up in Italy. After forced deportation, they roamed Europe but have to return to Italy as soon as they are arrested, after which the process starts all over again.\u00a0Even viewers are brought to their knees by the stories and the administrative hell in which these people find themselves, so you can guess how the guests and guards feel. And that\u2019s how the international refugee merry-go-round keeps turning. It has turned into an industry.<\/em><\/span><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"color: #993300; font-size: large;\">MARTED\u00ec 28\u00a0ore 20.45<\/span><\/p>\n<p><span class=\"Apple-style-span\" style=\"color: #515151;\"><span class=\"Apple-style-span\">serata con\u00a0presentazione e\u00a0proiezione di film a cura di<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">ViSiOnI &#8211; INCONTRI DI CINEMA<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small; color: #515151;\"><em>&#8220;E&#8217; buffo come i colori del mondo divengano veri soltanto quando uno li vede sullo schermo&#8221;\u00a0<\/em>(Alex in Arancia Meccanica, S. Kubrick, 1971)<\/span><\/p>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"color: #515151;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/18703.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3622\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/18703.jpg\" alt=\"18703\" width=\"240\" height=\"137\" \/><\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">Per il programma dettagliato e informazioni:\u00a0<a style=\"color: #515151;\" href=\"http:\/\/forumcinema.blog.tiscali.it\/\">http:\/\/forumcinema.blog.tiscali.it<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">Per partecipare agli incontri \u00e8 preferibile prenotarsi scrivendo a\u00a0<a style=\"color: #515151;\" href=\"mailto:visioni@gmelies.it\">visioni@gmelies.it<\/a><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\" style=\"font-size: 12pt; color: #515151;\">leggi\u00a0<a style=\"color: #515151;\" href=\"http:\/\/digilander.libero.it\/sergio.nota\/Scheda%20Presentazione.pdf\"><span class=\"s2\">Cos\u2019\u00e8 Visioni<\/span><\/a><\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt; color: #993300;\">MERCOLED\u00ec\u00a029 ore\u00a021.00<\/span><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><span style=\"font-size: 12pt;\">\u00a0PRIME VISIONI &#8211; IN COLLABORAZIONE CON\u00a0ISTITUTO LUCE<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">LE COSE BELLE<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt; color: #515151;\">di Agostino Ferrente, Giovanni Piperno (Italia\u00a02013, 88\u2019)<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\"><a href=\"http:\/\/jmp.sh\/t9zwD2r\">&gt;VAI AL TRAILER&lt;<\/a><\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/le-cose-belle_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3577\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/le-cose-belle_4.jpg\" alt=\"le-cose-belle_4\" width=\"350\" height=\"197\" \/><\/a><\/p>\n<p><em><span style=\"color: #993300; font-size: 12pt;\">prima della proiezione snack gratuito per i soci<\/span><\/em><\/p>\n<p><span style=\"font-size: 12pt;\">per la scheda completa del film vedere MERCOLED\u00ec 22<\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 14pt; color: #993300;\">GIOVED\u00ec 30 dalle ore\u00a019.30<\/span><\/p>\n<p><span style=\"font-size: 12pt; color: #515151;\">CINEMA ESTREMO FB Page &amp; DETOUR HORROR PROJECT<br \/>\n<em>in collaborazione con<\/em><\/span><br \/>\n<em> <span style=\"font-size: 12pt; color: #515151;\"> La Samain du cin\u00e9ma fantastique\u00a0de Nice &amp; The Optical Theatre Festival<\/span><\/em><\/p>\n<div>\n<div style=\"text-align: center;\" title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"font-size: xx-large; color: #515151;\">PRE-HALLOWEEN NIGHT(MARE)<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #515151;\"><strong><span style=\"font-size: 12pt;\">Serata di cinema horror inedito e\u00a0selezione musicale\u00a0horror soundtrack<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/SuburbanGothicLc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3592\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/SuburbanGothicLc.jpg\" alt=\"SuburbanGothicLc\" width=\"400\" height=\"593\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">\u00a0ore 19.30\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\">FINGER FOOD &amp; HORROR SOUNDTRACK DJING<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">ore 21.00 <\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\">Anteprima italiana assoluta dal regista di Excision<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt;\">SUBURBAN GOTHIC<br \/>\n<span style=\"font-size: 12pt;\">di Richard Bates Jr (Usa 2014, English Version, sottotitoli in italiano)<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/suburban_gothic.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3578\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/suburban_gothic.jpg\" alt=\"suburban_gothic\" width=\"450\" height=\"253\" \/><\/a><\/p>\n<p style=\"text-align: justify;\" align=\"left\"><span style=\"color: #333333;\"><span style=\"font-family: Verdana, Arial, sans-serif;\"><span style=\"font-size: small;\">Raymond si\u00a0\u00e8 laureato con lode n una prestigiosa universit\u00e0\u00a0ma non trova un lavoro ed \u00e8 costretto a tornare a vivere dai suoi in provincia: madre iperprotettiva, padre ex-atleta (l&#8217;attore Ray Wise, conosciuto come il padre di Laura Palmer nella serie Twin Peaks) e bulli ex-compagni di classe. I poteri paranormali che lo hanno tormentato in passato sembrano essersi esauriti, anche se continua fare strani sogni. Quando un fantasma vendicativo inizia a terrorizzare la piccola comunit\u00e0, Raymond recluta Becca, la &#8220;barista cazzuta&#8221; del pub del paese, per risolvere il mistero dello spirito che minaccia le vite di tutti. Se avete visto il cult Excision, conoscete bene l&#8217;irresistibile senso dell&#8217;umorismo del regista Bates.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\" align=\"left\"><em><span style=\"color: #333333;\"><span style=\"font-family: Verdana, Arial, sans-serif;\"><span style=\"font-size: small;\">Raymond has a prestigious MBA, but he can&#8217;t find work. He can channel the paranormal, but chatting with a cute girl mystifies him. Kicked out of his big city apartment, Raymond returns home to his overbearing mother, ex-jock father, and beer-bellied classmates. But when a vengeful ghost terrorizes the small town, the city-boy recruits Becca, a badass local bartender, to solve the mystery of the spirit threatening everyone&#8217;s lives. <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Helvetica, Arial, Verdana, 'Bitstream Vera Sans', sans-serif;\"><span style=\"font-size: small;\">If you&#8217;ve seen\u00a0<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Helvetica, Arial, Verdana, 'Bitstream Vera Sans', sans-serif;\"><span style=\"font-size: small;\">Excision<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Helvetica, Arial, Verdana, 'Bitstream Vera Sans', sans-serif;\"><span style=\"font-size: small;\">, you&#8217;ve experienced its maker&#8217;s wry sense of humour.<\/span><\/span><\/span><\/em><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #993300;\">VENERD\u00ec 31 ore 21.00<br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt; color: #515151;\">DOCUMENTARIO INEDITO DEL MESE\u00a0&#8211;\u00a0OUTSIDER ARTISTS<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"font-size: large; color: #515151;\"><span style=\"font-size: xx-large;\"><span style=\"color: #515151;\">IN THE REALMS OF THE UNREAL<\/span><br \/>\n<span style=\"font-size: 14pt;\">The Mystery of Henry Darger<\/span><br \/>\n<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\">di Jessica Ju\u00a0(Usa 2005, 83\u2019, english version, sottotitolato in italiano)\u00a0\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: medium; color: #993300;\">prima delle proiezioni\u00a0snack gratuito per i soci<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/in_the_realms.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3482\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/09\/in_the_realms.jpg\" alt=\"in_the_realms\" width=\"350\" height=\"511\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Chi ha conosciuto la\u00a0vicenda della fotografa Vivian Maier, non potr\u00e0 fare a meno di notare sorprendenti analogie con\u00a0la materia narrativa di <em>In the\u00a0Realms of the Unreal<\/em> (realizzato qualche hanno prima di quello sulla Maier)\u00a0in cui si racconta la storia vera di Henry Darger &#8211; solitario\u00a0custode d&#8217;ospedale\u00a0di Chicago -rivelazione postuma di\u00a0un eccentrico\u00a0genio\u00a0artistico, nascosto al mondo per una vita intera. Alla sua morte, nel 1972, il suo padrone di casa fece una scoperta sorprendente: un colossale e oscuro\u00a0manoscritto\u00a0fantasy composto di 15.143 pagine, corredato\u00a0da\u00a0pi\u00f9 di 300 illustrazioni strane e affascinanti, tra collage, disegni e dipinti ad acquarello. Piuttosto che intervistare esperti d&#8217;arte e psicologi, e in mancanza di altri materiali visivi d&#8217;archivio disponibili su Darger\u00a0(del quale\u00a0esistono solo quattro fotografie note), la regista sceglie di osservare\u00a0la sua opera\u00a0dal punto di vista di coloro che lo hanno conosciuto e di raccontare il mondo epico e allucinato\u00a0del suo romanzo\u00a0attraverso alcune\u00a0sequenze in animazione, realizzate a partire dai disegni originali del suo autore.<\/span><\/p>\n<p style=\"text-align: justify;\"><span id=\"movieSynopsisRemaining\" style=\"font-size: 10pt;\"><em>An obscure janitor during his life, Darger is known for the posthumous discovery of his elaborate 15,143-page fantasy manuscript entitled The Story of the Vivian Girls, in What is Known as the Realms of the Unreal, of the Glandeco-Angelinnian War Storm, Caused by the Child Slave Rebellion, along with several hundred watercolor paintings and other drawings illustrating the story. Because of his reclusive lifestyle (there are only four known photographs of Darger) and rather than interview art scholars and psychologists, the director chooses to look at Darger&#8217;s work from the viewpoints of those who knew him. She also incorporates animation segments into the documentary, using Darger&#8217;s original images. <\/em>\u00a0<\/span><\/p>\n<p>&#8212;<\/p>\n<div>\n<div style=\"text-align: center;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1283 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"130\" height=\"127\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Teatro | Produzione Distribuzione Editoria indipendente<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p>Tutti i film sono proiettati in lingua originale con sottotitoli in italiano<\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: small;\">Art-house cinema in Downtown Rome since 1997.<br \/>\nAll movies are screened in their original languages with italian or english subtitles<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Ingresso riservato ai soci ARCI Primo ingresso con tessera associativa annuale: 8\u20ac\/9\u20ac Ingresso alle proiezioni successive e alle attivit\u00e0: quota di adesione 5\u20ac\/6\u20ac<br \/>\n<\/span><span style=\"font-size: small;\">Cineclub Detour \u00e8 affiliato all&#8217;ARCI-UCCA e alla FICC (Federazione Italiana Circoli Cinema)<br \/>\nPer il tesseramento \u00e8 preferibile arrivare con almeno 15 minuti di anticipo prima dell&#8217;inizio dello spettacolo<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: small;\"> For ARCI members only. Annual membership including first admission: 8\u20ac \/9\u20ac Following admissions to screenings: 5\u20ac\/6\u20ac\u00a0<\/span><span style=\"font-size: small;\">Cineclub Detour is affiliated to ARCI-UCCA and to FICC<br \/>\nPlease kindly arrive 15-20 minutes before the film starts to allow time needed for membership <\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Sostienici<\/a> \/ <em><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Support Us<\/a><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Seguici su \/ <em>Follow us on:<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\" \/><\/a> <a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\" \/><\/a> <a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\" \/><\/a><\/p>\n<\/div>\n<p style=\"text-align: center;\"><strong style=\"text-align: center;\">\u00a0<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cinema | Corsi e Laboratori | Esposizioni | Attivit\u00e0 per Bambini | Cine Bar\u00a0| Musica | Video d&#8217;Arte e Teatro | Produzione | Distribuzione ed editoria indipendente | Web Radio &#8212; Comunicazione riservata ai soci DETOUR-ARCI &#8211; Il programma pu\u00f2 subire variazioni CINEMA\u00a0&gt; DETOUR &gt;\u00a0OTTOBRE 2014 Associazione Culturale DETOUR ARCI &#8211; Via Urbana 107 Roma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[282,224,259,281,221,264,204,269,15,193,122,162,222,213,26,223,280,283,270,45,260,272,250,271,216,77,263,219,257,279],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 17:09:22","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/3464"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=3464"}],"version-history":[{"count":75,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/3464\/revisions"}],"predecessor-version":[{"id":3523,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/3464\/revisions\/3523"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=3464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=3464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=3464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}