{"id":3627,"date":"2014-11-01T17:56:49","date_gmt":"2014-11-01T16:56:49","guid":{"rendered":"https:\/\/cinedetour.it\/?p=3627"},"modified":"2015-03-26T17:02:53","modified_gmt":"2015-03-26T16:02:53","slug":"se-chiudo-gli-occhi-non-sono-piu-qui-di-vittorio-moroni-al-detour-il-regista-e-il-cast","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2014\/11\/01\/se-chiudo-gli-occhi-non-sono-piu-qui-di-vittorio-moroni-al-detour-il-regista-e-il-cast\/","title":{"rendered":"SE CHIUDO GLI OCCHI NON SONO PI\u00d9 QUI di Vittorio Moroni &#8211; Incontro autore e cast (DOTR014 Preview)"},"content":{"rendered":"<div style=\"text-align: center;\">\n<table style=\"height: 48px;\" border=\"0\" width=\"839\">\n<tbody>\n<tr>\n<td><span style=\"font-size: 8pt;\">Con il sostegno di<\/span><\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td style=\"text-align: right;\"><span style=\"font-size: 8pt;\">\u00a0Patrocinio di<\/span><\/td>\n<\/tr>\n<tr>\n<td><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/11\/logo_reg_tras_small.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4038 alignleft\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/11\/logo_reg_tras_small.png\" alt=\"logo_reg_tras_small\" width=\"150\" height=\"38\" \/><\/a><\/td>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<td style=\"width: 120px; text-align: right;\">ROMA CAPITALE<br \/>Municipio I<\/td>\n<td style=\"width: 75px; text-align: right; vertical-align: middle;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4027 alignright\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/11\/logo-comune-roma-municipio_small.gif\" alt=\"logo-comune-roma-municipio_small\" width=\"57\" height=\"70\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong>Detour On the Road Film Fest _ \u00a0Preview 2014<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 14pt;\">In\u00a0collaborazione con le distribuzioni 50 Notturno,\u00a0Lo\u00a0Scrittoio,\u00a0Maremosso,<br \/>la rivista online\u00a0Schermaglie\u00a0e con\u00a0Save the Children\u00a0Italia<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\">presenta\u00a0<\/span>\u00a0<\/p>\n<\/div>\n<div id=\"yui_3_16_0_1_1403781753513_41026\" style=\"text-align: center;\">\n<p class=\"p1\"><span style=\"font-size: 18pt;\">Due serate speciali per il film di Vittorio Moroni\u00a0<\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 18pt;\">con <strong>Save the Children<\/strong><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 14pt;\">Cinema Detour &#8211; Sabato 1\u00a0Novembre ore 19.00\u00a0| Domenica 2 Novembre ore 20.00<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><b>Domenica 2 alle ore 20<\/b> un <b>aperitivo filippino<\/b> alla presenza di regista e cast preceder\u00e0 la proiezione del film, abbinata al cortometraggio presentato da Save the Children \u201c<b>Un core dentro stazione Termini\u201d di Samuel Cirpaci<\/b>. L\u2019autore sar\u00e0 presente in sala per parlare del suo cortometraggio, vincitore della menzione speciale al TuttoMondo contest 2014.\u00a0<\/span><\/p>\n<p class=\"p2\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Il cortometraggio presentato, prodotto dalla cooperativa CivicoZero con il contributo di Save the Children Italia, nasce da un laboratorio di documentario partecipato. Con questo tipo di iniziative Save the Children, l\u2019Organizzazione dedicata dal 1919 a salvare i bambini e a promuovere i loro diritti in tutto il mondo, vuole contribuire a contrastare la povert\u00e0 educativa in Italia, creando le condizioni perch\u00e9 \u00a0i giovani che vivono in contesti a rischio di povert\u00e0 ed esclusione sociale abbiano la possibilit\u00e0 concreta di coltivare ed esprimere liberamente capacit\u00e0, talenti e aspirazioni.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">Le proiezioni\u00a0di <b>domenica 2 novembre<\/b>\u00a0saranno introdotte da <b>Pietro Del Sold\u00e0<\/b>, conduttore di \u201cTutta la citt\u00e0 ne parla\u201d di Radio3 Rai. Interverr\u00e0 per Save the Children Italia\u00a0Antonella Inverno.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><b><i>Se chiudo gli occhi non sono pi\u00f9 qui<\/i>\u00a0<\/b>sar\u00e0 proiettato in italiano con l&#8217;<span class=\"s1\">aggiunta di sottotitoli in inglese<\/span>\u00a0per favorire la partecipazione del pubblico straniero residente a Roma.<\/span><\/p>\n<\/div>\n<div style=\"text-align: center;\">&#8212;<\/div>\n<div style=\"text-align: center;\">\u00a0<\/div>\n<div id=\"yui_3_16_0_1_1403781753513_41037\" style=\"text-align: center;\"><span style=\"font-size: 24pt;\">SE CHIUDO GLI OCCHI<br \/> <\/span><\/div>\n<div style=\"text-align: center;\">\u00a0<\/div>\n<div style=\"text-align: center;\"><span style=\"font-size: 24pt;\">NON SONO PI\u00d9 QUI<\/span><\/div>\n<div style=\"text-align: center;\"><span style=\"font-size: 24pt;\"><span style=\"color: #ff6600;\">\u00a0<\/span><\/span><\/div>\n<div style=\"text-align: center;\"><span style=\"font-size: medium;\">\u00a0di Vittorio Moroni\u00a0(Italia, 2013-14, 105&#8242;, Versione originale italiana, English subtitles)<\/span><\/div>\n<div style=\"text-align: center;\"><span style=\"font-size: medium;\">\u00a0<\/span><\/div>\n<div style=\"text-align: center;\">\u00a0<\/div>\n<div style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/Locandina_Sechiudo_mid.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3629\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2014\/10\/Locandina_Sechiudo_mid.jpg\" alt=\"Locandina_Sechiudo_mid\" width=\"800\" height=\"1120\" \/><\/a><\/div>\n<div style=\"text-align: center;\">\u00a0<\/div>\n<div>\u00a0<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #292929;\">Il film, che \u00e8 stato presentato lo scorso anno al Festival Internazionale del film di Roma e ha partecipato al Santa Barbara International Film Festival 2014, \u00e8 il quarto lavoro del regista sondriese Vittorio Moroni (Tu devi essere il lupo, le ferie di Licu, Eva e Adamo) che vede, tra i protagonisti, anche Beppe Fiorello e Giorgio Colangeli.<\/span><\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #292929;\">Kiko (Mark Manaloto), sedici anni,<span class=\"text_exposed_show\"> ha perso il padre italiano in un incidente e vive con la madre filippina Marilou e il suo nuovo compagno Ennio (Giuseppe Fiorello), un caporale che sfrutta immigrati clandestini in cantieri edili. Ogni giorno dopo scuola Kiko \u00e8 costretto a lavorare per Ennio. Sente di vivere nel pianeta sbagliato. C\u2019\u00e8 un solo posto dove \u00e8 possibile sognare: un vecchio autobus abbandonato che il ragazzo ha trasformato nel suo rifugio.\u00a0<\/span><\/span><span style=\"color: #292929; font-size: 12pt;\">L\u2019incontro con Ettore (Giorgio Colangeli), un vecchio amico del padre che si offre di aiutarlo negli studi, cambier\u00e0 il suo destino. Quell\u2019uomo, per\u00f2, nasconde un segreto.<\/span><\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #292929;\">Con uno stile delicato e rispettoso della sensibilit\u00e0 del suo protagonista, il documentarista Moroni riesce a creare un affresco poetico di emozioni attorno alla storia di un ragazzo speciale.\u00a0<\/span><span style=\"font-size: 12pt; color: #292929;\">Il film affronta temi importanti e contemporanei dall&#8217;importanza di avere una guida nel momento cruciale dell&#8217;adolescenza, all&#8217;integrazione dei ragazzi di seconda generazione, dallo sfruttamento dell&#8217;immigrazione clandestina, alla dispersione scolastica.<\/span><span style=\"font-size: 12pt; color: #292929;\">Il film sar\u00e0 proiettato in italiano con l&#8217;aggiunta di sottotitoli in inglese per favorire la partecipazione del pubblico straniero residente a Roma.<\/span><\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\"><span style=\"color: #292929;\"><em><span style=\"font-size: 12pt;\">The movie will be screened in Original Italian version with english subtitles.\u00a0<\/span><\/em><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #292929;\"><em>Kiko is a teenager whose now dead father was Italian and his mother Marilou is from the Philippines. They live with Ennio, mother\u2019s new boyfriend, a foreman who recruits and exploits illegal migrant workers. Kiko goes to school but at the same time he is forced to work in Ennio\u2019s building yards. He feels he lives in a wrong planet. There\u2019s only one place where Kiko can dream: an old abandoned bus in a dump yard that he\u2019s turned into his private refuge. One day it seems his fate could change: an elderly friend of his father\u2019s, Ettore, comes looking for Kiko and offers to become a strange kind of tutor for him. But one day Ettore reveals to Kiko his real identity\u2026<\/em><\/span><span style=\"color: #292929;\"><span style=\"font-size: 12pt;\">\u00a0<\/span><\/span><\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #292929;\">&#8212;<\/span><\/div>\n<div style=\"text-align: justify;\">\u00a0<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #292929;\">Le serate sono organizzate in collaborazione con le distribuzioni Lo Scrittoio e Maremosso, e con la rivista online Schermaglie<\/span><\/div>\n<div>\u00a0<\/div>\n<p style=\"text-align: center;\"><span class=\"Apple-style-span\" style=\"color: #5c5c5c; font-size: medium;\">&#8212;<\/span><\/p>\n<div style=\"text-align: center;\">\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1283 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"130\" height=\"127\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small; font-family: arial, helvetica, sans-serif;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Teatro | Produzione Distribuzione Editoria indipendente<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small; font-family: arial, helvetica, sans-serif;\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\">Tutti i film sono proiettati in lingua originale con sottotitoli in italiano<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><em><span style=\"font-size: small;\">Art-house cinema in Downtown Rome since 1997. All movies are screened in their original languages with italian or english subtitles<\/span><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><span style=\"font-size: small;\">Cineclub Detour \u00e8 affiliato all&#8217;ARCI-UCCA e alla FICC (Federazione Italiana Circoli Cinema)<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><span style=\"font-size: small;\"><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Sostienici<\/a> \/ <em><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Support Us<\/a><\/em><\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small; font-family: arial, helvetica, sans-serif;\">Seguici su \/ <em>Follow us on:<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\" \/><\/a> <a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\" \/><\/a> <a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\" \/><\/a><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con il sostegno di \u00a0 \u00a0 \u00a0 \u00a0Patrocinio di \u00a0 \u00a0 ROMA CAPITALEMunicipio I &nbsp; Detour On the Road Film Fest _ \u00a0Preview 2014 In\u00a0collaborazione con le distribuzioni 50 Notturno,\u00a0Lo\u00a0Scrittoio,\u00a0Maremosso,la rivista online\u00a0Schermaglie\u00a0e con\u00a0Save the Children\u00a0Italia presenta\u00a0\u00a0 Due serate speciali per il film di Vittorio Moroni\u00a0 con Save the Children Cinema Detour &#8211; Sabato 1\u00a0Novembre ore [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[493,376],"tags":[285,120,176,50,280,284,4,121,112,279],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 19:24:45","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/3627"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=3627"}],"version-history":[{"count":35,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/3627\/revisions"}],"predecessor-version":[{"id":5137,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/3627\/revisions\/5137"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=3627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=3627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=3627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}