{"id":510,"date":"2013-03-31T20:37:25","date_gmt":"2013-03-31T19:37:25","guid":{"rendered":"https:\/\/cinedetour.it\/?p=510"},"modified":"2014-11-04T10:24:04","modified_gmt":"2014-11-04T09:24:04","slug":"detour-aprile-april-2013","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2013\/03\/31\/detour-aprile-april-2013\/","title":{"rendered":"Aprile 2013"},"content":{"rendered":"<p style=\"text-align: center;\" align=\"center\"><a href=\"http:\/\/www.cinedetour.it\"><img loading=\"lazy\" decoding=\"async\" title=\"LOGOTONDO_detour_2012_piccolo\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/LOGOTONDO_detour_2012_piccolo.gif\" width=\"120\" height=\"120\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Cineclub Detour @ Oasi Urbana &#8211; Via Urbana 107 Roma <\/span><br \/>\n<span style=\"font-size: small;\"><a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Proiezioni riservate ai soci dell&#8217;associazione culturale Detour.<br \/>\nIngresso con tessera associativa annuale 7\u20ac (soci arci: 5\u20ac) \/ ingressi successivi a sottoscrizione<\/span><br \/>\n<span style=\"font-size: small;\">Cineclub Detour \u00e8 affiliato alla FICC (Federazione Italiana Circoli Cinema)<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"> For members only.\u00a0Admission: annual membership 7\u20ac \/ free subscription (arci members: 5\u20ac)<\/span><br \/>\n<span style=\"font-size: small;\">Cineclub Detour is affiliated to FICC (Federazione Italiana Circoli Cinema) <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"> seguici su \/Follow us on:<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" width=\"31\" height=\"31\" \/><\/a> <a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" width=\"30\" height=\"30\" \/><\/a> <a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" width=\"31\" height=\"30\" \/><\/a><\/p>\n<p style=\"text-align: center;\">_____<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: x-large;\">cinema &gt; April 2013<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">mercoled\u00ec 3\u00a0<\/span>_ore 21<br \/>\n<\/span><\/strong><span style=\"font-size: x-large;\">BLINKENDE LYGTER (Flickering Lights)<\/span><br \/>\ndi Anders Thomas Jensen\u00a0(Danimarca 2000, 109&#8242;, sott ita)<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-550\" title=\"flickeringlight\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/flickeringlight2.jpg\" width=\"250\" height=\"141\" \/><\/p>\n<p style=\"text-align: justify;\" align=\"center\"><span style=\"text-align: justify;\">Dal regista de &#8220;Le mele di Adamo&#8221;.\u00a0Un gruppo di quattro piccoli delinquenti decide di tenersi il bottino di una rapina su commissione. Per sfuggire alla vendetta del committente, un violento boss chiamato Eskimo, scappano alla volta di Barcellona ma il motore dell&#8217;auto si fonde lungo una strada che attraversa il bosco. Uno di loro \u00e8 ferito e, per poterlo curare, sono costretti a rifugiarsi nel rudere di un vecchio ristorante nel cuore del bosco stesso. Al fine di non destare sospetti, dapprima fingono di voler ristrutturare e riaprire il ristorante poi, progressivamente, il luogo e i loro strambi vicini li conquistano.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: large;\">gioved\u00ec 4<\/span>\u00a0_ dalle\u00a0<\/strong><strong>ore 20<\/strong><\/span><span style=\"color: #ff6600;\"><strong><br \/>\n<\/strong><\/span>in collaborazione con \u00a0il Circolo di Roma del Movimento per la Decrescita Felice<span style=\"font-size: x-large;\"><br \/>\n<em><span style=\"font-size: large;\">L\u2019ECONOMIA DELLA FELICITA\u2019<\/span><\/em><br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #33cccc;\"><strong><span style=\"color: #ff6600;\">ore 20.00<\/span><br \/>\n<\/strong><\/span>Intervento di Emanuele Piccinno Economista<br \/>\n<span style=\"font-size: large;\">&#8220;Il prezzo delle crescita \u00e8 il benessere?&#8221;<\/span><strong><br \/>\n<\/strong>La decrescita felice nel sistema economico attuale, potenzialit\u00e0 e nuovi indicatori di misurazione di progresso<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #33cccc;\"><span style=\"color: #ff6600;\">ore 21.15<\/span><br \/>\n<\/span><\/strong>Proiezione del film<br \/>\n<span style=\"font-size: x-large;\">L\u2019ECONOMIA DELLA FELICITA\u2019<\/span><\/p>\n<p style=\"text-align: justify;\">Prodotto e presentato da Helena Nordbert-Hodge, analista economica e autrice de \u201cIl futuro nel passato\u201d, il documentario pone in luce la crisi economica, ambientale e sociale in cui ci troviamo e allo stesso tempo indica una via d\u2019uscita che appare ben pi\u00f9 efficace dei tagli, dei prestiti e degli accordi che ora vengono decisi da non si sa chi, al chiuso delle stanze del potere.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">venerd\u00ec 5<\/span>\u00a0_<\/span><\/strong><strong><span style=\"color: #ff6600;\">ore 21.00<br \/>\n<\/span><\/strong><em><em>IL CINEMA GRECO CHE NON TI ASPETTI<\/em><br \/>\n<\/em><span style=\"font-size: x-large;\">ATTENBERG<br \/>\n<\/span>di\u00a0Athina Rachel Tsangari\u00a0(Grecia 2010, 95&#8242;, vo sott ita)<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" title=\"attenberg\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/02\/attenberg.jpg\" width=\"250\" height=\"188\" \/><\/p>\n<p style=\"text-align: justify;\">Marina ha 23 anni e vive con il padre in una cittadina industriale della Grecia. La ragazza \u00e8 poco interessata alla specie umana e praticamente per nulla al sesso anche se cerca di comprendere qualcosa grazie alle canzoni dei Suicide e ai documentari sulla Natura di Sir David Attenborough. C&#8217;\u00e8 poi Bella, l&#8217;amica\/rivale che le impartisce lezioni di educazione sessuale. Marina prover\u00e0 ad applicarle con un forestiero arrivato in citt\u00e0 per lavoro. Intanto suo padre si prepara a morire per tumore. Se avete amato Kynodontas, non perdete questo film prodotto e interpretato proprio da Yorgos Lanthimos.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: justify;\">\n<p align=\"center\"><strong><span style=\"font-size: large; color: #ff6600;\">sabato 6\u00a0<\/span><\/strong><strong><span style=\"color: #ff6600;\">_ore 21<br \/>\n<\/span><\/strong><span style=\"color: #000000;\">in collaborazione con Ass. Cult. Euskara e Dip. Lingua e Cultura Basca \/ Upter<br \/>\n<\/span><span style=\"font-size: x-large; text-align: justify;\">EMAK BAKIA<br \/>\n<\/span>di Man Ray (Francia 1927, 17&#8242;)<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-552\" title=\"emak_bakia1\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/emak_bakia11.jpg\" width=\"250\" height=\"183\" \/><\/p>\n<p>In questo cinepoema &#8220;l&#8217;incidente cinematografico \u00e8 messo a nudo: Man Ray lancia in aria una cinepresa dopo averne avviato il movimento; come un alchimista, esplora giochi d&#8217;ottica e di luce (scintillii, riflessi, effetti anamorfici); trae il meraviglioso dagli oggetti pi\u00f9 umili (la tazza di un wc per esempio). E il poeta Jacques Rigaut organizza una danza di colletti&#8221; (Philippe Alain Michaud). &#8220;A coloro che ancora si domandano &#8216;la ragione di questa stravaganza&#8217;, si pu\u00f2 semplicemente rispondere con la traduzione del titolo Emak Bakia, un&#8217;antica espressione basca che significa &#8216;non rompetemi le scatole'&#8221;, Man Ray.<\/p>\n<p align=\"center\"><span style=\"font-size: x-large; text-align: justify;\">\u00a0<strong><span style=\"font-size: medium; color: #ff6600;\">ore 21.30_<\/span><\/strong> LA CASA EMAK BAKIA<br \/>\n<\/span>di Oskar Alegria (Spagna 2012, 83&#8242;)<br \/>\nAl termine dibattito con il regista Oskar Alegria, che sar\u00e0 presente in sala.<span style=\"text-align: justify;\">\u00a0<\/span><\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-553\" title=\"La-casa-de-Emak-Bakia_piccola\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/La-casa-de-Emak-Bakia_piccola.jpg\" width=\"250\" height=\"167\" \/><\/p>\n<\/div>\n<p style=\"text-align: justify;\">Un originale e inclassificabile &#8216;documentario&#8217; alla ricerca della villa sulla costa basca in cui Man Ray visse e realizz\u00f2 il suo celebre cinepoema. In ossequio al credo surrealista il regista si lascia guidare dal caso in un viaggio in cui il cammino si impone alla meta, incrociando le tombe di un clown, un&#8217;utranovantenne nobildonna rumena e molte altre storie misteriose e affascinanti.<br \/>\nTrailer: <span style=\"font-size: small;\"><a href=\"http:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=oDFeSSymHEY\" target=\"_blank\">http:\/\/www.youtube.com\/watch?<wbr \/>feature=player_embedded&amp;v=<wbr \/>oDFeSSymHEY<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #888888;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">domenica 7 <span style=\"font-size: medium;\">_ore 21<br \/>\n<\/span><\/span><\/span><\/strong><\/span><em>IL CINEMA GRECO CHE NON TI ASPETTI<br \/>\n<\/em><span style=\"font-size: x-large;\">MACHEROVGALTIS<\/span><br \/>\ndi\u00a0Yiannis Economidis\u00a0(Cipro\/Grecia, 2010 108&#8242;,\u00a0orig vers sott ita)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"macherovgaltis\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/macherovgaltis.jpg\" width=\"250\" height=\"140\" \/><\/p>\n<p style=\"text-align: justify;\">Prosegue il nostro viaggio nel cinema greco e dopo Yorgos Lanthimos, conosciamo\u00a0Yannis Economides\u00a0(Soul Kicking, 2006 e Matchbox (2002).\u00a0Macherovgaltis \u00e8 il suo ultimo film. Racconta la parte malata della Grecia di oggi, descritta come un paese volgare in cui delinquenti e individui meschini vestono i panni di rispettabili cittadini, mentre le persone per bene non trovano posto nella societ\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #888888;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">marted\u00ec \u00a09 <span style=\"font-size: medium;\">_ore 21.00<\/span><\/span><span style=\"font-size: large;\"><br \/>\n<\/span><\/span><\/strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\"><em>SULLE TRACCE DI KAURISMAKI<br \/>\n<\/em><\/span><\/span><\/span><\/span><span style=\"font-size: x-large;\">AALTRA<br \/>\n<\/span>\u00a0di\u00a0Gustave de Kervern, Benoit Del\u00e9pine\u00a0(Belgio\/Francia 2004, 94&#8242;,\u00a0orig vers sott ita)<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-554\" title=\"Aaltra\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/Aaltra.jpg\" width=\"250\" height=\"166\" \/><\/p>\n<p style=\"text-align: justify;\">Questi due registi sono completamente pazzi. Completamente ubriachi all&#8217;anteprima italiana al festival di Pesaro di qualche anno fa chiesero al pubblico di cantare insieme a loro l&#8217;inno nazionale finlandese. Per capirci, sono gli stessi di Louis-Michel. Altr\u00e0 \u00e8 un film spassoso, politicamente scorretto, in un bellissimo bianco e nero e quasi muto. \u00a0La trama un semplice pretesto. Durante una colluttazione due vicini di casa finiscono sotto il rimorchio di un trattore (marca Aaltra) che li rende invalidi. Ai due non resta che partire a bordo delle loro sedie a rotelle, alla ricerca della fabbrica di trattori finlandese colpevole di aver costruito il dannato rimorchio. Da non perdere.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #888888;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">mercoled\u00ec 10<\/span><\/span><\/strong><\/span><span style=\"color: #888888;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">\u00a0<\/span><\/span><\/strong><\/span><span style=\"color: #888888;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\"><strong>_ore 21.00<br \/>\n<\/strong><\/span><\/span><\/strong><\/span><em>IL CINEMA GRECO CHE NON TI ASPETTI<br \/>\n<\/em><span style=\"font-size: x-large;\">MACHEROVGALTIS<br \/>\n<\/span>\u00a0di\u00a0Yiannis Economidis\u00a0(Cipro\/Grecia, 2010 108&#8242;,\u00a0orig vers sott ita)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-555 aligncenter\" title=\"macherovgaltis\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/macherovgaltis.jpg\" width=\"250\" height=\"140\" \/><\/p>\n<p style=\"text-align: justify;\">Prosegue il nostro viaggio nel cinema greco e dopo Yorgos Lanthimos, conosciamo\u00a0Yannis Economides\u00a0(Soul Kicking, 2006 e Matchbox (2002).\u00a0Macherovgaltis \u00e8 il suo ultimo film. Racconta la parte malata della Grecia di oggi, descritta come un paese volgare in cui delinquenti e individui meschini vestono i panni di rispettabili cittadini, mentre le persone per bene non trovano posto nella societ\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong><span style=\"color: #ff6600;\"><strong><span style=\"font-size: large;\">gioved\u00ec 11<strong>\u00a0<\/strong><strong>_ore 21.00<br \/>\n<\/strong><\/span><\/strong><\/span><\/strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\"><span style=\"color: #000000;\"><em>SPRING KORINE<\/em><\/span><\/span><\/span><strong><span style=\"color: #ff6600;\"><strong><span style=\"font-size: large;\"><strong><br \/>\n<\/strong><\/span><\/strong><\/span><\/strong><span style=\"font-size: x-large;\">MR. LONELY\u00a0<\/span><br \/>\ndi Harmony Korine \u00a0(Francia 2007, 112&#8242;, eng vers sott ita)<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-556\" title=\"mrlonely\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/mrlonely.jpg\" width=\"250\" height=\"160\" \/><\/p>\n<p style=\"text-align: justify;\">Un giovane americano, che sopravvive esibendosi per le strade di Parigi come sosia di Michael Jackson, un giorno incontra la sosia Marilyn Monroe e la segue fino a una comune in Scozia, nelle Highlands, in cui la donna abita con il marito Charlie Chaplin, la figlia Shirley Temple e varie celebrit\u00e0 &#8211; Madonna, James Dean, il Papa, la Regina d&#8217;Inghilterra e molti altri &#8211; tutte impegnate dell&#8217;allestimento di uno spettacolo teatrale destinato a sbalordire il mondo.\u00a0Imperdibile il cameo del regista Werner Herzog nella parte di un prete eccentrico.<\/p>\n<p align=\"center\"><strong><span style=\"color: #ff6600;\"><strong><span style=\"font-size: large;\"><strong>\u00a0<\/strong><\/span><\/strong><\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff6600;\"><strong><strong><span style=\"font-size: large;\">venerd\u00ec 12\u00a0<strong>\u00a0<\/strong><\/span><strong>_ore 21.00<\/strong><\/strong><\/strong><br \/>\n<\/span><span style=\"font-size: x-large;\">Schermaglie, cinema inOltre<br \/>\n<\/span>serata di proiezioni a cura della redazione della rivista\u00a0<a href=\"http:\/\/Schermaglie.it\/\">Schermaglie.it<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/Schermaglie.it\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-421\" title=\"logo schermaglie\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/02\/logo-schermaglie.jpg\" width=\"341\" height=\"66\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/02\/logo-schermaglie.jpg 341w, https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/02\/logo-schermaglie-300x58.jpg 300w\" sizes=\"(max-width: 341px) 100vw, 341px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/Schermaglie.it\/\"><br \/>\n<\/a><\/p>\n<p style=\"text-align: center;\" align=\"center\"><strong><span style=\"color: #ff6600;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">sabato 13\u00a0<\/span>\u00a0_ore 21.00<br \/>\n<\/span><\/strong><\/span><\/strong>UDON E KAIJU: ALTRE DUE SERATE DEDICATE AL GIAPPONE CHE CI PIACE<br \/>\n<span style=\"font-size: x-large;\">UDON &#8211;\u00a0\u3046\u3069\u3093<br \/>\n<\/span>di Katsuyuki Motohiro\u00a0(Giappone 2006, 134&#8242;, orig\u00a0vers sott ita)<\/p>\n<p style=\"text-align: center;\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-557\" title=\"udon\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/udon.jpg\" width=\"250\" height=\"140\" \/><\/p>\n<p style=\"text-align: justify;\" align=\"center\">E&#8217; un p\u00f2 come se un regista pugliese girasse un film sulle orecchiette e cime di rapa, uno genovese sul pesto e cos\u00ec via. Qui siamo in Giappone, e precisamente nell&#8217;isola di Shikoku e quindi il piatto forte sono gli udon. Chi \u00e8 conosce il Giappone sa che il sushi non \u00e8 il solo piatto tradizionale. Gli udon sono meravigliosi spaghettoni di farina bianca a sezione quadrata che vengono serviti in brodo caldo o freddi, senza condimento e che \u00a0vanno magiati succhiando rumorosamente dalla ciotola. Difficile trovarli qui da noi e quando ci sono non un granch\u00e8. E veniamo al film:\u00a0Kosuke Matsui ha passato sei anni in USA tentando inutilmente di sfondare nel mondo dello spettacolo. Fallito il suo sogno di gloria, ormai al verde, Kosuke \u00e8 costretto a tornare nel suo paese natale, Sanuki, nell&#8217;isola di Shikoku dove la sua famiglia gestisce un piccolo pastificio artigianale di udon. \u00a0<em>Spoiler Alert!<\/em>\u00a0Imperdibile la scena in cui il protagonista sogna di trasformarsi nel supereroe Captain Udon, impegnato nello sgominare una banda di spacciatori di farina!<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: large;\">domenica 14<\/span> _dalle ore 15.30<\/strong><\/span><span style=\"color: #ff6600;\"><strong><br \/>\n<strong><br \/>\nore 15.30_\u00a0<\/strong><\/strong><\/span><span style=\"font-size: x-large;\">CINEBIMBI<\/span><\/p>\n<p align=\"center\">Detour apre alle famiglie: Cinebimbi \u00e8 la fabbrica dei sogni per i pi\u00f9 piccoli e uno spazio di socialit\u00e0 per le loro famiglie. Per info:\u00a0<a href=\"mailto:cinebimbi@gmail.com\">cinebimbi@gmail.com<\/a>\u00a0oppure cell. 3397564720<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #ff6600;\">ore 21.00_<\/span><\/strong>\u00a0\u00a0<span style=\"font-size: x-large;\">BLINKENDE LYGTER <span style=\"font-size: large;\">(Flickering Lights)<\/span><\/span><br \/>\ndi Anders Thomas Jensen\u00a0(Danimarca 2000, 109&#8242;, sott ita)<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" title=\"flickeringlight\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/flickeringlight2.jpg\" width=\"250\" height=\"141\" \/><\/p>\n<p style=\"text-align: justify;\" align=\"center\">Dal regista de &#8220;Le mele di Adamo&#8221;.\u00a0Un gruppo di quattro piccoli delinquenti decide di tenersi il bottino di una rapina su commissione. Per sfuggire alla vendetta del committente, un violento boss chiamato Eskimo, scappano alla volta di Barcellona ma il motore dell&#8217;auto si fonde lungo una strada che attraversa il bosco. Uno di loro \u00e8 ferito e, per poterlo curare, sono costretti a rifugiarsi nel rudere di un vecchio ristorante nel cuore del bosco stesso. Al fine di non destare sospetti, dapprima fingono di voler ristrutturare e riaprire il ristorante poi, progressivamente, il luogo e i loro strambi vicini li conquistano.<\/p>\n<p>\u00a0<span style=\"text-align: center;\">\u00a0<\/span><\/p>\n<p align=\"center\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: large;\">marted\u00ec 16\u00a0<\/span> _ ore 21<br \/>\n<\/strong><\/span><span style=\"font-size: x-large;\">MISTER FREEDOM<br \/>\n<\/span>di\u00a0 William Klein (Francia 1969, 110&#8242;, orig vers sott ita)<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-559\" title=\"misterFteedom\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/misterFteedom.jpg\" width=\"250\" height=\"148\" \/><\/p>\n<p style=\"text-align: justify;\">Mezzo Superman e mezzo James Bond con funzioni di sceriffo a Stelle e Strisce, il colossale Mr. Freedom ha la missione di liberare la Francia corrotta dai Rossi mugichi e dai Gialli di Mao Mao per riportarla nel campo della Civilt\u00e0 Occidentale Bianca. Quando si accorge di non essere amato attua il suo compito a costo di una guerra devastatrice. Secondo una teoria diffusa negli anni &#8217;60 (tornata d&#8217;attualit\u00e0 all&#8217;inizio del 2000), alla radice dell&#8217;imperialismo USA c&#8217;\u00e8 un inappagato bisogno d&#8217;amore. Quello di Klein _ yankee di idee radicali, esule volontario in Francia, fotografo famoso con 3 precedenti cimenti nella regia _ \u00e8 un pamphlet satirico frenetico e caotico di rabbiosa sincerit\u00e0 all&#8217;insegna di una cabarettistica furia iconoclastica. (Morandini)<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: large;\">mercoled\u00ec 17<\/span> _ ore 21<\/strong><\/span><span style=\"font-size: x-large;\"><span style=\"font-size: medium;\"><br \/>\n<\/span>SOUND OF MY VOICE<br \/>\n<\/span>di Zal Batmanglij\u00a0(Usa 2011, 85&#8242;, eng vers sott ita)<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-560\" title=\"SoundOfMyVoice\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/SoundOfMyVoice.jpg\" width=\"250\" height=\"167\" \/><\/p>\n<p style=\"text-align: justify;\">Ambientato nella Los Angeles dei giorni nostri Sound of my Voice descrive una misteriosa setta i cui membri venerano Maggie (la bella Brit Marling di Another Earth), una giovane donna che sostiene di provenire dal futuro. Peter (Christopher Denham) e Lorna (Nicole Vicious) riescono ad infiltrarsi all&#8217;interno del culto con l&#8217;unico obiettivo di smascherare Maggie convinti che sia una ciarlatana. Il tema delle sette new age riletto in una chiave insolita e affascinante: il guru viene dal futuro (sar\u00e0 vero?) ed \u00e8 una donna dolce e bellissima alla quale \u00e8 difficile non credere. Da non perdere.<\/p>\n<p style=\"text-align: center;\"><em>\u00a0<\/em><\/p>\n<p style=\"text-align: center;\"><strong style=\"color: #888888;\"><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">gioved\u00ec 18\u00a0<\/span>\u00a0_ore 21<br \/>\n<\/span><\/strong><span style=\"font-size: x-large;\">INCONTRI DI CINEMA<br \/>\n<\/span>serata con proiezione e dibattito\u00a0a cura di VISIONI<\/p>\n<p style=\"text-align: center;\">Per il programma dettagliato e informazioni:\u00a0<a href=\"http:\/\/forumcinema.blog.tiscali.it\/\">http:\/\/forumcinema.blog.tiscali.it\/<br \/>\n<\/a>Per partecipare agli incontri occorre prenotarsi scrivendo a\u00a0<a href=\"mailto:visioni@gmelies.it\">visioni@gmelies.it<\/a><\/p>\n<p style=\"text-align: center;\"><em>\u00a0<\/em><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"color: #888888;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">venerd\u00ec 19\u00a0<\/span>_ore 20.30<br \/>\n<\/span><\/strong><\/span><em><span style=\"font-size: large;\">PALESTINA PER PRINCIPIANTI<\/span><\/em><br \/>\nCiclo di incontri e proiezioni in collaborazione con<br \/>\nRete Romana di Solidariet\u00e0 con il Popolo Palestinese.<br \/>\nUn ringraziamento a Valeria Belli e Livia Parisi<\/p>\n<p align=\"center\"><strong><span style=\"color: #ff6600;\">ore 20.30_<\/span>\u00a0<\/strong>&#8220;Vittorio Arrigoni&#8221;, un videoreportage di Mario Molinari (2011,22&#8242;)<br \/>\nViaggio a Gaza insieme a Vittorio Arrigoni, pochi giorni prima della sua morte.<\/p>\n<p style=\"text-align: center;\">In collaborazione con Ass. Cult. Euskara e Dip. Lingua e Cultura Basca \/ Upter<br \/>\n<span style=\"color: #ff6600;\"><strong>ore 21.00_<\/strong><\/span>\u00a0<span style=\"font-size: large;\"><span style=\"font-size: x-large;\">CHECKPOINT ROCK.<\/span> SONGS FROM PALESTINE<br \/>\n<\/span>di Fermin Muguruza\u00a0(Spagna\/Paesi Baschi \u00a02009, 73\u2019, orig vers sott ita)<br \/>\nIntroduce Adriano Cirulli di Ass. Cult. Euskara<\/p>\n<p style=\"text-align: center;\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-495\" title=\"check_point_rock_muguruza\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/check_point_rock_muguruza.jpg\" width=\"250\" height=\"220\" \/><\/p>\n<p style=\"text-align: justify;\" align=\"center\">Uno straordinario documentario firmato da Fermin Muguruza,\u00a0personaggio tra i pi\u00f9 influenti e carismatici del panorama musicale basco,\u00a0cantante e musicista militante degli\u00a0storici gruppi Kortatu e Negu Gorriak.\u00a0Il film, che mette in luce i talenti della scena musicale contemporanea palestinese, inizia con il musicista Marcel Khalife ai funerali del famoso poeta palestinese Mahmoud Darwish e attraversa quindi la Palestina \/ Israele, mostrando una vasta gamma di esperienze musicali lungo il percorso. Rapper, cantanti di matrimonio e musicisti tradizionali esprimono le loro lotte attraverso la musica.\u00a0Checkpoint Rock cambier\u00e0 la visione che abbiamo di un popolo sotto occupazione.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #888888;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">sabato 20\u00a0<\/span>_ore 21.00<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: x-large;\">LA CITTA&#8217; DELLE DONNE OGGI<br \/>\n<\/span>Storie di ragazze e dell&#8217;uso del loro corpo nell&#8217;Italia attuale<br \/>\ndi Chiara Sambuchi<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"><span style=\"font-family: Arial, sans-serif;\">a seguire incontro con<\/span><span style=\"font-family: Arial, sans-serif;\"><strong>\u00a0<\/strong><strong><br \/>\n<\/strong><\/span><\/span>Chiara Sanbuchi (regista),\u00a0Nicole Leghissa (co-produttrice)<br \/>\nNicoletta Dentico<strong>\u00a0<\/strong>(Se Non Ora Quando)<\/p>\n<p style=\"text-align: justify;\">&#8220;Ogni donna \u00e9 bella, ogni donna \u00e9 giovane! Amo le mie rughe e non ho paura di invecchiare!&#8221; Da queste parole, gridate e cantate insieme da centinaia di figure femminili in una scena del film &#8220;La citt\u00e0 delle donne&#8221; (Fellini,1981), \u00e8 nata l&#8217;idea del documentario &#8220;La citt\u00e0 delle donne, oggi&#8221;, in cui la regista Chiara Sambuchi ha seguito le vite di quattro figure femminili italiane la cui biografia \u00e9 strettamente legata al corpo. Per capire perch\u00e9, 30 anni dopo il film di Fellini, l&#8217;immagine della femminilit\u00e0 in Italia sia cos\u00ec profondamente cambiata. C&#8217;\u00e8 Mary che vorrebbe fare l&#8217;attrice di teatro ma \u00e8 costretta a vivere con pubblicit\u00e0 di completini sexy e a 29 anni pensa all&#8217;inseminazione artificiale. C&#8217;\u00e8 Claudia (Kohl) che ha raggiunto il successo facendo spettacolo del proprio corpo, ma oggi cerca se stessa con un cammino radicalmente opposto. C&#8217;\u00e8 Katja, cubista ed ex coinquilina di Ruby, che pensa di approfittare della fama che le \u00e8 derivata dallo scandalo nazionale, ma non sa spiegare la sua infelicit\u00e0. E poi c&#8217;\u00e8 Marina, ginecologa impegnata, ex sessantottina figurante ne &#8220;La citt\u00e0 delle donne&#8221; di Fellini, con uno struggente rimpianto per gli anni di cui \u00e8 stata protagonista. Le loro storie si intrecciano con quella della regista Chiara Sambuchi che, nel suo viaggio per l&#8217;Italia alla ricerca della \u201ccitt\u00e0 delle donne\u201d, incontra diversi esponenti\u00a0del mondo femminile attuale tra cui le &#8220;nuove femministe&#8221; del movimento &#8220;Se non ora quando&#8221;, la direttrice\u00a0di Vogue Franca Sozzani, Tenera Valse, prostituta romana ed ex insegnante di latino e greco e Renza Bellini, una chirurga estetica bolognese un po&#8217; speciale. Da regista, Sambuchi diventa una delle protagoniste del film nell&#8217;incontro finale con la sua famiglia in cui, da generazioni, nascono\u00a0solo donne.<br \/>\n<span style=\"font-size: medium;\">Trailer<\/span>:\u00a0<a style=\"font-family: Arial, sans-serif;\" href=\"http:\/\/vimeo.com\/44541780\" target=\"_blank\">http:\/\/vimeo.com\/44541780<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #ff6600;\"><span style=\"font-size: large;\">domenica 21\u00a0<\/span> _ore 21.00<br \/>\n<\/span><\/strong><span style=\"color: #ff6600;\"><span style=\"color: #000000;\">in collaborazione con Ass. Cult. Euskara e Dip. Lingua e Cultura Basca \/ Upter\u00a0<\/span><\/span><span style=\"font-size: x-large;\">BARRURA BEGIRATZEKO LEIHOAK <\/span><span style=\"font-size: x-large;\"><span style=\"font-size: large;\">(Finestre sull\u2019interno)<\/span><br \/>\n<\/span>di Josu Martinez, Eneko Olasagasti, MireiaGabilondo, Enara Goikoetxea, Txaber Larreategi (Spagna\/Paesi Baschi 2012, 95&#8242;)<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-563\" title=\"barruraBegiratzeko\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/barruraBegiratzeko1.jpg\" width=\"250\" height=\"139\" \/><\/p>\n<p style=\"text-align: justify;\">Questo lungometraggio sul mondo dei prigionieri politici baschi \u00e8 formato da cinque piccole storie indipendenti, diretto da 5 registi baschi che hanno voluto umanizzare una realt\u00e0 sociale spesso mistificata dai mezzi di comunicazione ufficiali. L\u2019obiettivo \u00e8 quello di raccontare le persone che troppo spesso vengono occultate dietro lo status di prigioniero. Il titolo gioca con l\u2019immagine cinematografica della finestra aperta con un duplice significato: per guardare all\u2019interno del carcere ma anche all\u2019interno di ogni ognuno.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: medium;\"><span style=\"font-size: large;\">marted\u00ec 23 \/ mercoled\u00ec 24\u00a0<\/span>_ore 21<br \/>\n<\/span><\/strong><\/span><span style=\"font-size: x-large;\">DOC.ARTE\u00a0<span style=\"font-size: medium;\">DOCUMENTARIO D\u2019ARTE &gt; D\u2019ARTISTA<\/span><\/span><br \/>\nCiclo di proiezioni di materiale raro e inedito<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-517\" title=\"pollock1\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/pollock1.jpg\" width=\"249\" height=\"158\" \/><\/p>\n<p><em><span style=\"font-size: small;\">In tutta la storia dell\u2019arte, i casi in cui un artista ha rappresentato un altro artista al lavoro sono piuttosto rari, Rosalind Krauss<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Doc.Arte, un ciclo di proiezioni dedicato al documentario d\u2019arte e d\u2019artista. In programma: il film, tra documentario e video d\u2019arte, l\u2019autoritratto filmato, l\u2019auto-documentazione video, la documentazione di eventi e mostre del passato, il documentario sociale d\u2019artista, e il documentario sull\u2019arte tradizionale. I nomi: Mario Ceroli, Willem de Kooning, Jonas Mekas, Hans Namuth, Jackson Pollock, Mario Schifano, Andy Warhol. E ancora: Jacopo Benci, Robert Cahen, Aude Fourel, Silvia Stucky, collettivo ranelettrike (Cristina Nist e Sergio Ponzio), Sergio Ponzio. Introduce Cristina Nistic\u00f2 (Storico dell\u2019Arte).<\/p>\n<p style=\"text-align: center;\"><strong>23 aprile _ ore 21.00<\/strong><br \/>\nBill Viola, Ancient of Days, 1979 (12\u2019)<br \/>\nRobert Cahen, <em>Voyage d\u2019hiver<\/em>, 1993 (18\u2019)<br \/>\nRanelettrike, <em>Robert Cahen<\/em>, 2011 (10\u2019)<br \/>\nAude Fourel, <em>\u00c0 travers Rome (Attraversare Roma)<\/em>, 2013 (20\u2019)<br \/>\nSergio Ponzio, <em>Mario Schifano<\/em>, 2007 (4\u2019)<br \/>\n<em>A seguire incontro con gli artisti Aude Fourel, Cristina Nist, Sergio Ponzio.<\/em><\/p>\n<p style=\"text-align: center;\"><strong>24 aprile _ ore 21.00<\/strong><br \/>\nHans Namuth, <em>Pollock<\/em> <em>\u201951<\/em>, 1951 (12\u2019)<br \/>\nHans Namuth, <em>De Kooning<\/em>, 1964 (11\u2019)<br \/>\nAndy Warhol, <em>Inaugurazione Ultima Cena, Palazzo delle Stelline, Milano<\/em>, 22\/1\/1987\u00a0(8\u2019)<br \/>\nRanelettrike, <em>Jonas Mekas<\/em>, 2008 (10\u2019)<br \/>\nJacopo Benci, Passaggi \u2013 Durchg\u00e4nge, 2011 (4\u201949\u201d)<br \/>\nSilvia Stucky, Le jardin int\u00e9rieur, 2007 (6\u2019)<br \/>\n<em>A seguire incontro con gli artisti Jacopo Benci, Silvia Stucky.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: medium;\"><span style=\"font-size: large;\">gioved\u00ec 25<\/span>\u00a0<\/span>_ore 21.00<br \/>\n<\/strong><\/span><span style=\"font-size: large;\">BUONA LIBERAZIONE<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span><strong><span style=\"font-size: large; color: #ff6600;\">\u00a0venerd\u00ec 26_ <span style=\"font-size: medium;\">ore 19.30<\/span>\u00a0<\/span><\/strong><span><strong><span style=\"color: #ff6600;\">\u00a0\/<\/span><\/strong>\u00a0<\/span><\/span><strong><span style=\"color: #ff6600; font-size: large;\">Friday 26th _\u00a0<span style=\"font-size: medium;\">7.30 p.m.<br \/>\n<\/span><\/span><\/strong>Friends in Rome &amp; Detour present<br \/>\n<span style=\"font-size: x-large;\">CINE FRIENDS<br \/>\n<\/span>The best Italian movies, not only pizza, spaghetti and mandolino&#8230;<br \/>\nAll movies are shown in Italian with English subtitles.<br \/>\nSerata di proiezione di cinema italiano sottotitolato in inglese.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" title=\"cinefriends\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/cinefriends1.jpg\" width=\"250\" height=\"167\" \/><\/p>\n<p align=\"center\"><span style=\"color: #ff6600;\"><strong>h7.30 p.m.\u00a0<\/strong><\/span>Meeting time<br \/>\nA chance to socialize and network while mingling with an international crowd.<\/p>\n<p align=\"center\"><span style=\"color: #ff6600;\"><strong>h9.00 p.m.<\/strong>\u00a0<\/span>Screening \/ proiezione<br \/>\nPer il programma dettagliato, info e prenotazioni\/<br \/>\nFor further information and reservation please:\u00a0cinedetour@tiscali.it<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><span style=\"color: #ff6600;\"><strong><span style=\"font-size: large;\">sabato 27\u00a0<\/span>_ore 21.00<br \/>\n<\/strong><\/span>UDON E KAIJU: ALTRE DUE SERATE DEDICATE AL GIAPPONE CHE CI PIACE<br \/>\n<span style=\"font-size: x-large;\">GANTZ<br \/>\n<\/span>\u00a0di \u00a0Shinsuke Sato\u00a0(Giappone 2010, 130&#8242;, orig vers sott ita)<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-564\" title=\"Gantz\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/Gantz.jpg\" width=\"250\" height=\"166\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0In piedi in una stazione della metropolitana\u00a0Kurono si appresta ad andare ad un colloquio di lavoro. Ad un tratto nota sul marciapiede un suo vecchio compagno ed amico delle scuole elementari, Kato; questi tenta di salvare un uomo che \u00e8 caduto improvvisamente sui binari. I due riescono a prestargli soccorso ma, proprio in quel momento, un treno sta accelerando all&#8217;interno della stazione. I due sembrano essere destinati a morire, invece si ritrovano in una stanza misteriosa in compagnia con altre persone. In questa stanza \u00a0c&#8217;\u00e8 \u00a0una sfera nera chiamata Gantz. Se il gruppo vuole vivere deve obbedire agli ordini di Gantz. Il primo ordine \u00e8 vestirsi con delle attillate tute nere, armarsi di tutto punto e&#8230;andare a caccia di demenziali quanto cattivissimi alieni. Il film \u00e8 fracassone, divertente, idiota, fantascientifico, spesso incomprensibile ma, vi garantiamo, tiene incollati allo schermo per tutti i suoi 130 minuti. Se avete amato BIG MAN JAPAN, non perdetelo!<\/p>\n<p align=\"center\"><span style=\"color: #ff6600;\"><br \/>\n<\/span><\/p>\n<p align=\"center\"><span><strong style=\"color: #ff6600;\"><span style=\"font-size: large;\">\u00a0domenica 28\u00a0<strong>_ore 21.00<br \/>\n<\/strong><\/span><\/strong><\/span><em>SPRING KORINE<br \/>\n<\/em><span style=\"font-size: x-large;\">MR. LONELY<br \/>\n<\/span>di Harmony Korine \u00a0(Francia 2007, 112&#8242;, orig vers sott ita)<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" title=\"mrlonely\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/mrlonely.jpg\" width=\"250\" height=\"160\" \/><\/p>\n<p style=\"text-align: justify;\">Un giovane americano, che sopravvive esibendosi per le strade di Parigi come sosia di Michael Jackson, un giorno incontra la sosia Marilyn Monroe e la segue fino a una comune in Scozia, nelle Highlands, in cui la donna abita con il marito Charlie Chaplin, la figlia Shirley Temple e varie celebrit\u00e0 &#8211; Madonna, James Dean, il Papa, la Regina d&#8217;Inghilterra e molti altri &#8211; tutte impegnate dell&#8217;allestimento di uno spettacolo teatrale destinato a sbalordire il mondo.\u00a0Imperdibile il cameo del regista Werner Herzog nella parte di un prete eccentrico.<\/p>\n<p style=\"text-align: justify;\" align=\"center\"><span><strong style=\"color: #ff6600;\"><span style=\"font-size: large;\"><strong>\u00a0<\/strong><\/span><\/strong><\/span><\/p>\n<p align=\"center\"><span><strong style=\"color: #ff6600;\"><span style=\"font-size: large;\">marted\u00ec 30\u00a0<strong><strong>_ore 21.00<br \/>\n<\/strong><\/strong><\/span><\/strong><\/span><span style=\"font-size: x-large;\">THE DREAMS THAT MONEY CAN BUY<br \/>\n<\/span>di Hans Richter (USA 1947, 85&#8242;, orig vers sott ita)<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-565\" title=\"DreamsThatMoneyCanBuy\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/03\/DreamsThatMoneyCanBuy.jpg\" width=\"250\" height=\"162\" \/><\/p>\n<p style=\"text-align: justify;\">6 episodi che corrispondono ad altrettanti sogni, immaginati da cinque artisti (Max Ernst, Fernand L\u00e9ger, Man Ray, Marcel Duchamp, Alexander Calder) e dallo stesso H. Richter (1888-1976), pittore dadaista e regista di film sperimentali, autore anche della sceneggiatura e delle scene insieme a Max Ernst e Jack Bittner. 1 ep. (M. Ernst): un uomo cerca di avvicinarsi a una fanciulla dormiente, circondata da sbarre; 2 ep. (F. L\u00e9ger): balletto di manichini in abiti nuziali in un emporio di New York; 3 ep. (Man Ray): parodia satirica dell&#8217;ambiente di Hollywood; 4 ep. (M. Duchamp): dischi ottici a due dimensioni che, messi in movimento, ne acquistano una terza; 5 ep. (A. Calder): sfere, unite da fili e asticelle, si muovono con le loro ombre su uno sfondo bianco; 6 ep. (H. Richter): Narciso, uomo comune (J. Bittner), scopre per caso di essere differente da ci\u00f2 che immaginava di essere. Le musiche sono nell&#8217;ordine di Paul Bowles, Libby Holman e John Latouche, Darius Milhaud, John Cage, Edgar Var\u00e8se. E un compendio del cinema surrealista e astratto che, pur nell&#8217;eterogeneit\u00e0 dei contributi, ha una sua coerenza di atmosfera. Prodotto no budget (10000 dollari del dopoguerra), fu esposto all&#8217;8a Mostra di Venezia dove ebbe un premio per il &#8220;contributo originale al progresso della cinematografia&#8221;. Fotografia di Arnold Eagle. (Morandini)<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff; font-size: large;\">E&#8217; ONLINE il BANDO DI PARTECIPAZIONE\u00a0<\/span><\/strong><\/p>\n<p style=\"text-align: center;\">al primo festival del corto ideato e curato da ragazzi con sindrome di Asperger<br \/>\n<a href=\"http:\/\/www.asfilmfestival.org\/it\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"logoAS\" alt=\"\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/02\/logoAS.jpg\" width=\"250\" height=\"127\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong>UN FESTIVAL UGUALE AGLI ALTRI. PERO&#8217; DIVERSO<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cineclub Detour<\/span> e Studio Kilab, con la collaborazione del Gruppo Asperger Onlus, il sostegno dall\u2019Agenzia Nazionale per i Giovani nell\u2019ambito del programma comunitario Giovent\u00f9 in Azione presentano, <span style=\"color: #333399;\"><strong>ASFF &#8211; AS FILM FESTIVAL 2013<\/strong><\/span> \u00e8 il primo festival del cortometraggio nato per volont\u00e0 di alcuni giovani con sindrome di Asperger, una condizione autistica ad alto funzionamento.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #333399;\">ASFF<\/span><\/strong> Non \u00e8 un festival sull\u2019autismo, ma un festival cinematografico vero e proprio, fatto da persone con autismo. Come in qualunque altro festival sono previste proiezioni, incontri, ospiti, una giuria, dei premi. Insomma, un festival uguale agli altri. Per\u00f2 diverso.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #333399;\">ASFF<\/span><\/strong> prevede due sezioni competitive ed una vetrina speciale:<\/p>\n<p style=\"text-align: justify;\"><em>Sezione 1: PUNTI DI VISTA<\/em> &#8211; Il cinema come punto di vista sulla realt\u00e0, come strumento per documentare e comunicare il sociale; il cortometraggio come sguardo personale sul mondo e sulla quotidianit\u00e0; il video come mezzo per raccontare e raccontarsi. Non ci sono limiti di genere per questa sezione, ma saranno favorite opere narrative e corti di facile comprensibilit\u00e0. Possono concorrere a questa sezione i lavori realizzati dopo gennaio 2011 da autori under 30. Le opere non devono superare i 20 minuti di durata.<\/p>\n<p style=\"text-align: justify;\"><em>Sezione 2: RAGIONEVOLMENTE DIFFERENTI<\/em> &#8211; Una sezione dedicata ai filmaker con Sindrome di Asperger o con Disturbi pervasivi dello Sviluppo e, pi\u00f9 in generale, ad opere che raccontino storie legate alla Condizione dello Spettro Autistico. Non sono previsti limiti di durata, genere e tecnica e possono partecipare autori di tutte le et\u00e0.<\/p>\n<p style=\"text-align: justify;\">LA VETRINA: Cinque anni di CINEMAUTISMO \u2013 Per festeggiare i cinque anni della rassegna curata da Marco Mastino e Ginevra Tomei per l\u2019Associazione Museo Nazionale del Cinema di Torino, saranno proposti, per la prima volta a Roma, alcuni tra i titoli pi\u00f9 significativi della manifestazione torinese.<\/p>\n<p style=\"text-align: justify;\">Il regolamento per partecipare al festival e il modulo di iscrizione da compilare online sono sul sito del festival: <a href=\"http:\/\/www.asfilmfestival.org\">www.asfilmfestival.org<\/a><\/p>\n<p style=\"text-align: justify;\">Il bando di partecipazione scade il <span style=\"color: #333399;\">15 maggio 2013.\u00a0<\/span><\/p>\n<p>Le giornate conclusive del festival si svolgeranno nella prima met\u00e0 di giugno 2013.<\/p>\n<p style=\"text-align: center;\">per informazioni:<br \/>\nweb:\u00a0<a href=\"http:\/\/www.asfilmfestival.org\">www.asfilmfestival.org<\/a><br \/>\nFb: <a href=\"http:\/\/www.facebook.com\/pages\/ASFF-AS-FILM-FESTIVAL-2013-un-festival-uguale-agli-altri-per%C3%B2-diverso\/130068117066656?ref=hl\">ASFF &#8211; AS FILM FESTIVAL<\/a><br \/>\nmail: info@asfilmfestival.org<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cineclub Detour @ Oasi Urbana &#8211; Via Urbana 107 Roma www.cinedetour.it&#8211; cinedetour@tiscali.it Proiezioni riservate ai soci dell&#8217;associazione culturale Detour. Ingresso con tessera associativa annuale 7\u20ac (soci arci: 5\u20ac) \/ ingressi successivi a sottoscrizione Cineclub Detour \u00e8 affiliato alla FICC (Federazione Italiana Circoli Cinema) For members only.\u00a0Admission: annual membership 7\u20ac \/ free subscription (arci members: 5\u20ac) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[6,874,9,4],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 22:51:37","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/510"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=510"}],"version-history":[{"count":19,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/510\/revisions"}],"predecessor-version":[{"id":1245,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/510\/revisions\/1245"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}