{"id":5331,"date":"2015-05-07T20:45:46","date_gmt":"2015-05-07T19:45:46","guid":{"rendered":"https:\/\/cinedetour.it\/?p=5331"},"modified":"2015-05-07T23:00:14","modified_gmt":"2015-05-07T22:00:14","slug":"gio-7-mag-cut-di-amir-naderi-a-cura-di-too-much-ciro-una-manifestazione-di-e-per-ciro-giorgini","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2015\/05\/07\/gio-7-mag-cut-di-amir-naderi-a-cura-di-too-much-ciro-una-manifestazione-di-e-per-ciro-giorgini\/","title":{"rendered":"gio 7 mag CUT di Amir Naderi [ Too Much Ciro&#8230; una manifestazione di e per Ciro Giorgini ]"},"content":{"rendered":"<p align=\"center\"><span style=\"font-size: 18pt\">\u00a0CINEMA DETOUR VIA URBANA 107 ROMA<\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 18pt\">gioved\u00ec 7 maggio\u00a02015 ore 21.00<\/span><\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: center\"><span style=\"color: #993300;font-size: 10pt\">a cura di<\/span><\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: 12pt;color: #993300\">Officina Film Club Fuori Orario e Casa del Cinema di Roma<\/span><\/strong><\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: 12pt;color: #993300\">con Cineteca del Friuli, Gemona e Cinemazero Pordenone<\/span><\/strong><\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: center\"><span style=\"font-size: 10pt;color: #993300\">in collaborazione con Cineteca Nazionale &#8211; Cinema Trevi, Palaexpo, Cinema Detour, <br \/>Cinema dei Piccoli, Cineteca D.W.Griffith (Genova), La Farfalla sul Mirino, <br \/>Filmstudio, Formacinema, Redazione Blob, Ripley\u2019s Home Video<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p align=\"center\">\u00a0<\/p>\n<p align=\"center\"><span style=\"font-size: 24pt\"><strong><span style=\"color: #993300\">TOO MUCH\u00a0<\/span><\/strong><span style=\"color: #993300\"><strong>CIRO&#8230;<\/strong><\/span><\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 14pt;color: #993300\">Welles 100 anni (di magnifiche ossessioni)<\/span><\/p>\n<p align=\"center\"><span style=\"color: #993300\"><span style=\"font-size: 14pt\">Una manifestazione di e per\u00a0<\/span><span style=\"font-size: 24pt\">Ciro Giorgini<\/span><\/span><\/p>\n<p align=\"center\"><span style=\"font-size: 12pt;color: #993300\">presenta<\/span><\/p>\n<div>\n<div title=\"Page 1\">\n<p style=\"text-align: center\"><span style=\"font-size: xx-large\"><span style=\"font-size: medium\"><span style=\"font-size: large\">\u00a0<\/span><\/span><\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 36pt\">CUT<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: medium\"><span style=\"font-size: 14pt\">di Amir Naderi\u00a0(Giappone 2011, 133&#8242;), v.o. sott. italiano<\/span><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt\">Il regista pi\u00f9 \u201capolide\u201d che ci sia cambia ancora una volta nazione, anche se solo per un film. Nato in Iran, \u201cadottato\u201d da vent\u2019anni dalla sua adorata New York e oggi volato in Giappone per esplorare nuove possibilit\u00e0 dopo la sua trilogia newyorchese e l&#8217;ottimo Vegas: Based on a True Story, Amir Naderi \u00e8 sicuramente uno dei registi pi\u00f9 interessanti, stimolanti e spesso geniali in circolazione. <\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt\">Il suo bisogno di cinema \u00e8 fortissimo, fisico, viscerale, \u00e8 questo suo Cut ne \u00e8 la traduzione metaforica. <br \/><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt\">Non si fa fatica infatti a vedere lo stesso Naderi incarnato nel suo protagonista, film-maker d&#8217;insuccesso, organizzatore di cineforum e profeta dell&#8217;apocalisse filmica che gira per le strade di Tokyo gridando al megafono che il Cinema sta morendo, ucciso dall&#8217;assenza dell&#8217;Arte, e che il cinema di oggi \u00e8 una puttana che si svilisce e umilia nel nome del solo intrattenimento.\u00a0<\/span><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/04\/cut-naderi_detour_giorgini_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5335\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/04\/cut-naderi_detour_giorgini_1.jpg\" alt=\"cut-naderi_detour_giorgini_1\" width=\"700\" height=\"989\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/04\/cut-naderi_detour_giorgini_1.jpg 700w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/04\/cut-naderi_detour_giorgini_1-212x300.jpg 212w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 10pt\">Shuji \u00e8 un regista indipendente che da qualche anno non riesce a realizzare opere personali, pertanto, persegue l&#8217;idea di sensibilizzare i suoi concittadini al cinema migliore, di cui auspica un ritorno e per la cui causa prega anche sulle tombe di Akira Kurosawa, Kenji Mizoguchi e Yasujiro Ozu. Passa le giornate facendo volantinaggio per strada, ammonendo con un megafono le persone che non hanno riguardo n\u00e9 interesse per la vera arte, rimpiangendo una storia del cinema dimenticata, composta da grandi e insostituibili maestri: infine, di sera, nel terrazzino del suo minuscolo loft, nell&#8217;attico di un palazzo, organizza un cineforum da lui stesso introdotto. Le scene con Shuji che fa propaganda cinefila e corre per le strade di Tokyo ci informano anche di un disagio sociale che proietta il fondale socio-politico verso una realt\u00e0 repressiva, da stato di polizia, da cui il giovane regista \u00e8 costretto a ripararsi. La militanza cinefila arriva a una svolta estrema quando Shuji scopre che suo fratello, uno strozzino che si \u00e8 indebitato per finanziare i suoi film, \u00e8 stato giustiziato da una banda affiliata alla yakuza, per non aver pagato quanto doveva. Il debito, maggiorato, pesa ora sulla testa di Shuji stesso&#8230;<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666699\"><em><span style=\"font-size: 10pt\">A man is willing to sacrifice his body for the sake of the art that feeds his soul in this unusual drama from director Amir Naderi. Shuji (Hidetoshi Nishijima) is an independent filmmaker who is a fervent believer in what he calls &#8220;pure cinema,&#8221; and loathes commercial movies that are made to satisfy the lowest common denominator without engaging the creative spirit. When he isn&#8217;t trying to put his next project together, Shuji is lecturing passer-bys about important films and hosting screenings <span id=\"movieSynopsisRemaining\">of cherished classics on the roof of a building. After Shuji&#8217;s brother, who helped bankroll his movies, turns up dead, the filmmaker makes a shocking discovery &#8212; his brother borrowed the money from a loan shark, and his failure to pay caused gangsters to murder him. Mobster Masaki (Shun Sugata) tells Shuji it&#8217;s up to him to pay off the loan; the film buff doesn&#8217;t have the cash, so instead he arranges for the gangsters to pummel him for the amusement of others for ten days, using his passion for cinema as a distraction to get him through the experience. A collaboration between an Iranian director and a Japanese cast and crew, Cut was an official selection at the 2011 Toronto International Film Festival. (Rotten Tomatoes)<\/span><\/span><\/em><\/span><\/p>\n<p style=\"text-align: center\">***<\/p>\n<p align=\"center\"><span style=\"font-size: 14pt\"><strong>TOO MUCH\u00a0<\/strong><strong>CIRO&#8230;\u00a0<\/strong>Welles 100 anni (di magnifiche ossessioni)\u00a0Una manifestazione di e per\u00a0Ciro Giorgini<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 10pt\">La scomparsa di Ciro Giorgini, avvenuta poche settimane fa, si sta rivelando pi\u00f9 dura da sopportare, non solo per i familiari, ma anche per gli amici e gli appassionati di cinema che lo hanno conosciuto in questi anni. Questa manifestazione si sarebbe dovuta svolgere lo scorso maggio 2014; dopo l\u2019anteprima alle Giornate del Cinema Muto di Pordenone, con Ciro avevamo ipotizzato una proiezione di Too much Johnson all\u2019Anteo di Milano e, in contemporanea, al Teatro Argentina di Roma; mentre a Milano la proiezione ebbe luogo, difficolt\u00e0 burocratiche impedirono quella di Roma; pur consapevoli tutti, Ciro per primo, del suo stato di salute, rimandammo, quasi scaramanticamente, a settembre\/ ottobre 2014 l\u2019idea della replica romana, accompagnata da altri materiali di e intorno a Welles; purtroppo, anche in quella occasione, la proiezione non siamo riusciti a farla nei tempi previsti e stabiliti&#8230; Allora abbiamo fatto qualcosa di pi\u00f9: abbiamo lavorato negli ultimi mesi con lui a questa manifestazione, cos\u00ec come vi si presenta oggi, film per film, titolo per titolo, giorno dopo giorno, fino al the end. Per noi \u00e8 stato un grande privilegio, per Ciro il suo modo di salutare gli amici e fare un regalo a Roma. [l\u2019Officina Film Club &#8211; Cristina Torelli, Paolo Luciani]<\/span><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/05\/ciro-copia.pdf\"><span style=\"font-size: 14pt;color: #993300\"><strong>scarica la brochure\u00a0con il programma completo delle proiezioni<\/strong><\/span><\/a><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-5332\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/04\/ciro_giorgini_detour.jpg\" alt=\"ciro_giorgini_detour\" width=\"219\" height=\"308\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/04\/ciro_giorgini_detour.jpg 400w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/04\/ciro_giorgini_detour-213x300.jpg 213w\" sizes=\"(max-width: 219px) 100vw, 219px\" \/><\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 10pt\"><span style=\"text-align: center\">***<\/span><\/span><\/p>\n<\/div>\n<div style=\"text-align: center\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1283 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"130\" height=\"127\" \/><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: small\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Teatro | Produzione Distribuzione Editoria indipendente<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: small\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p>Tutti i film sono proiettati in lingua originale con sottotitoli in italiano. <br \/>Ingresso: tessera annuale 3\u20ac + quota partecipativa 5\u20ac<\/p>\n<p style=\"text-align: center\"><em><span style=\"font-size: small\">Art-house cinema in Downtown Rome since 1997. <br \/>All movies are screened in their original languages with italian and\/or english subtitles<\/span><\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Shuji \u00e8 un regista indipendente che da qualche anno non riesce a realizzare opere personali, pertanto, persegue l&#8217;idea di sensibilizzare i suoi concittadini al cinema migliore, di cui auspica un ritorno e per la cui causa prega anche sulle tombe di  Kurosawa, Mizoguchi e Ozu. Passa le giornate facendo volantinaggio per strada, ammonendo con un megafono le persone che non hanno riguardo n\u00e9 interesse per la vera arte, rimpiangendo una storia del cinema dimenticata, composta da grandi e insostituibili maestri: infine, di sera, nel terrazzino del suo minuscolo loft, nell&#8217;attico di un palazzo, organizza un cineforum da lui stesso introdotto. La militanza cinefila arriva a una svolta estrema quando Shuji scopre che suo fratello, uno strozzino che si \u00e8 indebitato per finanziare i suoi film, \u00e8 stato giustiziato dalla yakuza, per non aver pagato quanto doveva. Il debito, maggiorato, pesa ora sulla testa di Shuji stesso&#8230; Il regista pi\u00f9 \u201capolide\u201d che ci sia cambia ancora una volta nazione, anche se solo per un film. Nato in Iran, \u201cadottato\u201d da vent\u2019anni dalla sua adorata New York e oggi volato in Giappone per esplorare nuove possibilit\u00e0 dopo la sua trilogia newyorchese e l&#8217;ottimo Vegas: Based on a True Story, Amir Naderi \u00e8 sicuramente uno dei registi pi\u00f9 interessanti, stimolanti e spesso geniali in circolazione.<\/p>\n","protected":false},"author":2,"featured_media":5333,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376],"tags":[533,536,293,534,537,535],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-14 00:21:57","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/5331"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=5331"}],"version-history":[{"count":7,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/5331\/revisions"}],"predecessor-version":[{"id":5430,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/5331\/revisions\/5430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/5333"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=5331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=5331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=5331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}