{"id":6090,"date":"2016-02-25T20:30:20","date_gmt":"2016-02-25T19:30:20","guid":{"rendered":"https:\/\/cinedetour.it\/?p=6090"},"modified":"2016-02-26T09:22:55","modified_gmt":"2016-02-26T08:22:55","slug":"9-ott-corn-island-di-george-ovashvili-short-list-migliori-film-stranieri-oscar-2014","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2016\/02\/25\/9-ott-corn-island-di-george-ovashvili-short-list-migliori-film-stranieri-oscar-2014\/","title":{"rendered":"CORN ISLAND di George Ovashvili. Nuovo Cinema Georgiano. Ultima proiezione!"},"content":{"rendered":"<p class=\"sinossieng\"><span style=\"font-size: 12pt;\"><em>in collaborazione con\u00a0CINEAMA<\/em>\u00a0<\/span><\/p>\n<p class=\"sinossieng\"><span style=\"font-size: 14pt;\"><em>Short List dieci migliori film stranieri Oscar 2014<\/em><\/span><\/p>\n<p class=\"sinossieng\"><strong><span style=\"font-size: 12pt;\">giov 25\u00a0febbraio\u00a0ore\u00a020.30<\/span><\/strong><\/p>\n<p><span style=\"font-size: 36pt;\">CORN ISLAND<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>di\u00a0George Ovashvili<\/strong><\/span><br \/><span style=\"font-size: 12pt;\"><em>Georgia\u00a02014, 98\u2019, orig vers, sott ita<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><em><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/09\/Corn-Island_detour1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6007\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/09\/Corn-Island_detour1.jpg\" alt=\"Corn-Island_detour1\" width=\"800\" height=\"533\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/09\/Corn-Island_detour1.jpg 800w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/09\/Corn-Island_detour1-300x199.jpg 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/em><em><br \/><\/em><\/span><\/p>\n<p>Sul fiume che segna il confine naturale e contrastato tra l&#8217;Abkhazia e la Georgia, isole itineranti si formano e si disfano a seconda delle stagioni e dei capricci degli elementi. Avventurosamente, un vecchio contadino e sua nipote si installano su questa terra di nessuno, per coltivarvi il necessario per sopravvivere all&#8217;inverno, ma i pericoli sono molteplici.<\/p>\n<p>Quando non sono i conflitti armati, e\u0300 la natura che minaccia di riacquistare i propri diritti scatenando il fiume, e l&#8217;arrivo di un militare ferito e ricercato turba il delicato equilibrio della coppia.<\/p>\n<p>Corn Island e\u0300 tutto questo ed altro. E\u0301 un&#8217;opera cinematografica di struggente bellezza in cui si mescolano e si uniscono temi e problematiche differenti tra loro: il costante ed infinito rapporto conflittuale tra uomo e Natura, le rivalita\u0300 etniche e geopolitiche e il tumultuoso sviluppo dell&#8217;adolescenza.<\/p>\n<p>Hanno detto del film:<\/p>\n<p>Una contemplazione poetica sull&#8217;umanita\u0300. &#8211; Twitchfilm<\/p>\n<p>Il regista georgiano tesse una potente fiaba di vita e di morte con ingredienti semplici, quasi senza parole. \u2212 The Hollywood Reporter<\/p>\n<p>Il film di Ovashvili riesce ad essere sorprendentemente coerente e omogeneo, ogni suo aspetto e\u0300 sotto il suo controllo.<br \/>\u2212 Screendaily<\/p>\n<p>Un film ruvido e duro, pieno di spigoli, come le vite dei protagonisti persi su un&#8217;isola effimera.<br \/>\u2212 La Terre e\u0301phe\u0301me\u0301re \u2013 la critique\u00a0<\/p>\n<p>\u00c8 con la poesia delle piccole cose semplici e antiche che il regista georgiano Ovashvili compone il suo film.\u00a0<br \/>&#8211; Schermaglie.it<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #666699; font-size: 10pt;\"><em>ENG.\u00a0Swollen up by the spring inundation, the river falls down on the lowlands and before eventually throwing rocks and silts in the sea, gathers them here and there in the middle of the river. In several days, even sometimes overnight, in these shoals rather large islands are created. Soil of such an island is rich and fertile. An old man and its young grand-daughter decide to grow corn on this island. But soldiers pass by.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Sul fiume che segna il confine naturale e contrastato tra l&#8217;Abkhazia e la Georgia, isole itineranti si formano e si disfano a seconda delle stagioni e dei capricci degli elementi. Avventurosamente, un vecchio contadino e sua nipote si installano su questa terra di nessuno, per coltivarvi il necessario per sopravvivere all&#8217;inverno, ma i pericoli sono molteplici. Quando non sono i conflitti armati, e\u0300 la natura che minaccia di riacquistare i propri diritti scatenando il fiume, e l&#8217;arrivo di un militare ferito e ricercato turba il delicato equilibrio della coppia. Corn Island e\u0300 tutto questo ed altro. E\u0301 un&#8217;opera cinematografica di struggente bellezza in cui si mescolano e si uniscono temi e problematiche differenti tra loro: il costante ed infinito rapporto conflittuale tra uomo e Natura, le rivalita\u0300 etniche e geopolitiche e il tumultuoso sviluppo dell&#8217;adolescenza. \/ ENG. Swollen up by the spring inundation, the river falls down on the lowlands and before eventually throwing rocks and silts in the sea, gathers them here and there in the middle of the river. In several days, even sometimes overnight, in these shoals rather large islands are created. Soil of such an island is rich and fertile. An old man and its young grand-daughter decide to grow corn on this island. But soldiers pass by.<\/p>\n","protected":false},"author":2,"featured_media":6008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[559,376,19],"tags":[224,293,434,221,305,204,193,162,222,26,300,61,605],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 20:02:14","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6090"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=6090"}],"version-history":[{"count":5,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6090\/revisions"}],"predecessor-version":[{"id":7535,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6090\/revisions\/7535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/6008"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=6090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=6090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=6090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}