{"id":6153,"date":"2015-10-11T19:00:38","date_gmt":"2015-10-11T18:00:38","guid":{"rendered":"https:\/\/cinedetour.it\/?p=6153"},"modified":"2015-10-11T23:02:20","modified_gmt":"2015-10-11T22:02:20","slug":"11-ott-laurence-anyways-di-xavier-dolan","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2015\/10\/11\/11-ott-laurence-anyways-di-xavier-dolan\/","title":{"rendered":"11 ott LAURENCE ANYWAYS di Xavier Dolan"},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"font-size: 14pt\">Roma Cinema Detour, Via Urbana 107 Roma<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 14pt\">Domenica\u00a011 ottobre\u00a02015 ore 19.00<\/span><\/p>\n<p style=\"text-align: center\"><em><span style=\"font-size: 12pt\">Inediti d&#8217;autore al Detour: Xavier Dolan<\/span><\/em><\/p>\n<p style=\"text-align: center\">\u00a0\u00a0<\/p>\n<div>\n<div title=\"Page 1\">\n<p style=\"text-align: center\"><span style=\"font-size: 36pt\">LAURENCE ANYWAYS<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\">di XAVIER DOLAN\u00a0 (Canada\/Francia, 2012, 159&#8242;, v.o.\u00a0sott. italiano)<\/span><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/09\/eau-argent\u00e9e_detour_1.jpg\"><br \/><\/a><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/10\/Laurence_Anyways_pic_01_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-6155\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/10\/Laurence_Anyways_pic_01_3-1024x585.jpg\" alt=\"Laurence_Anyways_pic_01_3\" width=\"670\" height=\"382\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/10\/Laurence_Anyways_pic_01_3-1024x585.jpg 1024w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/10\/Laurence_Anyways_pic_01_3-300x171.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/10\/Laurence_Anyways_pic_01_3.jpg 1050w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/a>\u00a0<\/p>\n<p style=\"text-align: justify\">Un altro capolavoro inedito di Xavier Dolan in esclusiva al Cinema Detour. Montr\u00e9al, Canada, 1989. Laurence \u00e8 uno stimato professore di letteratura in un liceo e un apprezzato romanziere esordiente. Nel giorno del suo 35esimo compleanno, confessa alla propria fidanzata &#8211; la grintosa regista Fr\u00e9d\u00e9rique &#8211; che la sua vita \u00e8 una totale menzogna. Laurence ha sempre sentito di essere nato nel corpo sbagliato. Donna costretta in abiti e attributi maschili, Laurence ha finalmente preso consapevolezza del bisogno di non mentire pi\u00f9, agli altri e soprattutto a se stesso. Fred, che sta con lui da due anni, \u00e8 sconvolta. Ma la loro \u00e8 una relazione di passione, affinit\u00e0, complicit\u00e0, stima, sostegno e un affetto profondissimo. Dopo un iniziale allontanamento, la coppia si ricompone: Laurence ama Fred comunque, a prescindere dal suo desiderio di diventare donna; Fred non pu\u00f2 fare a meno di lui e desidera sostenerlo nel difficile percorso di transizione. Inizia, cos\u00ec, una nuova vita. Ma le ostilit\u00e0 e i pregiudizi che i due innamorati dovranno affrontare, nei dieci anni seguenti, metteranno pi\u00f9 volte in discussione il loro rapporto straordinario.<\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 10pt;color: #666699\"><em>The story of an impossible love between a woman named Fred (Fr\u00e9d\u00e9rique) and a transgender woman named Laurence (then living as a man) who reveals her inner desire to become her true self: a woman. Set during the late 1980s and early 1990s, the story spans a decade, chronicling the doomed love of Fred and Laurence, as well as the trials and tribulations that they face.<\/em><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 10pt\"><i><span style=\"color: #505050;font-family: Arial\"><span style=\"line-height: 21px\">Dans les ann\u00e9es 90, Laurence annonce \u00e0 Fred, sa petite amie, qu\u2019il veut devenir une femme. Envers et contre tous, et peut-\u00eatre bien eux-m\u00eames, ils affrontent les pr\u00e9jug\u00e9s de leur entourage, r\u00e9sistent \u00e0 l\u2019influence de leur famille, et bravent les phobies de la soci\u00e9t\u00e9 qu\u2019ils d\u00e9rangent. Pendant dix ans, ils tentent de survivre \u00e0 cette transition, et s\u2019embarquent dans une aventure \u00e9pique dont leur perte semble \u00eatre la ran\u00e7on.<\/span><\/span><\/i><\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 10pt\"><span style=\"color: #555555\">\u00a0<\/span><span style=\"text-align: center\">***<\/span><\/span><\/p>\n<\/div>\n<div style=\"text-align: center\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1283 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"97\" height=\"95\" \/><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: small\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Teatro | Produzione Distribuzione Editoria indipendente<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: small\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p>Tutti i film sono proiettati in lingua originale con sottotitoli in italiano. <br \/>Ingresso: tessera annuale 3\u20ac + quota partecipativa 5\u20ac<\/p>\n<p style=\"text-align: center\"><em><span style=\"font-size: small\">Art-house cinema in Downtown Rome since 1997. <br \/>All movies are screened in their original languages with italian or english subtitles<\/span><\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un altro capolavoro inedito di Xavier Dolan in esclusiva al Cinema Detour.<br \/>\nLaurence \u00e8 uno stimato professore di letteratura in un liceo e un apprezzato romanziere esordiente. Nel giorno del suo 35esimo compleanno, confessa alla propria fidanzata &#8211; la grintosa regista Fr\u00e9d\u00e9rique &#8211; che la sua vita \u00e8 una totale menzogna. Laurence ha sempre sentito di essere nato nel corpo sbagliato. Donna costretta in abiti e attributi maschili, Laurence ha finalmente preso consapevolezza del bisogno di non mentire pi\u00f9, agli altri e soprattutto a se stesso.<\/p>\n","protected":false},"author":2,"featured_media":6155,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[221,542,543],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 22:08:59","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6153"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=6153"}],"version-history":[{"count":6,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6153\/revisions"}],"predecessor-version":[{"id":6205,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6153\/revisions\/6205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/6155"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=6153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=6153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=6153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}