{"id":6170,"date":"2015-10-23T20:45:38","date_gmt":"2015-10-23T19:45:38","guid":{"rendered":"https:\/\/cinedetour.it\/?p=6170"},"modified":"2015-10-23T23:00:37","modified_gmt":"2015-10-23T22:00:37","slug":"23-ott-adrenaline","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2015\/10\/23\/23-ott-adrenaline\/","title":{"rendered":"23 ott ADRENALINE"},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"font-size: 14pt\">Roma Cinema Detour, Via Urbana 107 Roma<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 14pt\">Venerd\u00ec\u00a023\u00a0ottobre\u00a02015 ore\u00a020.45<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 14pt\">Brutti sporchi e indipendenti &#8211;\u00a0Cinema italiano indipendente di genere<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\">Ingresso per i soci 4\u20ac. Tessera sociale 3\u20ac<\/span><\/p>\n<p style=\"text-align: center\">&#8212;<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\">A causa delle tematiche disturbanti\u00a0e della crudezza di linguaggio e immagini<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\">la visione del film \u00e8 rivolta\u00a0a un pubblico adulto e consapevole<\/span><\/p>\n<p style=\"text-align: center\">\u00a0\u00a0<\/p>\n<div>\n<div title=\"Page 1\">\n<p style=\"text-align: center\"><span style=\"font-size: 36pt\">ADRENALINE<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\">film collettivo. Progetto a cura di Daniele Misischia\u00a0(Italia\u00a02015, 120&#8242;)<\/span><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/09\/eau-argent\u00e9e_detour_1.jpg\"><br \/><\/a><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/10\/adrenaline_detour.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-6171\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/10\/adrenaline_detour.jpg\" alt=\"adrenaline_detour\" width=\"497\" height=\"789\" \/><\/a><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/10\/Laurence_Anyways_pic_01_3.jpg\"><br \/><\/a>\u00a0<\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><span style=\"font-size: 10pt\">Adrenaline e\u0300 un film collettivo, completamente indipendente, ideato dal regista romano Daniele Misischia. Un progetto composto da 10 cortometraggi adrenalinici di 10 registi differenti.<\/span><\/p>\n<p><span style=\"font-size: 10pt\">L&#8217;idea era quella di realizzare un film mettendo insieme 10 autori diversi che raccontassero la loro idea di adrenalina.<\/span><\/p>\n<p><span style=\"font-size: 10pt\">Ultimamente nel cinema indipendente di genere quella del film a episodi e\u0300 una realta\u0300 gia\u0300 ben rodata, ma per la maggior parte di casi si tratta di film horror. Adrenaline e\u0300 un esperimento, ed e\u0300 la prova che questa struttura si puo\u0300 espandere a tutti i generi.<\/span><\/p>\n<p><span style=\"font-size: 10pt\">ADRENALINE (2015) 122 min. Gli episodi sono:<\/span><\/p>\n<p><span style=\"font-size: 10pt\">ENCORE \u2013 di Ivan King<\/span><br \/><span style=\"font-size: 10pt\"> AOH \u2013 di Michela Fornaci<\/span><br \/><span style=\"font-size: 10pt\"> LIGHT NIGHT \u2013 di Steven Renso<\/span><br \/><span style=\"font-size: 10pt\"> DEVIL ON THE ROAD \u2013 di Daniele Misischia<\/span><br \/><span style=\"font-size: 10pt\"> ARTURO E ADELINA ALLA CONQUISTA DELL&#8217;AMORE \u2013 di Riccardo Camilli ROUGHONIUM \u2013 di Cristiano Ciccotti<\/span><br \/><span style=\"font-size: 10pt\"> NIKTORAMA \u2013 di Luca Baggiarini<\/span><br \/><span style=\"font-size: 10pt\"> NEO SEKIGUN \u2013 di Paolo Del Fiol<\/span><br \/><span style=\"font-size: 10pt\"> IRIS \u2013 di Giacomo Gabrielli<\/span><br \/><span style=\"font-size: 10pt\"> EVIL ANGELS \u2013 di Lorenzo Ciani<\/span><\/p>\n<p><span style=\"font-size: 10pt\">tra i 10 episodi e\u0300 alternato un \u201cEPISODIO CORNICE\u201d che lega il film, diretto da Daniele Misischia.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: center\"><span style=\"font-size: 10pt\"><span style=\"color: #555555\">\u00a0<\/span><span style=\"text-align: center\">***<\/span><\/span><\/p>\n<\/div>\n<div style=\"text-align: center\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1283 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"97\" height=\"95\" \/><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: small\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Teatro | Produzione Distribuzione Editoria indipendente<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: small\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p>Tutti i film sono proiettati in lingua originale con sottotitoli in italiano. <br \/>Ingresso: tessera annuale 3\u20ac + quota partecipativa 4\u20ac<\/p>\n<p style=\"text-align: center\"><em><span style=\"font-size: small\">Art-house cinema in Downtown Rome since 1997. <br \/>All movies are screened in their original languages with italian or english subtitles<\/span><\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Adrenaline e\u0300 un film collettivo, completamente indipendente, ideato dal regista romano Daniele Misischia. Un progetto composto da 10 cortometraggi adrenalinici di 10 registi differenti. L&#8217;idea era quella di realizzare un film mettendo insieme 10 autori diversi che raccontassero la loro idea di adrenalina. Ultimamente nel cinema indipendente di genere quella del film a episodi e\u0300 una realta\u0300 gia\u0300 ben rodata, ma per la maggior parte di casi si tratta di film horror. Adrenaline e\u0300 un esperimento, ed e\u0300 la prova che questa struttura si puo\u0300 espandere a tutti i generi.<\/p>\n","protected":false},"author":2,"featured_media":6171,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376],"tags":[476,221,391,630,631,632],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 20:09:00","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6170"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=6170"}],"version-history":[{"count":2,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6170\/revisions"}],"predecessor-version":[{"id":6241,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6170\/revisions\/6241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/6171"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=6170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=6170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=6170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}