{"id":6439,"date":"2015-11-20T20:30:40","date_gmt":"2015-11-20T19:30:40","guid":{"rendered":"https:\/\/cinedetour.it\/?p=6439"},"modified":"2015-11-20T23:05:01","modified_gmt":"2015-11-20T22:05:01","slug":"19-nov-dotr-015-localeuropa-musica-valida-per-lespatrio-concorso-lungometraggi","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2015\/11\/20\/19-nov-dotr-015-localeuropa-musica-valida-per-lespatrio-concorso-lungometraggi\/","title":{"rendered":"20 nov DOTR 015 | LOCALEUROPA MUSICA VALIDA PER L&#8217;ESPATRIO di Francesco Cordio | Concorso lungometraggi"},"content":{"rendered":"<p>&nbsp;<\/p>\n<table style=\"height: 89px;\" border=\"0\" width=\"605\">\n<tbody>\n<tr>\n<td>\n<p><span style=\"font-size: 8pt;\">Con il sostegno e il contributo di<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo_regione_trasparente.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6435\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo_regione_trasparente.png\" alt=\"logo_regione_trasparente\" width=\"138\" height=\"35\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo_regione_trasparente.png 800w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo_regione_trasparente-300x76.png 300w\" sizes=\"(max-width: 138px) 100vw, 138px\" \/><br \/><\/a><span style=\"font-size: 8pt;\">Assessorato alla Cultura\u00a0e Politiche Giovanili<\/span><\/p>\n<\/td>\n<td style=\"text-align: right;\">\n<p><span style=\"font-size: 8pt;\">Con il Patrocinio di Municipio Roma I Centro<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo-comune-roma-municipio.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6636\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo-comune-roma-municipio.png\" alt=\"logo-comune-roma-municipio\" width=\"48\" height=\"58\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo-comune-roma-municipio.png 400w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo-comune-roma-municipio-247x300.png 247w\" sizes=\"(max-width: 48px) 100vw, 48px\" \/><\/a><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6626\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LOGO-DOTR-2015.png\" alt=\"LOGO-DOTR-2015\" width=\"306\" height=\"265\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LOGO-DOTR-2015.png 1000w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LOGO-DOTR-2015-300x259.png 300w\" sizes=\"(max-width: 306px) 100vw, 306px\" \/><\/p>\n<p><span style=\"font-size: 10pt;\"><span style=\"color: #993300;\"><strong>Festival internazionale di cinema indipendente di viaggio, on the road, errante e di frontiera<\/strong><\/span><br \/><span style=\"color: #993300;\"><strong>Disorientamenti\u00a0e derive psicogeografiche<br \/><\/strong><\/span><\/span><em>An international\u00a0independent cinema festival, both on the road and borderline<br \/><\/em><em>Errant images, displacements and psychogeographical drifts<\/em><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 8pt;\"><em>&#8220;Un tragitto \u00e9 sempre tra due punti, ma lo spazio intermedio ha preso tutta la sua consistenza, \u00a0<\/em><em>e gode di un\u2019autonomia come di una direzione propria&#8221; &#8211; &#8220;A path is <em>always between two points<\/em>, <em>but<\/em> the in-<em>between<\/em> has taken on <em>all<\/em> the\u00a0<em>consistency<\/em> and <em>enjoys<\/em> both an <em>autonomy<\/em> and a <em>direction<\/em> of <em>its own&#8221;\u00a0<\/em><\/em>G. Deleuze, F. Guattari, 1987<\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 18pt;\"><strong><span style=\"color: #993300;\">ven 20\u00a0nov <\/span><br \/><\/strong><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: 12pt;\"><strong>h19.30<\/strong> PRESENTAZIONE LIBRO (ingresso gratuito\u00a0per i soci)<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: 18pt;\">Un Monaco free lance<\/span><br \/><span style=\"font-size: 12pt;\">di Fabio Morotti (Exorma edizioni)<\/span><br \/><em>Letture e immagini a cura dell\u2019autore<\/em><br \/>Un giovane reporter con un passato da etnologo viaggia nel sudest asiatico in cerca di storie.\u00a0Dopo essere stato sul punto di prendere i voti nel monastero di un saggio abate, scrittore di best-seller, e aver vagabondato assieme alla chef pi\u00f9 celebre del Vietnam, il protagonista si ritrova sulle tracce di una ragazza scomparsa nella giungla cambogiana e riapparsa all\u2019improvviso vent\u2019anni dopo.\u00a0<\/p>\n<p class=\"western\" align=\"justify\">&#8212;<\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 14pt;\"><span style=\"font-size: 12pt;\"><strong>h21.30<span style=\"color: #993300;\"><br \/>Selezione ufficiale 2015 | Lungometraggi |\u00a0In concorso |\u00a0Anteprima\u00a0italiana<\/span><br \/><\/strong><\/span><em><span style=\"font-size: 12pt;\">Official Selection 2015 | Feature Films\u00a0Section | In competition | Italian\u00a0Preview<\/span><\/em><br \/><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 18pt;\"><span style=\"font-size: 24pt;\">LOCALEUROPA<\/span>\u00a0Musica valida per l&#8217;Espatrio<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><span style=\"font-size: 18pt;\"><span style=\"font-size: 14pt;\">di\u00a0Francesco Cordio | con Fabi, Silvestri, Gazz\u00e8<\/span><br \/><\/span><\/span><span style=\"font-size: 12pt;\"><em>2014, Italia. 86&#8242;. v.o. ita sub eng<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt;\">a seguire incontro con l&#8217;autore<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LocalEuropa.-Musica-valida-per-l-espatrio_detour1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-6441\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LocalEuropa.-Musica-valida-per-l-espatrio_detour1-793x1024.jpg\" alt=\"LocalEuropa.-Musica-valida-per-l-espatrio_detour1\" width=\"350\" height=\"452\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LocalEuropa.-Musica-valida-per-l-espatrio_detour1-793x1024.jpg 793w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LocalEuropa.-Musica-valida-per-l-espatrio_detour1-232x300.jpg 232w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LocalEuropa.-Musica-valida-per-l-espatrio_detour1.jpg 800w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Novemila chilometri a bordo di un pulmino rosso, in compagnia di tre artisti d\u2019eccezione: Niccol\u00f2 Fabi, Daniele Silvestri e Max Gazz\u00e8. Un viaggio a ritmo di musica attraverso le principali citt\u00e0 europee (Parigi, Londra, Bruxelles, Colonia, Roma, Barcellona, Valencia, Amsterdam, Berlino) per il primo tour oltre confine del trio romano. Un percorso artistico e, al tempo stesso, umano: l\u2019occasione per scoprire l\u2019Europa degli italiani che hanno lasciato il loro paese per andare a vivere all\u2019estero.<\/p>\n<p style=\"text-align: justify;\">Francesco Cordio, videomaker indipendente, nel 2010 ha realizzato per conto della Commissione d&#8217;inchiesta sul Servizio Sanitario Nazionale un documentario sugli Ospedali Psichiatrici Giudiziari, girando immagini e raccogliendo testimonianze inedite ed esclusive. Questo documento gli \u00e8 valso una menzione speciale al Premio Ilaria Alpi 2011. Nel 2013 conclude un lavoro pi\u00f9 approfondito sul tema degli Ospedali Psichiatrici Giudiziari dal titolo Lo Stato della Follia. Il film gli \u00e8 valso la menzione speciale al Bif&amp;st 2013, la candidatura al Globo d&#8217;oro 2013 e al SIMA 2014. Nel 2009, cura la regia del docu-film sul caso Alitalia, Tutti gi\u00f9 per aria, con Dario Fo e Ascanio Celestini, pubblicato da Editori Riuniti.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><em>In the nineties, the Roman music scene had its period of great success with a lot of musicians meeting every night on small and biggest stages. And on one of these stages begins the match between Niccolo Fabi, Daniele Silvestri and Max Gazz\u00e8 to become a relationship. Today, these three artists take their chance through Europe, leaving on a minivan that will take them to the main European clubs to play their music. In Berlin, Barcelona, through Paris, London, Amsterdam and more and more cities, the trio will play their music, dealing with international audiences. In this documentary, on one hand, Daniele, Max and Niccol\u00f2 tell us about the European adventure they had and, on the other, they interact with the public mainly made up of Italian expats.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Francesco Cordio is an independent filmmaker. In 2010 on behalf of the Board of Inquiry on the National Health Service, he directed a documentary about Italian Judicial Psychiatric Hospitals, by directing this film he earned a special mention at the 2011 Ilaria Alpi Awards and, in 2013. In 2010, he redacted and published &#8220;L&#8217;occhio di Cordio&#8221;, in collaboration with Infinito Edizioni. In 2009, he directed the docu-film &#8220;Tutti gi\u00f9 per aria&#8221;, about the Alitalia case with Dario Fo and Ascanio Celestini, that was published by Editori Riuniti.<\/em><\/p>\n<p>&#8212;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Distribuzione indipendente<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 8pt; font-family: arial, helvetica, sans-serif;\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\"><em>Art-house cinema in Downtown Rome since 1997.\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\">Cineclub Detour \u00e8 affiliato a ENAL e alla FICC (Federazione Italiana Circoli Cinema)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\"><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Sostienici<\/a> \/ <em><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Support Us<\/a><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 8pt; font-family: arial, helvetica, sans-serif;\">Seguici su \/ <em>Follow us on:<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\" \/><\/a> <a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\" \/><\/a> <a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\" \/><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detour on the Road Film Fest 2015. Festival internazionale di cinema di viaggio, on the road e di frontiera. Official Selection 2015 | In concorso. \/\/ Novemila chilometri a bordo di un pulmino rosso, in compagnia di tre artisti d\u2019eccezione: Niccol\u00f2 Fabi, Daniele Silvestri e Max Gazz\u00e8. Un viaggio a ritmo di musica attraverso le principali citt\u00e0 europee (Parigi, Londra, Bruxelles, Colonia, Roma, Barcellona, Valencia, Amsterdam, Berlino) per il primo tour oltre confine del trio romano. Un percorso artistico e, al tempo stesso, umano: l\u2019occasione per scoprire l\u2019Europa degli italiani che hanno lasciato il loro paese per andare a vivere all\u2019estero. OPEN FOR ENG VERSION<\/p>\n","protected":false},"author":2,"featured_media":6443,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[567,376,309],"tags":[243,224,313,221,295,330,312,193,310,162,222,213,26,223,667,311,882,288,600,599,644,296,292,297,668,231,674,675,219],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 19:06:58","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6439"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=6439"}],"version-history":[{"count":12,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6439\/revisions"}],"predecessor-version":[{"id":6914,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6439\/revisions\/6914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/6443"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=6439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=6439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=6439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}