{"id":6461,"date":"2015-11-22T21:00:42","date_gmt":"2015-11-22T20:00:42","guid":{"rendered":"https:\/\/cinedetour.it\/?p=6461"},"modified":"2015-11-23T11:01:23","modified_gmt":"2015-11-23T10:01:23","slug":"22-nov-dotr-015-opla-animazione-dautore-dalla-polonia","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2015\/11\/22\/22-nov-dotr-015-opla-animazione-dautore-dalla-polonia\/","title":{"rendered":"22 nov DOTR 015 | O!PLA animazione d&#8217;autore dalla Polonia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<table style=\"height: 50px;\" border=\"0\" width=\"605\">\n<tbody>\n<tr>\n<td>\n<p><span style=\"font-size: 8pt;\">Con il sostegno e il contributo di<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo_regione_trasparente.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6435\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo_regione_trasparente.png\" alt=\"logo_regione_trasparente\" width=\"138\" height=\"35\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo_regione_trasparente.png 800w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo_regione_trasparente-300x76.png 300w\" sizes=\"(max-width: 138px) 100vw, 138px\" \/><br \/><\/a><span style=\"font-size: 8pt;\">Assessorato alla Cultura\u00a0e Politiche Giovanili<\/span><\/p>\n<\/td>\n<td style=\"text-align: right;\">\n<p><span style=\"font-size: 8pt;\">Con il Patrocinio di Municipio Roma I Centro<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo-comune-roma-municipio.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6636\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo-comune-roma-municipio.png\" alt=\"logo-comune-roma-municipio\" width=\"48\" height=\"58\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo-comune-roma-municipio.png 400w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/logo-comune-roma-municipio-247x300.png 247w\" sizes=\"(max-width: 48px) 100vw, 48px\" \/><\/a><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6626\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LOGO-DOTR-2015.png\" alt=\"LOGO-DOTR-2015\" width=\"306\" height=\"265\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LOGO-DOTR-2015.png 1000w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/LOGO-DOTR-2015-300x259.png 300w\" sizes=\"(max-width: 306px) 100vw, 306px\" \/><\/p>\n<p><span style=\"font-size: 10pt;\"><span style=\"color: #993300;\"><strong>Festival internazionale di cinema indipendente di viaggio, on the road, errante e di frontiera<\/strong><\/span><br \/><span style=\"color: #993300;\"><strong>Disorientamenti\u00a0e derive psicogeografiche<br \/><\/strong><\/span><\/span><em>An international\u00a0independent cinema festival, both on the road and borderline<br \/><\/em><em>Errant images, displacements and psychogeographical drifts<br \/><\/em><span style=\"font-size: 8pt; color: #5c5c5c;\">&#8220;Un tragitto \u00e9 sempre tra due punti, ma lo spazio intermedio ha preso tutta la sua consistenza, \u00a0e gode di un\u2019autonomia come di una direzione propria&#8221;<\/span><br \/><span style=\"font-size: 8pt; color: #5c5c5c;\"><em>&#8220;A path is <em>always between two points<\/em>, <em>but<\/em> the in-<em>between<\/em> has taken on <em>all<\/em> the\u00a0<em>consistency<\/em> and <em>enjoys<\/em> both an <em>autonomy<\/em> and a <em>direction<\/em> of <em>its own&#8221;\u00a0<br \/><\/em><\/em>G. Deleuze, F. Guattari, 1987<\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 18pt;\"><strong><span style=\"color: #993300;\">dom\u00a022\u00a0nov\u00a0<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>h21.00\u00a0<span style=\"color: #993300;\"><br \/>O!PLA AcrossBorders &#8211; Festival di Animazione Polacco 2015 | Anteprima romana<br \/><\/span><\/strong><\/span><em><span style=\"font-size: 12pt;\">Focus:\u00a0O!PLA \u2013 The Festival\u00a0of Polish Animation\u00a0| Rome\u00a0Preview<\/span><\/em><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 36pt;\"><span style=\"color: #333300;\">O<\/span><span style=\"color: #0000ff;\">!<\/span><span style=\"color: #ff00ff;\">P<\/span><span style=\"color: #808000;\">L<\/span><span style=\"color: #ff9900;\">A<\/span><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 14pt;\"><strong><span style=\"color: #993300;\">Festival\u00a0di animazione\u00a0d&#8217;autore dalla Polonia<\/span><\/strong><\/span><\/p>\n<p><strong>Tutti i corti sono in versione originale con sottotitoli in italiano<\/strong><br \/><em><strong>All shorts are in original language with italian subtitles<\/strong><\/em><\/p>\n<p>\u00a0<a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/OPLA-2015_POSTER-2015.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6951\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/OPLA-2015_POSTER-2015-212x300.jpg\" alt=\"O!PLA-2015_POSTER-2015\" width=\"212\" height=\"300\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/OPLA-2015_POSTER-2015-212x300.jpg 212w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/OPLA-2015_POSTER-2015.jpg 600w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">Una selezione dei migliori corti di animazione di autori polacchi contemporanei, dall\u2019edizione 2015 del Festival\u00a0itinerante del cinema di animazione, ideato e curato da <strong>Piotr Kardas<\/strong>.<\/span><span style=\"font-size: 10pt;\">\u00a0Un assaggio del talento dei giovani artisti nel solco della grande tradizione della scuola polacca d&#8217;animazione.\u00a0Il cuore del festival \u00e8 una competizione di lavori contemporanei di animazione polacca in cui \u00e8 il pubblico a decretare i vincitori. Fin dalle sue origini, il principale obiettivo di O!PLA \u00e8 (ri)costruire relazioni tra il pubblico e gli artisti, e diffondere l\u2019arte del film d\u2019animazione. Inoltre, O!PLA, grazie a proiezioni speciali per spettatori di tutte le et\u00e0, seminari, incontri con artisti e workshop di animazione, ha una dimensione educativa fondamentale. E attraverso il progetto parallelo O!PLA ACROSS THE BORDERS il festival diventa itinerante anche all\u2019estero.<\/span><\/p>\n<hr \/>\n<p><em>O!PLA \u2013 THE FESTIVAL OF POLISH ANIMATION is the fully independent project created and powered by Animation Across Borders (Piotr Kardas). The bases is a competition of contemporary Polish animations in which only audience decide about the winners. From the very beginning, the main aim of O!PLA is (re)build relations between audience and artists, and reaching out with the art of animation especially to smaller centers in Poland. Moreover, O!PLA \u2013 thanks to special screenings for viewers of all ages, lectures, meetings with artists and animation workshops \u2013 has a significant educational dimension. And thanks to O!PLA ACROSS THE BORDERS project can promote the art of Polish animation also abroad.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt;\">PROGRAMMA \/ PROGRAMME (21.00)<\/span><\/strong><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Water Lilies<\/strong> (Nenufary) di Marcin Surma, Polonia, 2013, 4\u2019<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_NENUFARY-Eng.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6937\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_NENUFARY-Eng.jpg\" alt=\"o!pla_detour_NENUFARY-(Eng\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>The Tenement Building<\/strong> (Kamienica) di Agnieszka Burszewska, Polonia, 2013, 13&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_KAMIENICA-tenement.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6934\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_KAMIENICA-tenement.jpg\" alt=\"o!pla_detour_KAMIENICA-tenement\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>But She\u2019s Nice&#8230;<\/strong> di Tomasz Pilarski, Polonia, 2014, 6\u2019<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_BUT-SHE\u2019S-NICE.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6929\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_BUT-SHE\u2019S-NICE.jpg\" alt=\"o!pla_detour_BUT-SHE\u2019S-NICE\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Doggydent<\/strong> (Piesydent) di Magdalena Pilecka, Polonia, 2014, 2&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6940\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_PIESYDENT-Eng.jpg\" alt=\"o!pla_detour_PIESYDENT-(Eng\" width=\"300\" height=\"169\" \/><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>The Drift<\/strong> (Dryf) di Marcin Oz\u0307\u00f3g, Polonia, 2014, 5&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour__DRYF.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6926\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour__DRYF.jpg\" alt=\"o!pla_detour__DRYF\" width=\"299\" height=\"166\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>331 Days<\/strong> (331 Dni) di Piotr Mazur, Polonia, 2014, 7&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_331days.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6927\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_331days.jpg\" alt=\"o!pla_detour_331days\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>De Herinacio. On the Hedgehog<\/strong> di Ala Nunu Leszyn\u0301ska, Polonia, 2014, 2&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_JE\u03a9-Eng.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6933\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_JE\u03a9-Eng.jpg\" alt=\"o!pla_detour_JE\u03a9-(Eng\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Hippos<\/strong> (Hipopotamy) di Piotr Duma\u0142a, Polonia, 2014, 13&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_HIPOPOTAMY-Eng.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6932\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_HIPOPOTAMY-Eng.jpg\" alt=\"o!pla_detour_HIPOPOTAMY-(Eng\" width=\"300\" height=\"162\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Over My Dead Body!<\/strong> (Po Moim Trupie!) di Agata Mianowska Polonia, 2015, 4&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_PO-MOIM-TRUPIE-Eng.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6941\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_PO-MOIM-TRUPIE-Eng.jpg\" alt=\"o!pla_detour_PO-MOIM-TRUPIE!-(Eng\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Pate (Pasztet)<\/strong> di \u0141ukasz Jedynasty, Zuzanna Staszewska, Polonia, 2014, 5&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_PASZTET-Eng.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6939\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_PASZTET-Eng.jpg\" alt=\"o!pla_detour_PASZTET-(Eng\" width=\"300\" height=\"168\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>My Identification<\/strong> (Moja Identyfikacja) di Natalia Krawczuk, Polonia, 2013, 3&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_MOJA-IDENTYFIKACJA-Eng.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6936\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_MOJA-IDENTYFIKACJA-Eng.jpg\" alt=\"o!pla_detour_MOJA-IDENTYFIKACJA-(Eng\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Supernova<\/strong> (Supernowa) di Pawe\u0142 Czarnecki, Polonia, 2014, 7&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_SUPERNOWA-Eng.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6943\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_SUPERNOWA-Eng.jpg\" alt=\"o!pla_detour_SUPERNOWA-(Eng\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>The Rivers (Rzeki)<\/strong> di Daria Wiktoria Kopiec, Polonia, 2014, 3&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_RZEKI-Eng.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6942\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_RZEKI-Eng.jpg\" alt=\"o!pla_detour_RZEKI-(Eng\" width=\"300\" height=\"191\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_RZEKI-Eng.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_RZEKI-Eng-80x50.jpg 80w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>A Documentary Film (Dokument)<\/strong> di Marcin Podolec, Polonia, 2015, 6&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_DOKUMENT.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6931\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_DOKUMENT.jpg\" alt=\"o!pla_detour_DOKUMENT\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Bevare of Smoking, or the Deadly Effects of Smoking,<\/strong> Ver.2 (Zgubne Skutki Palenia Ver.2) di Maciej Pestka, Polonia,<\/span><\/p>\n<p><span style=\"font-size: 12pt;\">2013, 5&#8242;<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_ZGUBNE-PALENIA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6944\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_ZGUBNE-PALENIA.jpg\" alt=\"o!pla_detour_ZGUBNE-PALENIA\" width=\"300\" height=\"158\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Loop<\/strong> di Micha\u0142 Socha, Polonia, 2014, 3\u2019<\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_LOOP_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6935\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_LOOP_1.jpg\" alt=\"o!pla_detour_LOOP_1\" width=\"300\" height=\"169\" \/><\/a><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Hedgehog (Jez\u0307)<\/strong> di Anna Nowicka, Polonia, 2014, 2&#8242;<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_DE-HERINACIO.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6930\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/11\/opla_detour_DE-HERINACIO.jpg\" alt=\"o!pla_detour_DE-HERINACIO\" width=\"300\" height=\"150\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">&#8212;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Distribuzione indipendente<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 8pt; font-family: arial, helvetica, sans-serif;\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\"><em>Art-house cinema in Downtown Rome since 1997.\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\">Cineclub Detour \u00e8 affiliato a ENAL e alla FICC (Federazione Italiana Circoli Cinema)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 8pt;\"><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Sostienici<\/a> \/ <em><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Support Us<\/a><\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 8pt; font-family: arial, helvetica, sans-serif;\">Seguici su \/ <em>Follow us on:<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\" \/><\/a> <a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\" \/><\/a> <a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\" \/><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detour on the Road Film Fest 2015. Festival internazionale di cinema di viaggio, on the road e di frontiera. Focus: animazione d&#8217;autore dalla Polonia. \/ Una selezione dei migliori corti di animazione di autori polacchi contemporanei, dall\u2019edizione 2015 del Festival itinerante del cinema di animazione, ideato e curato da Piotr Kardas. Un assaggio del talento dei giovani artisti nel solco della grande tradizione della scuola polacca d&#8217;animazione. OPEN FOR ENG VERSION<\/p>\n","protected":false},"author":2,"featured_media":6951,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[567,376,309],"tags":[676,243,224,313,221,295,330,312,193,310,162,222,213,26,223,667,311,678,882,288,600,599,644,296,677,292,297,668,231,674,675,219],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 19:24:52","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6461"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=6461"}],"version-history":[{"count":21,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6461\/revisions"}],"predecessor-version":[{"id":6981,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/6461\/revisions\/6981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/6951"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=6461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=6461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=6461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}