{"id":7043,"date":"2015-12-15T19:30:08","date_gmt":"2015-12-15T18:30:08","guid":{"rendered":"https:\/\/cinedetour.it\/?p=7043"},"modified":"2015-12-16T09:35:03","modified_gmt":"2015-12-16T08:35:03","slug":"15-dic-mdf-medici-senza-frontiere-presenta-dust-la-seconda-vita-proiezione-e-incontro","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2015\/12\/15\/15-dic-mdf-medici-senza-frontiere-presenta-dust-la-seconda-vita-proiezione-e-incontro\/","title":{"rendered":"15 dic MEDICI SENZA FRONTIERE presenta \u201cDUST &#8211; la seconda vita\u201d proiezione e incontro"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/12\/logo-medici_senza_frontiere.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7046\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/12\/logo-medici_senza_frontiere.png\" alt=\"logo-medici_senza_frontiere\" width=\"248\" height=\"78\" \/><\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Medici Senza Frontiere\u00a0presenta<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 12pt; color: #993300;\">gioved\u00ec 10 dic h19.30<\/span><\/strong><\/p>\n<p><span style=\"font-size: 24pt;\">DUST &#8211; la seconda vita<\/span><\/p>\n<p>(Anteprima assoluta, Italia 2015) di\u00a0Stefano Tallia e Stefano Rogliatti<\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/12\/dust_medici_senza_frontiere_detour.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-7049\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/12\/dust_medici_senza_frontiere_detour-1024x768.jpg\" alt=\"dust_medici_senza_frontiere_detour\" width=\"474\" height=\"355\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/12\/dust_medici_senza_frontiere_detour-1024x768.jpg 1024w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/12\/dust_medici_senza_frontiere_detour-300x225.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/12\/dust_medici_senza_frontiere_detour.jpg 1280w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/a><\/p>\n<p>Il documentario, \u00e8 completamente autoprodotto e tutti i professionisti che vi hanno lavorato lo hanno fatto gratuitamente. Oltre ai due\u00a0autori\u00a0del documentario, Stefano Tallia e Stefano Rogliatti,\u00a0interverr\u00e0 per MSF, Gabriella Bianchi, responsabile comunicazione nel Kurdistan iracheno, che ha accompagnato i due reporter\u00a0nel loro viaggio.<\/p>\n<p>Nel Kurdistan iracheno vive oggi un milione di profughi. Donne e uomini in fuga dall\u2019avanzata dell\u2019Isis in Siria e Iraq, persone che hanno perso in un attimo tutto ci\u00f2 che avevano: casa, lavoro, affetti e che in molti casi hanno anche assistito all\u2019uccisione di parenti e amici. La guerra in corso in Medio Oriente non fa distinzioni di religione: a scappare sono musulmani sunniti e sciiti, cristiani, yazidi.<\/p>\n<p>Due giornalisti italiani sono andati a raccogliere le loro testimonianze nel campo profughi di Domiz e nei territori che si trovano a nord di Dohuk dove non esistono strutture attrezzate e i rifugiati vivono praticamente senza acqua, senza energia elettrica e con pochi servizi igienici. Nel quartiere cristiano di Erbil le storie si assomigliano, si intrecciano e i container, intorno alle chiese, prendono il posto delle tende.<\/p>\n<p>Con le parole dei rifugiati, nel documentario sono raccolte anche le testimonianze degli operatori di Medici Senza Frontiere che si occupano della loro salute attraverso le cliniche mobili e le strutture fisse all\u2019interno dei campi che si trovano vicino a Dohuk. Alcuni tra i medici e gli infermieri di Msf sono anch\u2019essi profughi, orgogliosi di poter aiutare il proprio popolo come l\u2019infermiere Jalal, fuggito un anno fa dall\u2019ospedale di Sinjar sotto alle bombe dell\u2019Isis.<\/p>\n<p>Il documentario vuole contribuire alla riflessione sul tema dei profughi. In Kurdistan lo \u00e8 un abitante su sei e quello proposto da \u201cDust\u201d \u00e8 anche il racconto di come un paese pur povero di strutture abbia saputo aprire le proprie porte alle persone in fuga. Sofferenza e dignit\u00e0 raccontate\u00a0tra gli altri dal\u00a0dottor Azad Haleem, vice direttore dell\u2019ospedale infantile di Dohuk, che con l\u2019arrivo dei profughi ha visto crescere del 40 per cento il numero dei ricoveri.<\/p>\n<p>E non si tratta di una situazione temporanea perch\u00e9 i rifugiati hanno poche\u00a0speranze di tornare nelle proprie terre, e con la fuga \u00e8 iniziata a tutti gli effetti la loro\u00a0seconda vita. Tra la polvere dei campi.<\/p>\n<p>Voce narrante Marco Alotto;\u00a0doppiaggio maschile Claudio Secco; doppiaggio femminile Elisa Galvagno; traduzioni\/sottotitoli Annalisa Palisca<\/p>\n<p>https:\/\/www.facebook.com\/DustLasecondavita\/info\/?tab=page_info<\/p>\n<p><p><iframe loading=\"lazy\" title=\"Dust, la seconda vita - Trailer\" width=\"870\" height=\"489\" src=\"https:\/\/www.youtube.com\/embed\/hjjUOZ-8YMM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<\/p>\n<p>&#8212;<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1283\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"130\" height=\"127\" \/><br \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><em>your friendly neighbourhood arthouse cinema | screening in downtown rome since 1997<\/em><\/span><\/p>\n<p><span style=\"font-size: 8pt;\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<br \/><\/a>Cineclub Detour \u00e8 affiliato a ENAL e alla FICC (Federazione Italiana Circoli Cinema)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 8pt;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Sostienici<\/a> \/ <em><a href=\"https:\/\/cinedetour.it\/crowdfunding-sostienici\/\" target=\"_blank\">Support Us<br \/><\/a><\/em><\/span>Seguici su \/ <em>Follow us on:<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\" \/><\/a> <a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\" \/><\/a> <a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\" \/><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel Kurdistan iracheno vive oggi un milione di profughi. Donne e uomini in fuga dall\u2019avanzata dell\u2019Isis in Siria e Iraq, persone che hanno perso in un attimo tutto ci\u00f2 che avevano: casa, lavoro, affetti e che in molti casi hanno anche assistito all\u2019uccisione di parenti e amici. La guerra in corso in Medio Oriente non fa distinzioni di religione: a scappare sono musulmani sunniti e sciiti, cristiani, yazidi.<\/p>\n<p>Due giornalisti italiani sono andati a raccogliere le loro testimonianze nel campo profughi di Domiz e nei territori che si trovano a nord di Dohuk dove non esistono strutture attrezzate e i rifugiati vivono praticamente senza acqua, senza energia elettrica e con pochi servizi igienici. Nel quartiere cristiano di Erbil le storie si assomigliano, si intrecciano e i container, intorno alle chiese, prendono il posto delle tende.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376],"tags":[243,224,221,295,193,162,222,213,26,223,686,553],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 20:52:55","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7043"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=7043"}],"version-history":[{"count":8,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7043\/revisions"}],"predecessor-version":[{"id":7148,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7043\/revisions\/7148"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=7043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=7043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=7043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}