{"id":7500,"date":"2016-03-08T19:00:09","date_gmt":"2016-03-08T18:00:09","guid":{"rendered":"https:\/\/cinedetour.it\/?p=7500"},"modified":"2016-03-02T15:36:13","modified_gmt":"2016-03-02T14:36:13","slug":"fotografia-corsi-2016-presentazione-25-febbraio-a-ingresso-libero","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2016\/03\/08\/fotografia-corsi-2016-presentazione-25-febbraio-a-ingresso-libero\/","title":{"rendered":"FOTOGRAFIA Corsi 2016"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><span style=\"font-size: 18pt;\">Cineclub Detour | Corsi 2016<\/span><\/strong><\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: 36pt; color: #c2721d;\"><b><span style=\"color: #800000;\">FOTOGRAFIA<\/span>\u00a0<\/b><\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: 18pt;\"><b>16 lezioni + mostra di fine corso<\/b><\/span><\/p>\n<div style=\"text-align: center;\">\n<div dir=\"ltr\">\n<p><span style=\"font-size: 14pt; line-height: 25px;\"><b>la fotografia come mezzo di espressione-comunicazione-<wbr \/>socializzazione<\/b><\/span><\/p>\n<p><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/fotografia-2016_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-7502\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/fotografia-2016_.jpg\" alt=\"fotografia-2016_!\" width=\"600\" height=\"424\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/fotografia-2016_.jpg 800w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/fotografia-2016_-300x211.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2015\/09\/fotografia_nuova_foto.jpg\"><br \/><\/a>\u00a0<\/p>\n<p class=\"p1\"><span style=\"font-size: 12pt;\"><b>SEGRETERIA:<\/b><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 12pt;\">gioved\u00ec 11 e gioved\u00ec 18 febbraio (ore 19.00-20.00)<\/span><\/p>\n<p class=\"p1\">&#8212;<\/p>\n<p class=\"p1\"><span style=\"font-size: 12pt;\"><b>PRESENTAZIONE:<\/b><\/span><\/p>\n<p class=\"p1\"><span style=\"font-size: 12pt;\">25 febbraio ore 19-20 (ingresso libero)<\/span><\/p>\n<p class=\"p1\">&#8212;<\/p>\n<p><strong><span style=\"font-size: 12pt;\">INIZIO CORSI:<\/span><\/strong>\u00a0<\/p>\n<p><span style=\"font-size: 12pt;\">livello BASE gioved\u00ec 10\u00a0marzo ore 19.00-20.30<\/span><\/p>\n<p><span style=\"font-size: 12pt;\">II livello marted\u00ec 8\u00a0marzo 19.00-20.30<\/span><\/p>\n<p><span style=\"font-size: 12pt;\">III livello mercoled\u00ec 9\u00a0marzo ore 19.00-20.30<\/span><\/p>\n<p class=\"p1\">&#8212;<\/p>\n<p><span style=\"font-size: medium;\">Informazioni: cell.3384634278 &#8211; email\u00a0<a href=\"mailto:patriziacopponi@libero.it%20\" target=\"_blank\">patriziacopponi@libero.it\u00a0<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 10pt;\">Patrizia Copponi \u00e8 fotoreporter dal 1980.<br \/>Ha collaborato con i maggiori Settimanali, Quotidiani e Mensili italiani ed esteri. <\/span><br \/><span style=\"font-size: 10pt;\">Attualmente si occupa dell\u2019Organizzazione di attivit\u00e0 culturali sulla comunicazione visiva e dell\u2019insegnamento della Fotografia.\u00a0<\/span>\u00a0<\/p>\n<\/div>\n<\/div>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Cineclub Detour \u00e8 affiliato all&#8217;ENAL e alla FICC \/ Cineclub Detour is affiliated to ENAL\u00a0and FICC<br \/> <\/span><span style=\"font-size: small;\">seguici su \/Follow us on:<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/cineclub.detour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32\" title=\"facebook_logo_s\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/facebook_logo_s1.jpg\" alt=\"\" width=\"31\" height=\"31\" \/><\/a>\u00a0<a href=\"https:\/\/twitter.com\/#!\/CineclubDetour\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33\" title=\"Twitter2\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/Twitter21.jpg\" alt=\"\" width=\"30\" height=\"30\" \/><\/a>\u00a0<a href=\"http:\/\/www.youtube.com\/user\/CineclubDetour?feature=watch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" title=\"youtube_logo\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/01\/youtube_logo.jpg\" alt=\"\" width=\"31\" height=\"30\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Detour Via Urbana 107 Roma<br \/> <span style=\"font-size: small;\"><a style=\"font-style: normal;\" href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>\u00a0<span style=\"color: #333333; font-size: small; font-style: normal;\">&#8211;<\/span><span style=\"color: #333333; font-size: small; font-style: normal;\">\u00a0<\/span><a style=\"font-style: normal;\" href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FOTOGRAFIA 16 lezioni + Mostra di fine corso.<br \/>\nLa fotografia come mezzo di espressione-comunicazione-socializzazione.<br \/>\nTre livelli: Base, Reportage, Avanzato.<br \/>\nPresentazione Corsi: 25 febbraio 2016. Inizio corsi I, II e III livello (riservato agli allievi del II): marzo 2016.<br \/>\nInfo cell.3384634278 &#8211; email patriziacopponi@libero.it<br \/>\nPatrizia Copponi \u00e8 fotoreporter dal 1980. Ha collaborato con i maggiori Settimanali, Quotidiani e Mensili italiani ed esteri. Attualmente si occupa dell\u2019Organizzazione di attivit\u00e0 culturali sulla comunicazione visiva e dell\u2019insegnamento della Fotografia. <\/p>\n","protected":false},"author":2,"featured_media":7502,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376,38],"tags":[875,708,879,712,711,710,709,393,67],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 22:48:45","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7500"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=7500"}],"version-history":[{"count":3,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7500\/revisions"}],"predecessor-version":[{"id":7622,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7500\/revisions\/7622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/7502"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=7500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=7500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=7500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}