{"id":7797,"date":"2016-03-18T21:00:45","date_gmt":"2016-03-18T20:00:45","guid":{"rendered":"https:\/\/cinedetour.it\/?p=7797"},"modified":"2016-12-01T12:22:41","modified_gmt":"2016-12-01T11:22:41","slug":"the-discourse-game-di-helmy-nouh-festival-cinema-arabo-palestinese","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2016\/03\/18\/the-discourse-game-di-helmy-nouh-festival-cinema-arabo-palestinese\/","title":{"rendered":"THE DISCOURSE GAME di Helmy Nouh &#8211; Cinema Arabo Palestinese"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">Roma Cinema Detour, Via Urbana 107 Roma<\/span><br \/><span style=\"font-size: 12pt;\">Venerd\u00ec 18\u00a0Marzo\u00a02016 ore\u00a021.00<\/span><\/p>\n<p style=\"text-align: center;\">DETOUR ON THE ROAD 2016 PREVIEW\u00a0<\/p>\n<p style=\"text-align: center;\">Presenta<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt;\">***<\/span><\/p>\n<p style=\"text-align: center;\">Festival Cinema Arabo e Palestinese. 18&gt;20 marzo 2016<\/p>\n<p style=\"text-align: center;\">Il miglior cinema documentario arabo e palestinese. <br \/>In collaborazione con Al Ard Doc Film Festival, ULAIA Arte Sud Onlus, Edizioni Q.<\/p>\n<p style=\"text-align: center;\">***\u00a0<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt;\"><span style=\"font-size: 36pt;\"><strong>THE DISCOURSE GAME<\/strong><\/span><\/span><\/p>\n<div>\n<div title=\"Page 1\">\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">di Helmy Nouh\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">(Egitto, arabo, sottotitoli italiano, 60\u2032)<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">Menzione speciale della Giuria Al Ard Doc Film Festival 2015<br \/>Incontro Skype con il regista Helmy Nouh<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/03\/Helmy_nouh.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-7798\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/03\/Helmy_nouh.jpg\" alt=\"Helmy_nouh\" width=\"339\" height=\"226\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/03\/Helmy_nouh.jpg 960w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/03\/Helmy_nouh-300x200.jpg 300w\" sizes=\"(max-width: 339px) 100vw, 339px\" \/><\/a><\/p>\n<p>Osservando la realt\u00e0 che ci circonda, talvolta, sentiamo che ogni dettaglio \u00e8 in relazione con una rete complessa di potere che ci controlla. Questa rete viene definita in inglese \u201cdiscourse\u201d: un gioco difficile da descrivere e da comprendere, ma che si riflette sui nostri comportamenti e la nostra comunicazione verbale.\u00a0<\/p>\n<p>Il film cerca di catturare il complesso meccanismo e le relazioni che riguardano la societ\u00e0 attuale egiziana, misurando due diversi modi di intendere questa rete: il \u201cdiscourse\u201d sociale e quello militare.<\/p>\n<p style=\"text-align: justify;\">Al Ard Doc Film Festival\u00a0\u00e8 una panoramica di livello internazionale sul miglior cinema della Palestina e del mondo arabo. Grazie a Fawzi Ismail, Simonetta Lambertini e Cristina Nistic\u00f2 AL ARD approda per la prima volta al Detour arricchito da eventi inediti.<\/p>\n<p>Una parte del ricavato della rassegna andr\u00e0 a Ulaia ArteSud Onlus per sostenere il progetto \u201cMa che bella storia\u201d che troverete sul sito dell\u2019Associazione <a href=\"http:\/\/www.ulaia.org\/\" target=\"_blank\" rel=\"nofollow nofollow\">http:\/\/www.ulaia.org\/<\/a><\/p>\n<p>L\u2019Associazione Culturale Amicizia Sardegna Palestina presieduta da Fawzi Ismail \u00e8 la promotrice di Al Ard Doc Film Festival presieduto da Monica Maurer e con la direzione artistica di Giuseppe Pusceddu.<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\"><span style=\"color: #555555;\">\u00a0<\/span><span style=\"text-align: center;\">***<\/span><\/span><\/p>\n<\/div>\n<div style=\"text-align: center;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1283 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"97\" height=\"95\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Teatro | Produzione Distribuzione Editoria indipendente<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p>Tutti i film sono proiettati in lingua originale con sottotitoli in italiano. <br \/>Ingresso: tessera annuale 3\u20ac + quota partecipativa 5\u20ac<br \/>E&#8217; consigliata la <a href=\"https:\/\/cinedetour.it\/2016\/01\/13\/finalmente-il-pre-tesseramento-online\/\">pre-iscrizione <\/a>sul nostro sito.<\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: small;\">Art-house cinema in Downtown Rome since 1997. <br \/>All movies are screened in their original languages with italian or english subtitles<\/span><\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Osservando la realt\u00e0 che ci circonda, talvolta, sentiamo che ogni dettaglio \u00e8 in relazione con una rete complessa di potere che ci controlla. Questa rete viene definita in inglese \u201cdiscourse\u201d: un gioco difficile da descrivere e da comprendere, ma che si riflette sui nostri comportamenti e la nostra comunicazione verbale. Il film cerca di catturare il complesso meccanismo e le relazioni che riguardano la societ\u00e0 attuale egiziana, misurando due diversi modi di intendere questa rete: il \u201cdiscourse\u201d sociale e quello militare. Incontro Skype con il regista.<\/p>\n","protected":false},"author":2,"featured_media":7798,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376],"tags":[734,733,221,739,543,548,731,738,878],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-10 01:43:29","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7797"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=7797"}],"version-history":[{"count":4,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7797\/revisions"}],"predecessor-version":[{"id":7854,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7797\/revisions\/7854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/7798"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=7797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=7797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=7797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}