{"id":7943,"date":"2016-04-10T20:30:01","date_gmt":"2016-04-10T19:30:01","guid":{"rendered":"https:\/\/cinedetour.it\/?p=7943"},"modified":"2016-12-01T12:22:38","modified_gmt":"2016-12-01T11:22:38","slug":"unlearning-la-vita-comincia-alla-fine-della-tua-zona-comfort","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2016\/04\/10\/unlearning-la-vita-comincia-alla-fine-della-tua-zona-comfort\/","title":{"rendered":"UNLEARNING &#8211; La vita comincia  alla fine della tua zona comfort"},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"font-size: 12pt\">Roma Cinema Detour, Via Urbana 107 Roma<\/span><br \/><span style=\"font-size: 12pt\">Domenica\u00a010\u00a0Marzo\u00a02016 ore 20.30<br \/><\/span><\/p>\n<p style=\"text-align: center\">DETOUR ON THE ROAD 2016 PREVIEW\u00a0<\/p>\n<p style=\"text-align: center\">Presenta<\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 8pt\">***<\/span><\/p>\n<p style=\"text-align: center\"><em><span style=\"font-size: 12pt\">dopo le proiezioni\u00a0SOLD OUT\u00a0in tutta Italia<br \/>arriva al Cinema Detour il curioso caso \u00a0di un\u00a0documentario sulla fiducia, <br \/>su un&#8217;Italia di uomini, donne e bambini che, all&#8217;omologazione, <br \/>hanno risposto facendo della propria esistenza<br \/>un inno alla diversita\u0300 per aprirsi al cambiamento<\/span><\/em><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 8pt\">***\u00a0<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\">La vita comincia alla fine della tua zona comfort<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 24pt\"><span style=\"font-size: 36pt\">UNLEARNING<\/span><\/span><\/p>\n<div>\n<div title=\"Page 1\">\n<p style=\"text-align: center\"><strong><span style=\"font-size: 12pt\">una guida per le famiglie che cambiano il mondo<\/span><\/strong><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: 12pt\">di Lucio Basadonne e Anna Pollio (Italia\u00a02014, 89&#8242;)<\/span><\/p>\n<p style=\"text-align: center\"><strong><span style=\"font-size: 10pt\">A seguire incontro Skype con gli autori<\/span><\/strong><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/unlearning-detour1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-7577\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/unlearning-detour1-721x1024.jpg\" alt=\"unlearning-detour1\" width=\"499\" height=\"708\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/unlearning-detour1-721x1024.jpg 721w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/unlearning-detour1-211x300.jpg 211w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/02\/unlearning-detour1.jpg 1000w\" sizes=\"(max-width: 499px) 100vw, 499px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Otto ore di lavoro al giorno a testa, bambina a scuola fino alle quattro del pomeriggio, babysitter. Quando arriva il momento piu\u0300 importante della giornata, la cena, in cui finalmente si puo\u0300 stare insieme ci ritroviamo sfiniti a parlare di mutuo e bollette, organizzando un&#8217;altra giornata di sopravvivenza. Questo e\u0300 il modello comune che finora abbiamo vissuto, che ci confina in uno stile di vita che a nostra volta stiamo trasmettendo ai nostri figli come assunto di verita\u0300. Ma se lasciassimo la zona comfort della nostra esistenza, \u201cdisimparando\u201d la religione del comfort per condividere i tempi, gli spazi, le logiche e i meccanismi di relazione con chi ha un concetto diverso di famiglia? Come vedremo la nostra vecchia vita al nostro ritorno? E, soprattutto, la vorremmo ancora? \ufffc<\/p>\n<p>Unlearning e\u0300 il viaggio di Lucio, Anna e Gaia attraverso ecovillaggi, comunita\u0300, famiglie itineranti per conoscere chi ha avuto il coraggio di cambiare. Un documentario familydriven che racconta il punto di vista non certo oggettivo di un&#8217; ansiosa insegnante in aspettativa, un regista televisivo stanco di format ripetitivi e una bambina di 5 anni in balia degli eventi.<\/p>\n<div class=\"page\" title=\"Page 4\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Unlearning e\u0300 un invito gentile alla disobbedienza, una proposta per tutte le famiglie stanche della propria vita ripetitiva che da sempre si chiedono se un&#8217;altra vita e\u0300 possibile.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: center\"><span style=\"font-size: 10pt\"><span style=\"color: #555555\">\u00a0<\/span><span style=\"text-align: center\">***<\/span><\/span><\/p>\n<\/div>\n<div style=\"text-align: center\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1283 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"97\" height=\"95\" \/><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: small\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Video d&#8217;arte | Teatro | Produzione Distribuzione Editoria indipendente<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-size: small\">Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p>Tutti i film sono proiettati in lingua originale con sottotitoli in italiano. <br \/>Ingresso: tessera annuale 3\u20ac + quota partecipativa 5\u20ac<br \/>E&#8217; consigliata la <a href=\"https:\/\/cinedetour.it\/2016\/01\/13\/finalmente-il-pre-tesseramento-online\/\">pre-iscrizione <\/a>sul nostro sito.<\/p>\n<p style=\"text-align: center\"><em><span style=\"font-size: small\">Art-house cinema in Downtown Rome since 1997. <br \/>All movies are screened in their original languages with italian or english subtitles<\/span><\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Otto ore di lavoro al giorno a testa, bambina a scuola fino alle quattro del pomeriggio, babysitter. Quando arriva il momento piu\u0300 importante della giornata, la cena, in cui finalmente si puo\u0300 stare insieme ci ritroviamo sfiniti a parlare di mutuo e bollette, organizzando un&#8217;altra giornata di sopravvivenza. Questo e\u0300 il modello comune che finora abbiamo vissuto, che ci confina in uno stile di vita che a nostra volta stiamo trasmettendo ai nostri figli come assunto di verita\u0300. Ma se lasciassimo la zona comfort della nostra esistenza, \u201cdisimparando\u201d la religione del comfort per condividere i tempi, gli spazi, le logiche e i meccanismi di relazione con chi ha un concetto diverso di famiglia? Come vedremo la nostra vecchia vita al nostro ritorno? E, soprattutto, la vorremmo ancora? \ufffc<br \/>\nUnlearning e\u0300 un invito gentile alla disobbedienza, una proposta per tutte le famiglie stanche della propria vita ripetitiva che da sempre si chiedono se un&#8217;altra vita e\u0300 possibile.<\/p>\n","protected":false},"author":2,"featured_media":7944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376],"tags":[221,543,729,731],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 19:08:00","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7943"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=7943"}],"version-history":[{"count":2,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7943\/revisions"}],"predecessor-version":[{"id":7982,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/7943\/revisions\/7982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/7944"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=7943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=7943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=7943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}