{"id":8655,"date":"2016-05-01T10:00:34","date_gmt":"2016-05-01T09:00:34","guid":{"rendered":"https:\/\/cinedetour.it\/?p=8655"},"modified":"2017-03-27T14:41:21","modified_gmt":"2017-03-27T13:41:21","slug":"masterclass-internazionale-con-artur-aristakisyan-e-la-partecipazione-di-enrico-ghezzi-solo-i-morti-possono-girare-film-e-scattare-foto-2","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2016\/05\/01\/masterclass-internazionale-con-artur-aristakisyan-e-la-partecipazione-di-enrico-ghezzi-solo-i-morti-possono-girare-film-e-scattare-foto-2\/","title":{"rendered":"MASTERCLASS internazionale con Artur Aristakisyan e la partecipazione di Enrico Ghezzi: &#8220;SOLO I MORTI POSSONO GIRARE FILM e SCATTARE FOTO&#8221;"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #333333;\"><span style=\"font-size: 10pt;\">Noeltan<br \/>\n<\/span><span style=\"font-size: 8pt;\">in collaborazione con<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #333333;\">Fuori Orario &#8211; Rai Tre<\/span><br \/>\n<span style=\"color: #333333;\">Moskow School of New Cinema<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt; color: #333333;\"><strong><span style=\"font-size: 12pt;\">Cinema Detour&nbsp;&#8211;&nbsp;On the Road Film Festival 2016<\/span><\/strong><br \/>\ncon il sostegno di&nbsp;<\/span><br \/>\n<span style=\"color: #333333;\">Regione Lazio &#8211; Assesorato alla Cultura e Politiche Giovanili<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">roma, cinema detour<\/span><br \/>\n<span style=\"font-size: 12pt;\">29 settembre &#8211;&nbsp;2 ottobre 2016<\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><strong><span style=\"font-size: 14pt; color: #356a87;\">SOLO I MORTI POSSONO GIRARE FILM E SCATTARE FOTO<\/span><\/strong><br \/>\n<span style=\"font-size: 12pt;\">Masterclass internazionale con <strong>Artur Aristakisyan<\/strong> <br \/>\ne con la partecipazione di <strong>Enrico Ghezzi<\/strong><\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/cinedetour.it\/en\/2016\/05\/01\/masterclass-internazionale-con-artur-aristakisyan-e-la-partecipazione-di-enrico-ghezzi-solo-i-morti-possono-girare-film-e-scattare-foto-2\/\">english version &#8211; &nbsp;versione inglese<\/a><\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"color: #800000;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/05\/A3_masterclass.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8676\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/05\/A3_masterclass.jpg\" alt=\"A3_masterclass\" width=\"396\" height=\"562\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/05\/A3_masterclass.jpg 1149w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/05\/A3_masterclass-211x300.jpg 211w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/05\/A3_masterclass-722x1024.jpg 722w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/a><br \/>\n<\/span><\/p>\n<div style=\"text-align: center;\">\n<div dir=\"ltr\">\n<p style=\"text-align: left;\"><span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/05\/ARISTAKISYAN_Regulation-Entry.pdf\"><strong><span style=\"text-decoration: underline;\">Scarica&nbsp;il bando e la scheda di iscrizione<\/span><\/strong><\/a><\/span><\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: left;\">Una masterclass esclusiva a Roma con un autore geniale.<\/p>\n<p style=\"text-align: left;\"><span class=\"text_exposed_show\">I Noeltan Film Lab ospitano, nell&#8217;ambito del Detour on the Road Film Festival 2016, il geniale regista russo Artur Aristakisyan (autore dei film cult Palms e Un Posto sulla Terra distribuiti in dvd in Italia da Raro Video e docente alla prestigiosa Moskow School of New Cinema assieme a Leos Carax, Carlos Reygadas, Sharunas Bartas, Peter Greenaway, Jurij Nors\u030ctejn e Andrey Zvyagintsev) <br \/>\nDopo l\u2019esperienza in Basilicata del 2008, l\u2019appuntamento questa volta \u00e8 nel centro di Roma, nei locali dello storico cinema indipendente Detour. Sar\u00e0 una masterclass \u201csui margini e sul centro\u201d: si studier\u00e0 nella sala del Detour e si esplorer\u00e0 la finisterrae della stazione Termini di Roma che diverr\u00e0 uno dei luoghi d&#8217;osservazione per i partecipanti.&nbsp;<br \/>\n<\/span><\/p>\n<p style=\"text-align: left;\">Un esclusivo metodo d\u2019autore su come guardare, capire e fare cinema d&#8217;arte.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\">Artur Aristakisyan presenta il suo esclusivo metodo d\u2019autore su come guardare, capire e fare cinema d&#8217;arte. Questa masterclass non e\u0300 pensata solo per i futuri registi ma per fotografi, critici d&#8217;arte e artisti tout court. Aristakisyan si concentra sulle relazioni invisibili nascoste negli oggetti visivi, egli mostra modi di trasformazione metaforica di immagini afferenti le diverse arti visive. Il maestro utilizza un ampio contesto visivo, dalla pittura classica alla fotografia moderna fino alle immagini del reale.<\/p>\n<p style=\"text-align: justify;\">Aristakisyan da\u0300 ai suoi allievi un materiale visivo elaborato e stratificato che potrebbe sembrare a prima vista non combinabile e stilisticamente incoerente: solo allora si puo\u0300 essere testimoni del miracolo della nascita del senso e di una visione creativa unica!<br \/>\n Artur ama scioccare il suo pubblico. Ad esempio, egli insiste sul fatto che i migliori film possono essere visti da una cosiddetta \u201csala cinematografica per i morti\u201d perche\u0301 la morte dei sentimenti familiari di ogni giorno e\u0300 la sola in grado di dare una una perfetta ottica per filmare.<\/p>\n<p style=\"text-align: justify;\">Come riprendere gli oggetti dalla nostra realta\u0300 per vedere in loro una realta\u0300 piu\u0300 profonda?<br \/>\n Perche\u0301 e\u0300 cosi\u0300 importante sapere che tutti vogliono difendersi da una \u201creale visione\u201d?<br \/>\n Come capire che non si puo\u0300 filmare se non si e\u0300 abbastanza morti?<br \/>\n Alcune delle masterclass di Artur si tengono proprio in cimiteri reali. Alcuni dei suoi metodi sono davvero insoliti e anche scioccanti. Le masterclass di Aristakisyan sono una sorta di \u201cpericolosa\u201d avventura nel territorio delle arti visive. Molti studenti durante i corsi di Aristakisyan compiono un incredibile passo avanti nel cuore della loro professione e trovano finalmente la propria unica visione.<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 8pt;\"><a href=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/08\/ARTUR-trip-lab17_web.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-8647 alignleft\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/08\/ARTUR-trip-lab17_web-150x150.jpg\" alt=\"ARTUR trip lab17_web\" width=\"150\" height=\"150\"><\/a><\/span><span style=\"font-size: 8pt;\">Bio &#8211; Artur Aristakisyan (nella foto, cortesemente \u00a9 Salvatore Laurenzana\/Noeltan Film Studio).&nbsp;Nato a Kishinev in Moldavia ha studiato al VGIK la scuola di cinema di Mosca (una delle piu\u0300 autorevoli al mondo). Ha lavorato duramente per completare la sua opera prima Palms, racconto di dieci storie d\u2019amore tra i mendicanti di Kishinev. Palms (Ladoni &#8211; 1994) &#8211; risultato di quattro anni di vita vissuta tra vagabondi, mendicanti, tossicodipendenti e disabili. Tra i numerosi riconoscimenti ha vinto il Nika, attribuitogli dall\u2019Accademia di Arte Cinematografica Russa per il miglior documentario del 1994. A Place on Earth (Un Posto sulla Terra &#8211; 2001), e\u0300 un\u2019esplorazione lirica della relazione tra la sofferenza umana e l\u2019assenza di limiti. Oggi Aristakisyan insegna alla Moskow School of New Cinema assieme ad alcuni tra i principali autori del cinema d\u2019arte contemporaneo come Leos Carax, Carlos Reygadas, Sharunas Bartas, Peter Greenaway, Jurij Nors\u030ctejn e Andrey Zvyagintsev.\u2028<\/span>&nbsp;<\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: left;\">Informazioni e iscrizioni: studio@noeltan.it<\/p>\n<p style=\"text-align: left;\"><span style=\"color: #993300;\"><a style=\"color: #993300;\" href=\"http:\/\/www.noeltan.it\">www.noeltan.it<\/a><\/span><br \/>\n<span style=\"color: #993300;\"><a style=\"color: #993300;\" href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a><\/span><br \/>\n<span style=\"color: #993300;\"><a style=\"color: #993300;\" href=\"www.fuoriorario.rai.it\">www.fuoriorario.rai.it<\/a><\/span><br \/>\n<span style=\"color: #993300;\"><a style=\"color: #993300;\" href=\"http:\/\/www.newcinemaschool.com\">www.newcinemaschool.com<\/a><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una masterclass esclusiva a Roma con un autore geniale.<br \/>\nI Noeltan Film Lab ospitano, nell&#8217;ambito del Detour on the Road Film Festival 2016, il geniale regista russo Artur Aristakisyan (autore dei film cult Palms e Un Posto sulla Terra distribuiti in dvd in Italia da Raro Video e docente alla prestigiosa Moskow School of New Cinema assieme a Leos Carax, Carlos Reygadas, Sharunas Bartas, Peter Greenaway, Jurij Nors\u030ctejn e Andrey Zvyagintsev)<br \/>\nDopo l\u2019esperienza in Basilicata del 2008, l\u2019appuntamento questa volta \u00e8 nel centro di Roma, nei locali dello storico cinema indipendente Detour. Sar\u00e0 una masterclass \u201csui margini e sul centro\u201d: si studier\u00e0 nella sala del Detour e si esplorer\u00e0 la finisterrae della stazione Termini di Roma che diverr\u00e0 uno dei luoghi d&#8217;osservazione per i partecipanti. Un esclusivo metodo d\u2019autore su come guardare, capire e fare cinema d&#8217;arte.<\/p>\n","protected":false},"author":2,"featured_media":8647,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[863,945,376],"tags":[847,874,852,875,846,851,673,855,854,853,879,850,856,411,67],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-13 19:24:54","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/8655"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=8655"}],"version-history":[{"count":14,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/8655\/revisions"}],"predecessor-version":[{"id":10737,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/8655\/revisions\/10737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/8647"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=8655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=8655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=8655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}