{"id":9469,"date":"2017-01-15T18:00:15","date_gmt":"2017-01-15T17:00:15","guid":{"rendered":"https:\/\/cinedetour.it\/?p=9469"},"modified":"2017-01-15T18:00:02","modified_gmt":"2017-01-15T17:00:02","slug":"among-the-believers-i-documentari-di-internazionale","status":"publish","type":"post","link":"https:\/\/cinedetour.it\/en\/2017\/01\/15\/among-the-believers-i-documentari-di-internazionale\/","title":{"rendered":"AMONG THE BELIEVERS [I documentari di INTERNAZIONALE]"},"content":{"rendered":"<table style=\"height: 95px;\" width=\"958\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9482 alignleft\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/11\/CineAgenzia_logo_2015-300x255.jpg\" alt=\"cineagenzia_logo_2015\" width=\"62\" height=\"53\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/11\/CineAgenzia_logo_2015-300x255.jpg 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/11\/CineAgenzia_logo_2015-1024x870.jpg 1024w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/11\/CineAgenzia_logo_2015.jpg 1525w\" sizes=\"(max-width: 62px) 100vw, 62px\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9483 aligncenter\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/11\/Internazionale_testata-300x66.png\" alt=\"internazionale_testata\" width=\"241\" height=\"53\" srcset=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/11\/Internazionale_testata-300x66.png 300w, https:\/\/cinedetour.it\/wp-content\/uploads\/2016\/11\/Internazionale_testata.png 800w\" sizes=\"(max-width: 241px) 100vw, 241px\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1283 alignright\" src=\"https:\/\/cinedetour.it\/wp-content\/uploads\/2013\/11\/LOGOTONDO_ombra-e1383573010633.png\" alt=\"LOGOTONDO_ombra\" width=\"54\" height=\"53\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: left;\"><span style=\"font-size: 12pt; font-family: 'trebuchet ms', geneva;\">Roma Cinema Detour, Via Urbana 107 Roma<br \/>\nDomenica&nbsp;15 gennaio 2017 ore 18.00<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva;\">in collaborazione con <a href=\"http:\/\/www.internazionale.it\/festival\/mondovisioni\">Internazionale<\/a> e <a href=\"http:\/\/www.cineagenzia.it\/mondovisionitour2015-2016\/\">CineAgenzia<\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #993300;\"><strong><span style=\"font-size: 14pt; font-family: 'trebuchet ms', geneva;\">MONDOVISIONI.&nbsp;<span style=\"font-size: 12pt;\">I Documentari di&nbsp;Internazionale a Roma&nbsp;<\/span><\/span>&nbsp;<\/strong><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 36pt; font-family: 'trebuchet ms', geneva;\">AMONG THE BELIEVERS&nbsp;<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: 'trebuchet ms', geneva; font-size: 12pt;\">di <strong>Mohammed Ali Naqvi<\/strong> e <strong>Hemal Trivedi<\/strong><\/span><br \/>\n <span style=\"font-family: 'trebuchet ms', geneva;\"><em>Stati Uniti\/Pakistan\/India 2015, 85<\/em>\u2019.&nbsp;<br \/>\n in Inglese e Urdu, sottotitoli in italiano<br \/>\n <\/span><a href=\"https:\/\/cinedetour.it\/prenotazioni\/\"><strong>&gt; <span style=\"color: #993300;\">Prenotazioni online<\/span><\/strong><\/a><\/p>\n<p><iframe loading=\"lazy\" title=\"Among the Believers Trailer\" width=\"870\" height=\"489\" src=\"https:\/\/www.youtube.com\/embed\/MSklZY_VCIM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'trebuchet ms', geneva; font-size: 10pt;\">Il carismatico leader religioso Abdul Aziz Ghazi, sostenitore del gruppo Stato islamico e dei taliban, incita aljihad e sogna d\u2019imporre in Pakistan una rigida versione della sharia. Il film segue Ghazi nella sua personale lotta per la creazione di un\u2019utopia islamica, insieme ai destini opposti di due adolescenti che frequentano le sue scuole coraniche.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'trebuchet ms', geneva;\">Mondovisioni \u00e8 un programma di straordinari documentari d&#8217;autore su attualit\u00e0, diritti umani e informazione curata ogni anno da <a href=\"https:\/\/www.facebook.com\/CineAgenzia\/\">CineAgenzia<\/a> in collaborazione con <a href=\"https:\/\/www.facebook.com\/Internazionale\/\">Internazionale<\/a>.&nbsp;I documentari sono stati presentati in anteprima italiana durante il festival di Internazionale a Ferrara, e poi proposti in un tour che durante l\u2019anno tocca molte citt\u00e0, dal nord al sud del paese.&nbsp;Dopo le anteprime romane al Palaexp\u00f2, Mondovisioni approda al Cinema Detour.<\/span>&nbsp;<\/p>\n<p><span style=\"font-family: 'trebuchet ms', geneva;\">&gt;<strong><a href=\"https:\/\/facebook.com\/events\/1229714713716510\/\"> Evento Facebook<\/a><\/strong><\/span><\/p>\n<div>\n<div title=\"Page 1\">\n<div title=\"Page 1\">\n<div title=\"Page 1\">\n<p style=\"text-align: left;\">___<\/p>\n<\/div>\n<div style=\"text-align: center;\">\n<p style=\"text-align: left;\"><span style=\"font-size: 18pt; font-family: 'trebuchet ms', geneva;\"><span style=\"color: #993300;\">CINEMA DETOUR<\/span><br \/>\n <\/span><span style=\"font-size: 8pt; font-family: 'trebuchet ms', geneva;\">Cinema | Corsi e laboratori | Esposizioni | attivit\u00e0 per bambini | Cinebar | Musica | Produzione Distribuzione indipendente<br \/>\n Associazione Culturale Detour &#8211; Via Urbana 107 Roma <a href=\"http:\/\/www.cinedetour.it\">www.cinedetour.it<\/a>&#8211; <a href=\"cinedetour@tiscali.it\">cinedetour@tiscali.it<\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 8pt; font-family: 'trebuchet ms', geneva;\">Tutti i film sono proiettati in lingua originale con sottotitoli in italiano. <\/span><br \/>\n <span style=\"font-size: 8pt; font-family: 'trebuchet ms', geneva;\">Ingresso: tessera annuale 3\u20ac + quota partecipativa 5\u20ac<br \/>\n <em>Art-house cinema in Downtown Rome since 1997.&nbsp;<br \/>\n <\/em><em>All movies are screened in their original languages with italian or english subtitles<\/em><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il carismatico leader religioso Abdul Aziz Ghazi, sostenitore del gruppo Stato islamico e dei taliban, incita aljihad e sogna d\u2019imporre in Pakistan una rigida versione della sharia. Il film segue Ghazi nella sua personale lotta per la creazione di un\u2019utopia islamica, insieme ai destini opposti di due adolescenti che frequentano le sue scuole coraniche. Mondovisioni \u00e8 un programma di straordinari documentari d&#8217;autore su attualit\u00e0, diritti umani e informazione curata ogni anno da CineAgenzia in collaborazione con la rivista Internazionale. Dopo il successo di pubblico al Palaexp\u00f2, Mondovisioni approda al Detour. <\/p>\n","protected":false},"author":2,"featured_media":9477,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[376,873],"tags":[642,221,542,543,15,635,643,638,623,640,639,641,636,637],"translation":{"provider":"WPGlobus","version":"2.8.11","language":"en","enabled_languages":["it","en"],"languages":{"it":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"publishpress_future_action":{"enabled":false,"date":"2026-05-10 00:40:32","action":"category-remove","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/9469"}],"collection":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/comments?post=9469"}],"version-history":[{"count":17,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/9469\/revisions"}],"predecessor-version":[{"id":9979,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/posts\/9469\/revisions\/9979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media\/9477"}],"wp:attachment":[{"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/media?parent=9469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/categories?post=9469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinedetour.it\/en\/wp-json\/wp\/v2\/tags?post=9469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}